{"id":108542,"date":"2023-07-21T18:00:37","date_gmt":"2023-07-21T21:00:37","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/21\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai"},"modified":"2023-07-21T18:02:51","modified_gmt":"2023-07-21T21:02:51","slug":"ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/21\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai","title":{"rendered":"Z\u00e9 Neto e Cristino e Gustavo Mioto est\u00e3o no segundo final de semana da Festa Julina de Jundia\u00ed"},"content":{"rendered":"<p>Um final de semana sertanejo. Gustavo Mioto e Z\u00e9 Neto e Cristiano v\u00e3o emocionar e empolgar o p\u00fablico numa das maiores e mais tradicionais festas de S\u00e3o Paulo.<\/p>\n<p>De acordo com as informa\u00e7\u00f5es, a Festa Julina de Jundia\u00ed tem uma mega estrutura com arena, pista premium, camarote, camarote vip e privates.<\/p>\n<p>Ainda de acordo com as informa\u00e7\u00f5es, \u00e9 importante lembrar que a compra de ingressos deve ser feita apenas para os interessados em assistir \u00e0s atra\u00e7\u00f5es musicais e que todos os setores possuem acessibilidade para pessoas com mobilidade reduzida.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-108543 size-large\" src=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/07\/Design-sem-nome-2021-10-21T160300-1024x512.jpg\" alt=\"Z\u00e9 Neto e Cristino e Gustavo Mioto est\u00e3o no segundo final de semana da Festa Julina de Jundia\u00ed\" width=\"1024\" height=\"512\" srcset=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/07\/Design-sem-nome-2021-10-21T160300-1024x512.jpg?v=1689973214 1024w, https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/07\/Design-sem-nome-2021-10-21T160300-300x150.jpg?v=1689973214 300w, https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/07\/Design-sem-nome-2021-10-21T160300-768x384.jpg?v=1689973214 768w, https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/07\/Design-sem-nome-2021-10-21T160300.jpg?v=1689973214 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><em>Confira os valores, mapa do evento e efetue as compras pelo <a href=\"http:\/\/festajulinajundiai.com.br\/\">site oficial<\/a>.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Sendo assim, o evento que j\u00e1 teve a escolha da miss e do mister caipirinha, apresenta tamb\u00e9m o Festival de Quadrilhas, cord\u00e9is, festival de bandeirinhas, reunindo alunos das escolas municipais de Jundia\u00ed e parcerias com mais de 30 entidades assistenciais do munic\u00edpio.<\/p>\n<p>Por fim, mais de 30 mil pessoas passaram pelo evento no primeiro final de semana da festa, com muita m\u00fasica boa, comidas t\u00edpicas com culin\u00e1ria caipira, divers\u00e3o e atra\u00e7\u00f5es para toda a fam\u00edlia.<\/p>\n<h2>Atra\u00e7\u00f5es<\/h2>\n<p>Enfim, al\u00e9m das atra\u00e7\u00f5es musicais, o evento conta tamb\u00e9m com uma apresenta\u00e7\u00e3o variadas para atrair as familias. \u00c9 a <strong>Julina das Crian\u00e7as<\/strong>. Neste final de semana ser\u00e1 escolhido o <strong>Miss Pet caipirinha<\/strong>. S\u00e3o mais de 30 inscritos e os votos s\u00e3o computados pela internet. Mais de 30 mil pessoas j\u00e1 se manifestaram para escolher o vencedor.<\/p>\n<h3><strong>Confira a programa\u00e7\u00e3o completa<\/strong><\/h3>\n<p>22 de julho: Gustavo Mioto, Carla Melo, Gabriel<br \/>\n23 de julho: Z\u00e9 Neto e Cristiano, Luiz Miguel &amp; Daniel<\/p>\n<p>29 de julho: Henrique e Juliano<br \/>\n30 de julho: Piseiro com Tarc\u00edsio do Acordeon, Jo\u00e3o Gomes e Iguinho e Lulinha<\/p>\n<p><strong>Leia mais<\/strong><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2023\/07\/17\/capital-inicial-e-sorriso-maroto-esquentam-a-galera-no-primeiro-final-de-semana-da-festa-julina\">Capital Inicial e Sorriso Maroto esquentam a galera no primeiro final de semana da Festa Julina<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um final de semana sertanejo. Gustavo Mioto e Z\u00e9 Neto e Cristiano v\u00e3o emocionar e empolgar o p\u00fablico numa das maiores e mais tradicionais festas de S\u00e3o Paulo. De acordo com as informa\u00e7\u00f5es, a Festa Julina de Jundia\u00ed tem uma mega estrutura com arena, pista premium, camarote, camarote vip e privates. Ainda de acordo com &hellip;<\/p>\n","protected":false},"author":12,"featured_media":108544,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6,57751,66299,66300],"class_list":["post-108542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem","tag-jundiai","tag-festa-julina","tag-festejos-julinos","tag-miss-caipirinha"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Z\u00e9 Neto e Cristino e Gustavo Mioto est\u00e3o no segundo final de semana da Festa Julina de Jundia\u00ed - Litoral SP<\/title>\n<meta name=\"description\" content=\"Gustavo Mioto e Z\u00e9 Neto e Cristiano v\u00e3o emocionar e empolgar o p\u00fablico numa das maiores e mais tradicionais festas de S\u00e3o Paulo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/21\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Z\u00e9 Neto e Cristino e Gustavo Mioto est\u00e3o no segundo final de semana da Festa Julina de Jundia\u00ed - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"Gustavo Mioto e Z\u00e9 Neto e Cristiano v\u00e3o emocionar e empolgar o p\u00fablico numa das maiores e mais tradicionais festas de S\u00e3o Paulo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/21\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-21T21:00:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-21T21:02:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/07\/WhatsApp-Image-2023-07-21-at-15.16.07.jpeg?v=1689973151\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gustavo Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/21\\\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/21\\\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai\"},\"author\":{\"name\":\"Gustavo Silva\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\"},\"headline\":\"Z\u00e9 Neto e Cristino e Gustavo Mioto est\u00e3o no segundo final de semana da Festa Julina de Jundia\u00ed\",\"datePublished\":\"2023-07-21T21:00:37+00:00\",\"dateModified\":\"2023-07-21T21:02:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/21\\\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai\"},\"wordCount\":330,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/21\\\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/WhatsApp-Image-2023-07-21-at-15.16.07.jpeg?v=1689973151\",\"keywords\":[\"#jundiai\",\"FESTA JULINA\",\"festejos julinos\",\"miss caipirinha\"],\"articleSection\":[\"sem\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/21\\\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/21\\\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/21\\\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai\",\"name\":\"Z\u00e9 Neto e Cristino e Gustavo Mioto est\u00e3o no segundo final de semana da Festa Julina de Jundia\u00ed - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/21\\\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/21\\\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/WhatsApp-Image-2023-07-21-at-15.16.07.jpeg?v=1689973151\",\"datePublished\":\"2023-07-21T21:00:37+00:00\",\"dateModified\":\"2023-07-21T21:02:51+00:00\",\"description\":\"Gustavo Mioto e Z\u00e9 Neto e Cristiano v\u00e3o emocionar e empolgar o p\u00fablico numa das maiores e mais tradicionais festas de S\u00e3o Paulo.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/21\\\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/21\\\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/WhatsApp-Image-2023-07-21-at-15.16.07.jpeg?v=1689973151\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/WhatsApp-Image-2023-07-21-at-15.16.07.jpeg?v=1689973151\",\"width\":1600,\"height\":1066,\"caption\":\"Z\u00e9 Neto e Cristino e Gustavo Mioto est\u00e3o no segundo final de semana da Festa Julina de Jundia\u00ed\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\",\"name\":\"Gustavo Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"caption\":\"Gustavo Silva\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/gustavosilva\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Z\u00e9 Neto e Cristino e Gustavo Mioto est\u00e3o no segundo final de semana da Festa Julina de Jundia\u00ed - Litoral SP","description":"Gustavo Mioto e Z\u00e9 Neto e Cristiano v\u00e3o emocionar e empolgar o p\u00fablico numa das maiores e mais tradicionais festas de S\u00e3o Paulo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/21\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai","og_locale":"pt_BR","og_type":"article","og_title":"Z\u00e9 Neto e Cristino e Gustavo Mioto est\u00e3o no segundo final de semana da Festa Julina de Jundia\u00ed - Litoral SP","og_description":"Gustavo Mioto e Z\u00e9 Neto e Cristiano v\u00e3o emocionar e empolgar o p\u00fablico numa das maiores e mais tradicionais festas de S\u00e3o Paulo.","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/21\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai","og_site_name":"Litoral SP","article_published_time":"2023-07-21T21:00:37+00:00","article_modified_time":"2023-07-21T21:02:51+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/07\/WhatsApp-Image-2023-07-21-at-15.16.07.jpeg?v=1689973151","type":"image\/jpeg"}],"author":"Gustavo Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gustavo Silva","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/21\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/21\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai"},"author":{"name":"Gustavo Silva","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e"},"headline":"Z\u00e9 Neto e Cristino e Gustavo Mioto est\u00e3o no segundo final de semana da Festa Julina de Jundia\u00ed","datePublished":"2023-07-21T21:00:37+00:00","dateModified":"2023-07-21T21:02:51+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/21\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai"},"wordCount":330,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/21\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/07\/WhatsApp-Image-2023-07-21-at-15.16.07.jpeg?v=1689973151","keywords":["#jundiai","FESTA JULINA","festejos julinos","miss caipirinha"],"articleSection":["sem"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/21\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/21\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/21\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai","name":"Z\u00e9 Neto e Cristino e Gustavo Mioto est\u00e3o no segundo final de semana da Festa Julina de Jundia\u00ed - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/21\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/21\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/07\/WhatsApp-Image-2023-07-21-at-15.16.07.jpeg?v=1689973151","datePublished":"2023-07-21T21:00:37+00:00","dateModified":"2023-07-21T21:02:51+00:00","description":"Gustavo Mioto e Z\u00e9 Neto e Cristiano v\u00e3o emocionar e empolgar o p\u00fablico numa das maiores e mais tradicionais festas de S\u00e3o Paulo.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/21\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/21\/ze-neto-e-cristino-e-gustavo-mioto-estao-no-segundo-final-de-semana-da-festa-julina-de-jundiai#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/07\/WhatsApp-Image-2023-07-21-at-15.16.07.jpeg?v=1689973151","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/07\/WhatsApp-Image-2023-07-21-at-15.16.07.jpeg?v=1689973151","width":1600,"height":1066,"caption":"Z\u00e9 Neto e Cristino e Gustavo Mioto est\u00e3o no segundo final de semana da Festa Julina de Jundia\u00ed"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e","name":"Gustavo Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","caption":"Gustavo Silva"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/gustavosilva"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/108542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=108542"}],"version-history":[{"count":2,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/108542\/revisions"}],"predecessor-version":[{"id":108546,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/108542\/revisions\/108546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/108544"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=108542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=108542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=108542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}