{"id":108796,"date":"2023-07-28T18:15:39","date_gmt":"2023-07-28T21:15:39","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/28\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher"},"modified":"2023-07-28T18:17:34","modified_gmt":"2023-07-28T21:17:34","slug":"filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/28\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher","title":{"rendered":"Filha do cantor\u00a0Xanddy e Carla Perez assume relacionamento com mulher"},"content":{"rendered":"<p>A Filha do cantor Xanddy e da dan\u00e7arina Carla Perez assumiu um relacionamento com uma mulher nesta quinta-feira (27).<\/p>\n<p>De acordo com as informa\u00e7\u00f5es, Camilly Vict\u00f3ria, 21 anos, compartilhou um v\u00eddeo em uma rede social em que mostra imagens se beijando e abra\u00e7ando &#8220;Daze&#8221;.<\/p>\n<p>Ainda de acordo com as informa\u00e7\u00f5es, a confirma\u00e7\u00e3o vem ap\u00f3s meses de especula\u00e7\u00e3o, j\u00e1 que o colunista Leo Dias j\u00e1 havia informado que seus pais estavam em crise devido a not\u00edcia.<\/p>\n<p>https:\/\/www.tiktok.com\/@prettygirlslovemillz\/video\/7260646684982660398<\/p>\n<p>Sendo assim, Nos coment\u00e1rios, seguidores desejaram felicita\u00e7\u00f5es. &#8220;Felicidades Camilly \ud83e\udd70 Deus aben\u00e7oe voc\u00eas \u2764\ufe0f&#8221;, escreveu uma pessoa.<\/p>\n<div class=\"article-paragraph\">\n<p>&#8220;Que sejam felizes \ud83e\udd70&#8221;, disse outra. &#8220;Felicidades Camilly, a torcida torce pela sua felicidade \u2764\ufe0f&#8221;, comentou outra.<\/p>\n<p><strong>Leia mais<\/strong><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2023\/07\/28\/dia-mundial-da-hepatite-oms-quer-melhorar-enfrentamento-da-doenca\">Dia Mundial da Hepatite: OMS quer melhorar enfrentamento da doen\u00e7a<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Filha do cantor Xanddy e da dan\u00e7arina Carla Perez assumiu um relacionamento com uma mulher nesta quinta-feira (27). De acordo com as informa\u00e7\u00f5es, Camilly Vict\u00f3ria, 21 anos, compartilhou um v\u00eddeo em uma rede social em que mostra imagens se beijando e abra\u00e7ando &#8220;Daze&#8221;. Ainda de acordo com as informa\u00e7\u00f5es, a confirma\u00e7\u00e3o vem ap\u00f3s meses &hellip;<\/p>\n","protected":false},"author":12,"featured_media":108797,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60954,170],"tags":[66438,66439,32979,59303],"class_list":["post-108796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades","category-entretenimento","tag-camilly-victoria","tag-carla-perez","tag-leo-dias","tag-xanddy"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Filha do cantor\u00a0Xanddy e Carla Perez assume relacionamento com mulher - Litoral SP<\/title>\n<meta name=\"description\" content=\"A Filha do cantor Xanddy e da dan\u00e7arina Carla Perez assumiu um relacionamento com uma mulher nesta quinta-feira (27).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/28\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Filha do cantor\u00a0Xanddy e Carla Perez assume relacionamento com mulher - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"A Filha do cantor Xanddy e da dan\u00e7arina Carla Perez assumiu um relacionamento com uma mulher nesta quinta-feira (27).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/28\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-28T21:15:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-28T21:17:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/07\/4788825_a8c7ece2961c557.jpg?v=1690578886\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gustavo Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/28\\\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/28\\\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher\"},\"author\":{\"name\":\"Gustavo Silva\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\"},\"headline\":\"Filha do cantor\u00a0Xanddy e Carla Perez assume relacionamento com mulher\",\"datePublished\":\"2023-07-28T21:15:39+00:00\",\"dateModified\":\"2023-07-28T21:17:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/28\\\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher\"},\"wordCount\":147,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/28\\\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/4788825_a8c7ece2961c557.jpg?v=1690578886\",\"keywords\":[\"camilly victoria\",\"carla perez\",\"LEO DIAS\",\"Xanddy\"],\"articleSection\":[\"Celebridades\",\"Entretenimento\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/28\\\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/28\\\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/28\\\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher\",\"name\":\"Filha do cantor\u00a0Xanddy e Carla Perez assume relacionamento com mulher - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/28\\\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/28\\\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/4788825_a8c7ece2961c557.jpg?v=1690578886\",\"datePublished\":\"2023-07-28T21:15:39+00:00\",\"dateModified\":\"2023-07-28T21:17:34+00:00\",\"description\":\"A Filha do cantor Xanddy e da dan\u00e7arina Carla Perez assumiu um relacionamento com uma mulher nesta quinta-feira (27).\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/28\\\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/07\\\/28\\\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/4788825_a8c7ece2961c557.jpg?v=1690578886\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/07\\\/4788825_a8c7ece2961c557.jpg?v=1690578886\",\"width\":700,\"height\":466,\"caption\":\"Filha do cantor\u00a0Xanddy e Carla Perez assume relacionamento com mulher\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\",\"name\":\"Gustavo Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"caption\":\"Gustavo Silva\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/gustavosilva\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Filha do cantor\u00a0Xanddy e Carla Perez assume relacionamento com mulher - Litoral SP","description":"A Filha do cantor Xanddy e da dan\u00e7arina Carla Perez assumiu um relacionamento com uma mulher nesta quinta-feira (27).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/28\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher","og_locale":"pt_BR","og_type":"article","og_title":"Filha do cantor\u00a0Xanddy e Carla Perez assume relacionamento com mulher - Litoral SP","og_description":"A Filha do cantor Xanddy e da dan\u00e7arina Carla Perez assumiu um relacionamento com uma mulher nesta quinta-feira (27).","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/28\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher","og_site_name":"Litoral SP","article_published_time":"2023-07-28T21:15:39+00:00","article_modified_time":"2023-07-28T21:17:34+00:00","og_image":[{"width":700,"height":466,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/07\/4788825_a8c7ece2961c557.jpg?v=1690578886","type":"image\/jpeg"}],"author":"Gustavo Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gustavo Silva","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/28\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/28\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher"},"author":{"name":"Gustavo Silva","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e"},"headline":"Filha do cantor\u00a0Xanddy e Carla Perez assume relacionamento com mulher","datePublished":"2023-07-28T21:15:39+00:00","dateModified":"2023-07-28T21:17:34+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/28\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher"},"wordCount":147,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/28\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/07\/4788825_a8c7ece2961c557.jpg?v=1690578886","keywords":["camilly victoria","carla perez","LEO DIAS","Xanddy"],"articleSection":["Celebridades","Entretenimento"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/28\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/28\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/28\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher","name":"Filha do cantor\u00a0Xanddy e Carla Perez assume relacionamento com mulher - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/28\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/28\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/07\/4788825_a8c7ece2961c557.jpg?v=1690578886","datePublished":"2023-07-28T21:15:39+00:00","dateModified":"2023-07-28T21:17:34+00:00","description":"A Filha do cantor Xanddy e da dan\u00e7arina Carla Perez assumiu um relacionamento com uma mulher nesta quinta-feira (27).","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/28\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/28\/filha-do-cantor-xanddy-e-carla-perez-assume-relacionamento-com-mulher#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/07\/4788825_a8c7ece2961c557.jpg?v=1690578886","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/07\/4788825_a8c7ece2961c557.jpg?v=1690578886","width":700,"height":466,"caption":"Filha do cantor\u00a0Xanddy e Carla Perez assume relacionamento com mulher"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e","name":"Gustavo Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","caption":"Gustavo Silva"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/gustavosilva"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/108796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=108796"}],"version-history":[{"count":0,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/108796\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/108797"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=108796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=108796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=108796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}