{"id":109024,"date":"2023-08-06T07:00:49","date_gmt":"2023-08-06T10:00:49","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/?p=109024"},"modified":"2023-08-02T20:12:09","modified_gmt":"2023-08-02T23:12:09","slug":"jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/08\/06\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais","title":{"rendered":"Jovem de 21 anos fatura 50 mil em 4 meses vendendo conte\u00fado nas redes sociais"},"content":{"rendered":"<p>July Garcia, uma jovem de 21 anos, natural de Sorocaba\/SP, tem sido um nome bastante procurado na Privacy, onde compartilha conte\u00fados exclusivos e personalizados.<\/p>\n<p>Em entrevista \u00e0 Privacy, July contou que encontrou uma oportunidade \u00fanica na plataforma ao transformar sua paix\u00e3o por exibicionismo e produ\u00e7\u00e3o de conte\u00fado em uma carreira promissora. A ariana e solteira, tem conquistado novos patamares e alcan\u00e7ado uma liberdade profissional e financeira que sempre almejou e que jamais imaginou conseguir em t\u00e3o pouco tempo:<\/p>\n<p>\u201cConfesso que nunca imaginei que um trabalho t\u00e3o flex\u00edvel e gostoso fosse me permitir conquistar tudo o que estou conquistando e tudo o que ainda est\u00e1 por vir. A Privacy para mim, representa liberdade, liberdade financeira, profissional e pessoal, hoje eu finalmente me sinto livre para viver o que h\u00e1 de melhor dessa vida.\u201d<\/p>\n<p>A hist\u00f3ria de July na venda de conte\u00fado adulto da Privacy come\u00e7ou em novembro, quando viu na plataforma o destaque e a relev\u00e2ncia no mercado brasileiro. Motivada pela oportunidade de faturar com sua paix\u00e3o, n\u00e3o hesitou em mergulhar nesse mundo incr\u00edvel. Hoje, ela est\u00e1 prestes a realizar um de seus sonhos:\u00a0<em>\u201c<\/em><em>Com a Privacy, eu consegui atingir minha t\u00e3o sonhada independ\u00eancia financeira e liberdade profissional e mesmo sabendo que ainda \u00e9 s\u00f3 o come\u00e7o, pois estou bem perto de conquistar meu t\u00e3o sonhado apartamento, me surpreendo em como tudo aconteceu muito r\u00e1pido, isso tudo gra\u00e7as a Privacy.\u201d<\/em><\/p>\n<p>Embora sua jornada tenha sido marcada por conquistas, July tamb\u00e9m enfrentou desafios e lidar com o tabu e preconceitos em rela\u00e7\u00e3o \u00e0 sua profiss\u00e3o foram algumas das barreiras que superou com coragem e determina\u00e7\u00e3o.<\/p>\n<p>Nas horas vagas, July gosta de se divertir com jogos de v\u00eddeo game, assistir filmes, s\u00e9ries e animes, al\u00e9m de desfrutar de momentos agrad\u00e1veis em restaurantes, cinemas e parques. Seu lugar preferido \u00e9 uma boa praia, onde ela se conecta com a natureza e se apaixona pelo mar. Seu paladar \u00e9 marcado por um milkshake de ovo maltine e uma deliciosa costela com barbecue. E, para complementar, sua cor preferida \u00e9 o encantador lil\u00e1s.<\/p>\n<p>July Garcia \u00e9 uma prova viva de que a Privacy oferece oportunidades transformadoras. Sua trajet\u00f3ria de supera\u00e7\u00e3o, sucesso e enaltecimento \u00e9 um exemplo inspirador para todas as criadoras que encontram na plataforma um espa\u00e7o para viver seus sonhos e conquistar a liberdade que tanto desejam. Com a Privacy ao seu lado, July continua a inspirar e encorajar muitas outras mulheres a seguirem em dire\u00e7\u00e3o ao seu sucesso e alcan\u00e7arem tudo o que desejam na vida.<\/p>\n<p>Leia mais<\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2023\/07\/25\/nova-musa-da-privacy-andressa-urach-viraliza-respondendo-seguidores-nas-redes-sociais\">Nova Musa da Privacy: Andressa Urach viraliza respondendo seguidores nas redes sociais<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>July Garcia, uma jovem de 21 anos, natural de Sorocaba\/SP, tem sido um nome bastante procurado na Privacy, onde compartilha conte\u00fados exclusivos e personalizados. Em entrevista \u00e0 Privacy, July contou que encontrou uma oportunidade \u00fanica na plataforma ao transformar sua paix\u00e3o por exibicionismo e produ\u00e7\u00e3o de conte\u00fado em uma carreira promissora. A ariana e solteira, &hellip;<\/p>\n","protected":false},"author":12,"featured_media":109025,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60954,170],"tags":[66529,66350,9657],"class_list":["post-109024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebridades","category-entretenimento","tag-july-garcia","tag-privacy","tag-redes-sociais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jovem de 21 anos fatura 50 mil em 4 meses vendendo conte\u00fado nas redes sociais - Litoral SP<\/title>\n<meta name=\"description\" content=\"July Garcia, uma jovem de 21 anos, natural de Sorocaba\/SP, tem sido um nome bastante procurado na Privacy, onde compartilha conte\u00fados exclusivos e personalizados.\u00a0\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/08\/06\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jovem de 21 anos fatura 50 mil em 4 meses vendendo conte\u00fado nas redes sociais - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"July Garcia, uma jovem de 21 anos, natural de Sorocaba\/SP, tem sido um nome bastante procurado na Privacy, onde compartilha conte\u00fados exclusivos e personalizados.\u00a0\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/08\/06\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-06T10:00:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/08\/July-Garcia-no-Instagram.jpg?v=1691017883\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gustavo Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/08\\\/06\\\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/08\\\/06\\\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais\"},\"author\":{\"name\":\"Gustavo Silva\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\"},\"headline\":\"Jovem de 21 anos fatura 50 mil em 4 meses vendendo conte\u00fado nas redes sociais\",\"datePublished\":\"2023-08-06T10:00:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/08\\\/06\\\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais\"},\"wordCount\":466,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/08\\\/06\\\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/08\\\/July-Garcia-no-Instagram.jpg?v=1691017883\",\"keywords\":[\"July Garcia\",\"privacy\",\"REDES SOCIAIS\"],\"articleSection\":[\"Celebridades\",\"Entretenimento\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/08\\\/06\\\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/08\\\/06\\\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/08\\\/06\\\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais\",\"name\":\"Jovem de 21 anos fatura 50 mil em 4 meses vendendo conte\u00fado nas redes sociais - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/08\\\/06\\\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/08\\\/06\\\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/08\\\/July-Garcia-no-Instagram.jpg?v=1691017883\",\"datePublished\":\"2023-08-06T10:00:49+00:00\",\"description\":\"July Garcia, uma jovem de 21 anos, natural de Sorocaba\\\/SP, tem sido um nome bastante procurado na Privacy, onde compartilha conte\u00fados exclusivos e personalizados.\u00a0\u00a0\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/08\\\/06\\\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/08\\\/06\\\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/08\\\/July-Garcia-no-Instagram.jpg?v=1691017883\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/08\\\/July-Garcia-no-Instagram.jpg?v=1691017883\",\"width\":640,\"height\":800,\"caption\":\"Jovem de 21 anos fatura 50 mil em 4 meses vendendo conte\u00fado nas redes sociais\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\",\"name\":\"Gustavo Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"caption\":\"Gustavo Silva\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/gustavosilva\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jovem de 21 anos fatura 50 mil em 4 meses vendendo conte\u00fado nas redes sociais - Litoral SP","description":"July Garcia, uma jovem de 21 anos, natural de Sorocaba\/SP, tem sido um nome bastante procurado na Privacy, onde compartilha conte\u00fados exclusivos e personalizados.\u00a0\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/08\/06\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais","og_locale":"pt_BR","og_type":"article","og_title":"Jovem de 21 anos fatura 50 mil em 4 meses vendendo conte\u00fado nas redes sociais - Litoral SP","og_description":"July Garcia, uma jovem de 21 anos, natural de Sorocaba\/SP, tem sido um nome bastante procurado na Privacy, onde compartilha conte\u00fados exclusivos e personalizados.\u00a0\u00a0","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/08\/06\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais","og_site_name":"Litoral SP","article_published_time":"2023-08-06T10:00:49+00:00","og_image":[{"width":640,"height":800,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/08\/July-Garcia-no-Instagram.jpg?v=1691017883","type":"image\/jpeg"}],"author":"Gustavo Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gustavo Silva","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/08\/06\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/08\/06\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais"},"author":{"name":"Gustavo Silva","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e"},"headline":"Jovem de 21 anos fatura 50 mil em 4 meses vendendo conte\u00fado nas redes sociais","datePublished":"2023-08-06T10:00:49+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/08\/06\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais"},"wordCount":466,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/08\/06\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/08\/July-Garcia-no-Instagram.jpg?v=1691017883","keywords":["July Garcia","privacy","REDES SOCIAIS"],"articleSection":["Celebridades","Entretenimento"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/08\/06\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/08\/06\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/08\/06\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais","name":"Jovem de 21 anos fatura 50 mil em 4 meses vendendo conte\u00fado nas redes sociais - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/08\/06\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/08\/06\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/08\/July-Garcia-no-Instagram.jpg?v=1691017883","datePublished":"2023-08-06T10:00:49+00:00","description":"July Garcia, uma jovem de 21 anos, natural de Sorocaba\/SP, tem sido um nome bastante procurado na Privacy, onde compartilha conte\u00fados exclusivos e personalizados.\u00a0\u00a0","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/08\/06\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/08\/06\/jovem-de-21-anos-fatura-50-mil-em-4-meses-vendendo-conteudo-nas-redes-sociais#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/08\/July-Garcia-no-Instagram.jpg?v=1691017883","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2023\/08\/July-Garcia-no-Instagram.jpg?v=1691017883","width":640,"height":800,"caption":"Jovem de 21 anos fatura 50 mil em 4 meses vendendo conte\u00fado nas redes sociais"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e","name":"Gustavo Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","caption":"Gustavo Silva"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/gustavosilva"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/109024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=109024"}],"version-history":[{"count":0,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/109024\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/109025"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=109024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=109024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=109024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}