{"id":112537,"date":"2023-12-02T12:00:35","date_gmt":"2023-12-02T15:00:35","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/?p=112537"},"modified":"2023-11-29T21:14:06","modified_gmt":"2023-11-30T00:14:06","slug":"expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/02\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia","title":{"rendered":"Expectativa de vida sobe para 75,5 anos ap\u00f3s queda na pandemia"},"content":{"rendered":"<p>A expectativa de vida ao nascer no Brasil, em 2022, ficou em 75,5 anos, segundo dados das T\u00e1buas da Mortalidade, divulgados nesta quarta-feira (29), no Rio de Janeiro, pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE). O dado que projeta a longevidade dos brasileiros teve uma recupera\u00e7\u00e3o parcial no ano passado ap\u00f3s dois anos seguidos de quedas em 2021 e 2020, quando a pandemia de covid-19 fez mais v\u00edtimas. \u00a0<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1569453&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1569453&amp;o=node\" \/><\/p>\n<p>O estudo foi constru\u00eddo com base no Censo Demogr\u00e1fico de 2022, diferentemente dos anos anteriores, em que a expectativa de vida era calculada a partir de proje\u00e7\u00f5es populacionais revisadas em 2018, que eram baseadas no Censo de 2010.<\/p>\n<p>A informa\u00e7\u00e3o mostra, pela primeira vez, os impactos da pandemia de covid-19 na expectativa de vida do brasileiro, e, com isso, o IBGE tamb\u00e9m revisou a esperan\u00e7a de vida ao nascer divulgada nos anos anteriores.<\/p>\n<p>Os n\u00fameros preliminares apontam que a expectativa de vida em 2020 foi de 74,8 anos, portanto, dois anos a menos do que o estimado anteriormente, de 76,8 anos.<\/p>\n<p>Em 2021, ano da pandemia com mais mortes, a proje\u00e7\u00e3o foi de de 72,8 anos, ou seja, 4,2 anos a menos que os 77 anos publicados na divulga\u00e7\u00e3o passada.<\/p>\n<p>\u201cA gente fez uma estimativa n\u00e3o prevendo uma crise sanit\u00e1ria que afetasse os \u00f3bitos\u201d, explicou Izabel Marri, pesquisadora do IBGE, sobre os n\u00fameros que foram publicados antes da revis\u00e3o.<\/p>\n<h2>Esperan\u00e7a recuperada<\/h2>\n<p>\u201cA\u00a0esperan\u00e7a de vida de 2022 \u00e9 como se a gente recuperasse um pouco a esperan\u00e7a de vida em rela\u00e7\u00e3o ao pior ano da pandemia. Passado o pior ano, com o maior aumento de \u00f3bitos do mundo, a gente consegue recuperar um c\u00e1lculo de esperan\u00e7a de vida ao nascer&#8221;, afirma Marri.<\/p>\n<p>Em rela\u00e7\u00e3o aos anos pr\u00e9-pandemia, a revis\u00e3o do IBGE aponta para as seguintes expectativas de vida: 2019 (76,2 anos), 2018 (76,1 anos), 2017 (75,6 anos) e 2016 (75,3 anos). Portanto, com a revis\u00e3o do IBGE, a esperan\u00e7a de vida ao nascer em 2022 \u00e9 a menor desde 2017, excluindo os anos com maior mortalidade durante a pandemia (2020 e 2021)\u00a0.<\/p>\n<p>Marri acredita que, em 2023, cujos dados sair\u00e3o apenas em 2024, a expectativa de vida continuar\u00e1 crescendo, recuperando as perdas ocorridas durante a pandemia. \u201cA gente j\u00e1 recuperou um pouco o n\u00edvel de esperan\u00e7a de vida ao nascer e a gente tende a recuperar um pouco mais no pr\u00f3ximo ano\u201d, argumenta a pesquisadora.<\/p>\n<h2>Sexo<\/h2>\n<p>Em rela\u00e7\u00e3o aos sexos, a expectativa de vida das mulheres ficou em 79 anos, abaixo dos 80,1 anos de 2019, enquanto a dos homens ficou em 72 anos, taxa tamb\u00e9m inferior aos 73,1 anos de 2019.<\/p>\n<p>A probabilidade de morte do rec\u00e9m-nascido &#8211; registrada em 2022 &#8211; ficou em 12,84 por mil nascidos vivos, acima dos 11,94 por mil de 2019. Entre os homens, a taxa foi de 13,94 (superior aos 12,85 de 2019), enquanto entre as mulheres foi 11,69 (maior que os 10,98 de 2019).<\/p>\n<p>Leia mais<\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2023\/11\/27\/inclusao-digital-para-idosos-ainda-enfrenta-desafios\">Inclus\u00e3o digital para idosos ainda enfrenta desafios<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A expectativa de vida ao nascer no Brasil, em 2022, ficou em 75,5 anos, segundo dados das T\u00e1buas da Mortalidade, divulgados nesta quarta-feira (29), no Rio de Janeiro, pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE). O dado que projeta a longevidade dos brasileiros teve uma recupera\u00e7\u00e3o parcial no ano passado ap\u00f3s dois anos seguidos &hellip;<\/p>\n","protected":false},"author":12,"featured_media":85991,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6470,10278],"tags":[],"class_list":["post-112537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acao-social","category-cidadania"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Expectativa de vida sobe para 75,5 anos ap\u00f3s queda na pandemia - Litoral SP<\/title>\n<meta name=\"description\" content=\"O dado que projeta a longevidade dos brasileiros teve uma recupera\u00e7\u00e3o parcial no ano passado ap\u00f3s dois anos seguidos de quedas em 2021 e 2020, quando a pandemia de covid-19 fez mais v\u00edtimas. \u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/02\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expectativa de vida sobe para 75,5 anos ap\u00f3s queda na pandemia - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"O dado que projeta a longevidade dos brasileiros teve uma recupera\u00e7\u00e3o parcial no ano passado ap\u00f3s dois anos seguidos de quedas em 2021 e 2020, quando a pandemia de covid-19 fez mais v\u00edtimas. \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/02\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-02T15:00:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/06\/1-16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gustavo Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/02\\\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/02\\\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia\"},\"author\":{\"name\":\"Gustavo Silva\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\"},\"headline\":\"Expectativa de vida sobe para 75,5 anos ap\u00f3s queda na pandemia\",\"datePublished\":\"2023-12-02T15:00:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/02\\\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia\"},\"wordCount\":491,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/02\\\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/1-16.jpg\",\"articleSection\":[\"A\u00e7\u00e3o Social\",\"Cidadania\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/02\\\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/02\\\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/02\\\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia\",\"name\":\"Expectativa de vida sobe para 75,5 anos ap\u00f3s queda na pandemia - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/02\\\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/02\\\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/1-16.jpg\",\"datePublished\":\"2023-12-02T15:00:35+00:00\",\"description\":\"O dado que projeta a longevidade dos brasileiros teve uma recupera\u00e7\u00e3o parcial no ano passado ap\u00f3s dois anos seguidos de quedas em 2021 e 2020, quando a pandemia de covid-19 fez mais v\u00edtimas. \u00a0\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/02\\\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/02\\\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/1-16.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/1-16.jpg\",\"width\":1440,\"height\":1080,\"caption\":\"Propriet\u00e1rio de banca \u00e9 multado por furto de energia em S\u00e3o Vicente\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\",\"name\":\"Gustavo Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"caption\":\"Gustavo Silva\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/gustavosilva\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Expectativa de vida sobe para 75,5 anos ap\u00f3s queda na pandemia - Litoral SP","description":"O dado que projeta a longevidade dos brasileiros teve uma recupera\u00e7\u00e3o parcial no ano passado ap\u00f3s dois anos seguidos de quedas em 2021 e 2020, quando a pandemia de covid-19 fez mais v\u00edtimas. \u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/02\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia","og_locale":"pt_BR","og_type":"article","og_title":"Expectativa de vida sobe para 75,5 anos ap\u00f3s queda na pandemia - Litoral SP","og_description":"O dado que projeta a longevidade dos brasileiros teve uma recupera\u00e7\u00e3o parcial no ano passado ap\u00f3s dois anos seguidos de quedas em 2021 e 2020, quando a pandemia de covid-19 fez mais v\u00edtimas. \u00a0","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/02\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia","og_site_name":"Litoral SP","article_published_time":"2023-12-02T15:00:35+00:00","og_image":[{"width":1440,"height":1080,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/06\/1-16.jpg","type":"image\/jpeg"}],"author":"Gustavo Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gustavo Silva","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/02\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/02\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia"},"author":{"name":"Gustavo Silva","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e"},"headline":"Expectativa de vida sobe para 75,5 anos ap\u00f3s queda na pandemia","datePublished":"2023-12-02T15:00:35+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/02\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia"},"wordCount":491,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/02\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/06\/1-16.jpg","articleSection":["A\u00e7\u00e3o Social","Cidadania"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/02\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/02\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/02\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia","name":"Expectativa de vida sobe para 75,5 anos ap\u00f3s queda na pandemia - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/02\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/02\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/06\/1-16.jpg","datePublished":"2023-12-02T15:00:35+00:00","description":"O dado que projeta a longevidade dos brasileiros teve uma recupera\u00e7\u00e3o parcial no ano passado ap\u00f3s dois anos seguidos de quedas em 2021 e 2020, quando a pandemia de covid-19 fez mais v\u00edtimas. \u00a0","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/02\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/02\/expectativa-de-vida-sobe-para-755-anos-apos-queda-na-pandemia#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/06\/1-16.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/06\/1-16.jpg","width":1440,"height":1080,"caption":"Propriet\u00e1rio de banca \u00e9 multado por furto de energia em S\u00e3o Vicente"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e","name":"Gustavo Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","caption":"Gustavo Silva"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/gustavosilva"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/112537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=112537"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/112537\/revisions"}],"predecessor-version":[{"id":112585,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/112537\/revisions\/112585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/85991"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=112537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=112537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=112537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}