{"id":113133,"date":"2023-12-23T15:00:08","date_gmt":"2023-12-23T18:00:08","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/?p=113133"},"modified":"2023-12-20T23:25:36","modified_gmt":"2023-12-21T02:25:36","slug":"apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/23\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos","title":{"rendered":"Apenas 10% das secretarias estaduais s\u00e3o ocupadas por pretos e pardos"},"content":{"rendered":"<p>Um estudo in\u00e9dito realizada pelo Grupo de Estudos Multidisciplinares de A\u00e7\u00e3o Afirmativa da Universidade Estadual do Rio de Janeiro (Gemaa\/Uerj), a pedido da Funda\u00e7\u00e3o Lemann em parceria com a Imaginable Futures, revelou que s\u00f3 10,5% dos secret\u00e1rios e secret\u00e1rias dos governos estaduais s\u00e3o pessoas pretas e pardas. Mulheres ocupam apenas 29,7% desses cargos de alta lideran\u00e7a, e as pretas e pardas ocupam apenas 4% do secretariado.\u00a0<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1573680&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1573680&amp;o=node\" \/><\/p>\n<p>Quando analisadas as regi\u00f5es, somente o Nordeste apresenta percentual de secret\u00e1rias de estado acima da m\u00e9dia nacional, de 37,2% contra os 29,7%, quase metade das mulheres (47,1%) mapeadas em cargos de secret\u00e1ria estadual se encontram na regi\u00e3o. O Nordeste (13,5%) e o Norte (13,7%) s\u00e3o as \u00fanicas regi\u00f5es que t\u00eam percentual de pretos e pardos acima da m\u00e9dia nacional no secretariado (10,5%), sendo que 81,7% de todos os secret\u00e1rios estaduais pretos e pardos se encontram nessas regi\u00f5es.<\/p>\n<p>Segundo a pesquisa, mais da metade dos secret\u00e1rios pretos e pardos (51,6%) comandam pastas sociais, como Assist\u00eancia Social, Cultura e Esportes. O setor social tamb\u00e9m \u00e9 onde est\u00e1 a maioria das secret\u00e1rias (53,5%), enquanto os homens est\u00e3o mais distribu\u00eddos entre os setores social (25,3%), de infraestrutura (23,3%), econ\u00f4mico (24,1%) e central (27,1%).<\/p>\n<p>Segundo o coordenador do Gemaa e professor de Ci\u00eancia Pol\u00edtica da Uerj, Luiz Augusto\u00a0 Campos, a pequena presen\u00e7a de pessoas pretas e pardas no secretariado implica um d\u00e9ficit democr\u00e1tico. \u201cAs pol\u00edticas p\u00fablicas estaduais, da educa\u00e7\u00e3o \u00e0 sa\u00fade passando pela seguran\u00e7a p\u00fablica, impactam sobremaneira a popula\u00e7\u00e3o preta e parda brasileira, mas s\u00e3o pensadas e geridas por secret\u00e1rios em sua maioria brancos e homens\u201d, disse Campos.<\/p>\n<p>De acordo com o diretor de Conhecimento, Dados e Pesquisa da Funda\u00e7\u00e3o Lemann, Daniel de Bonis, o objetivo da pesquisa \u00e9 mostrar que h\u00e1 falta de dados nessa \u00e1rea, pois n\u00e3o h\u00e1 uma exig\u00eancia oficial sobre publicar dados a respeito do perfil racial, de g\u00eanero ou socioecon\u00f4mico dos altos dirigentes p\u00fablicos.<\/p>\n<p>\u201cIsso \u00e9 um uma defici\u00eancia muito grande para termos visibilidade de um grupo que tem uma influ\u00eancia enorme no desenho e implementa\u00e7\u00e3o de pol\u00edticas p\u00fablicas\u201d, avalia.<\/p>\n<p>Bonis defende que para modificar essa situa\u00e7\u00e3o \u00e9 preciso haver diversidade e inclus\u00e3o, j\u00e1 que o que aparece atualmente \u00e9 um grupo majoritariamente formado por homens brancos, nada muito diferente do que se encontra Congresso Nacional.<\/p>\n<p>\u201c\u00c9 mais um indicador de que os espa\u00e7os de poder no pa\u00eds ainda s\u00e3o muito concentrados nesse grupo. E em termos internacionais, mostra que o Brasil est\u00e1 muito atr\u00e1s de conseguir ter mais diversidade e inclus\u00e3o, fatores importantes na sociedade contempor\u00e2nea para a gente ter uma democratiza\u00e7\u00e3o plena desses espa\u00e7os\u201d. afirmou.<\/p>\n<p>Para concluir a pesquisa foi feito o mapeamento de 572 secret\u00e1rios e secret\u00e1rias estaduais nas 27 Unidades da Federa\u00e7\u00e3o, classificando as pastas por campo de atua\u00e7\u00e3o &#8211; social, econ\u00f4mica, infraestrutura ou \u00f3rg\u00e3os centrais.<\/p>\n<p><strong>Leia mais<\/strong><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2023\/06\/17\/faltam-mulheres-negras-em-altas-liderancas-do-setor-de-publicidade\">Jundia\u00ed conta com 120 vagas para cursos t\u00e9cnicos gratuitos<\/a><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2023\/06\/17\/faltam-mulheres-negras-em-altas-liderancas-do-setor-de-publicidade\">Faltam mulheres negras em altas lideran\u00e7as do setor de publicidade<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um estudo in\u00e9dito realizada pelo Grupo de Estudos Multidisciplinares de A\u00e7\u00e3o Afirmativa da Universidade Estadual do Rio de Janeiro (Gemaa\/Uerj), a pedido da Funda\u00e7\u00e3o Lemann em parceria com a Imaginable Futures, revelou que s\u00f3 10,5% dos secret\u00e1rios e secret\u00e1rias dos governos estaduais s\u00e3o pessoas pretas e pardas. Mulheres ocupam apenas 29,7% desses cargos de alta &hellip;<\/p>\n","protected":false},"author":12,"featured_media":95149,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10278,1625],"tags":[12353,67753,67617,67754],"class_list":["post-113133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidadania","category-direitos-humanos","tag-mulheres","tag-pardos","tag-pretos","tag-tecnicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apenas 10% das secretarias estaduais s\u00e3o ocupadas por pretos e pardos - Litoral SP<\/title>\n<meta name=\"description\" content=\"Mulheres ocupam apenas 29,7% desses cargos de alta lideran\u00e7a, e as pretas e pardas ocupam apenas 4% do secretariado.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/23\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apenas 10% das secretarias estaduais s\u00e3o ocupadas por pretos e pardos - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"Mulheres ocupam apenas 29,7% desses cargos de alta lideran\u00e7a, e as pretas e pardas ocupam apenas 4% do secretariado.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/23\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-23T18:00:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/11\/Populacao-mundial-atinge-a-marca-de-8-bilhoes-de-pessoas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gustavo Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/23\\\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/23\\\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos\"},\"author\":{\"name\":\"Gustavo Silva\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\"},\"headline\":\"Apenas 10% das secretarias estaduais s\u00e3o ocupadas por pretos e pardos\",\"datePublished\":\"2023-12-23T18:00:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/23\\\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos\"},\"wordCount\":531,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/23\\\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/11\\\/Populacao-mundial-atinge-a-marca-de-8-bilhoes-de-pessoas.jpg\",\"keywords\":[\"MULHERES\",\"pardos\",\"pretos\",\"t\u00e9cnicos\"],\"articleSection\":[\"Cidadania\",\"Direitos Humanos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/23\\\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/23\\\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/23\\\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos\",\"name\":\"Apenas 10% das secretarias estaduais s\u00e3o ocupadas por pretos e pardos - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/23\\\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/23\\\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/11\\\/Populacao-mundial-atinge-a-marca-de-8-bilhoes-de-pessoas.jpg\",\"datePublished\":\"2023-12-23T18:00:08+00:00\",\"description\":\"Mulheres ocupam apenas 29,7% desses cargos de alta lideran\u00e7a, e as pretas e pardas ocupam apenas 4% do secretariado.\u00a0\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/23\\\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2023\\\/12\\\/23\\\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/11\\\/Populacao-mundial-atinge-a-marca-de-8-bilhoes-de-pessoas.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/11\\\/Populacao-mundial-atinge-a-marca-de-8-bilhoes-de-pessoas.jpg\",\"width\":1200,\"height\":628,\"caption\":\"Cr\u00e9dito: Reprodu\u00e7\u00e3o\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\",\"name\":\"Gustavo Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"caption\":\"Gustavo Silva\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/gustavosilva\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apenas 10% das secretarias estaduais s\u00e3o ocupadas por pretos e pardos - Litoral SP","description":"Mulheres ocupam apenas 29,7% desses cargos de alta lideran\u00e7a, e as pretas e pardas ocupam apenas 4% do secretariado.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/23\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos","og_locale":"pt_BR","og_type":"article","og_title":"Apenas 10% das secretarias estaduais s\u00e3o ocupadas por pretos e pardos - Litoral SP","og_description":"Mulheres ocupam apenas 29,7% desses cargos de alta lideran\u00e7a, e as pretas e pardas ocupam apenas 4% do secretariado.\u00a0","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/23\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos","og_site_name":"Litoral SP","article_published_time":"2023-12-23T18:00:08+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/11\/Populacao-mundial-atinge-a-marca-de-8-bilhoes-de-pessoas.jpg","type":"image\/jpeg"}],"author":"Gustavo Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gustavo Silva","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/23\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/23\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos"},"author":{"name":"Gustavo Silva","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e"},"headline":"Apenas 10% das secretarias estaduais s\u00e3o ocupadas por pretos e pardos","datePublished":"2023-12-23T18:00:08+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/23\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos"},"wordCount":531,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/23\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/11\/Populacao-mundial-atinge-a-marca-de-8-bilhoes-de-pessoas.jpg","keywords":["MULHERES","pardos","pretos","t\u00e9cnicos"],"articleSection":["Cidadania","Direitos Humanos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/23\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/23\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/23\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos","name":"Apenas 10% das secretarias estaduais s\u00e3o ocupadas por pretos e pardos - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/23\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/23\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/11\/Populacao-mundial-atinge-a-marca-de-8-bilhoes-de-pessoas.jpg","datePublished":"2023-12-23T18:00:08+00:00","description":"Mulheres ocupam apenas 29,7% desses cargos de alta lideran\u00e7a, e as pretas e pardas ocupam apenas 4% do secretariado.\u00a0","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/23\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/12\/23\/apenas-10-das-secretarias-estaduais-sao-ocupadas-por-pretos-e-pardos#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/11\/Populacao-mundial-atinge-a-marca-de-8-bilhoes-de-pessoas.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/11\/Populacao-mundial-atinge-a-marca-de-8-bilhoes-de-pessoas.jpg","width":1200,"height":628,"caption":"Cr\u00e9dito: Reprodu\u00e7\u00e3o"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e","name":"Gustavo Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","caption":"Gustavo Silva"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/gustavosilva"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/113133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=113133"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/113133\/revisions"}],"predecessor-version":[{"id":113180,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/113133\/revisions\/113180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/95149"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=113133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=113133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=113133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}