{"id":113837,"date":"2024-01-20T19:52:12","date_gmt":"2024-01-20T22:52:12","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/?p=113837"},"modified":"2024-01-20T19:52:12","modified_gmt":"2024-01-20T22:52:12","slug":"operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/20\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia","title":{"rendered":"Opera\u00e7\u00e3o de Fiscaliza\u00e7\u00e3o retira 38 equipamentos de som da faixa de areia"},"content":{"rendered":"<p data-raofz=\"17\">A primeira semana de apreens\u00e3o de equipamentos de som na faixa de areia das praias de Guaruj\u00e1 demonstra a efetividade da a\u00e7\u00e3o coordenada pela Secretaria Municipal de Defesa e Conviv\u00eancia Social.<\/p>\n<p data-raofz=\"17\">O balan\u00e7o no per\u00edodo de 8 a 16 de janeiro registrou\u00a0484 orienta\u00e7\u00f5es sobre a proibi\u00e7\u00e3o do som, 38 aparelhos retirados das praias e\u00a010 apreens\u00f5es realizadas pelas equipes de fiscaliza\u00e7\u00e3o.<\/p>\n<p data-raofz=\"17\">Mas, principalmente, tem sido observado pelas equipes nas ruas o respeito \u00e0 regra e a conscientiza\u00e7\u00e3o da popula\u00e7\u00e3o.<\/p>\n<p data-raofz=\"17\">Todos os dias, 80 guardas civis municipais, policiais militares em Atividade Delegada (quando, em dias de folga, os agentes volunt\u00e1rios atuam com a hora paga pelo Munic\u00edpio) e fiscais integram a Opera\u00e7\u00e3o Especial de Ver\u00e3o de Fiscaliza\u00e7\u00e3o 2024.<\/p>\n<p data-raofz=\"17\">As equipes percorrem as seis principais praias de Guaruj\u00e1 distribuindo material informativo e fiscalizando o cumprimento do C\u00f3digo Municipal de Posturas, que prev\u00ea as regras de praia.<\/p>\n<p data-raofz=\"17\"><strong>Leia mais<\/strong><\/p>\n<p data-raofz=\"17\"><a href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/07\/servidores-de-guaruja-acolhem-pets-no-ambiente-de-trabalho\">Servidores de Guaruj\u00e1 acolhem pets no ambiente de trabalho<\/a><\/p>\n<p data-raofz=\"17\"><a href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/03\/som-abusivo-e-recordista-com-mais-de-47-mil-ocorrencias-registradas-nas-praias-de-guaruja\">Som abusivo \u00e9 recordista com mais de 4,7 mil ocorr\u00eancias registradas nas praias de Guaruj\u00e1<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A primeira semana de apreens\u00e3o de equipamentos de som na faixa de areia das praias de Guaruj\u00e1 demonstra a efetividade da a\u00e7\u00e3o coordenada pela Secretaria Municipal de Defesa e Conviv\u00eancia Social. O balan\u00e7o no per\u00edodo de 8 a 16 de janeiro registrou\u00a0484 orienta\u00e7\u00f5es sobre a proibi\u00e7\u00e3o do som, 38 aparelhos retirados das praias e\u00a010 apreens\u00f5es &hellip;<\/p>\n","protected":false},"author":12,"featured_media":113838,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[187,10],"tags":[67903,6426,67904],"class_list":["post-113837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guaruja","category-policia","tag-caixas-som","tag-guaruja-2","tag-som-nas-praias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Opera\u00e7\u00e3o de Fiscaliza\u00e7\u00e3o retira 38 equipamentos de som da faixa de areia - Litoral SP<\/title>\n<meta name=\"description\" content=\"A primeira semana de apreens\u00e3o de equipamentos de som na faixa de areia das praias de Guaruj\u00e1 demonstra a efetividade da a\u00e7\u00e3o coordenada pela Secretaria Municipal de Defesa e Conviv\u00eancia Social.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/20\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Opera\u00e7\u00e3o de Fiscaliza\u00e7\u00e3o retira 38 equipamentos de som da faixa de areia - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"A primeira semana de apreens\u00e3o de equipamentos de som na faixa de areia das praias de Guaruj\u00e1 demonstra a efetividade da a\u00e7\u00e3o coordenada pela Secretaria Municipal de Defesa e Conviv\u00eancia Social.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/20\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-20T22:52:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/01\/53470732229_3da67a2fd4_b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gustavo Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/01\\\/20\\\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/01\\\/20\\\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia\"},\"author\":{\"name\":\"Gustavo Silva\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\"},\"headline\":\"Opera\u00e7\u00e3o de Fiscaliza\u00e7\u00e3o retira 38 equipamentos de som da faixa de areia\",\"datePublished\":\"2024-01-20T22:52:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/01\\\/20\\\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia\"},\"wordCount\":192,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/01\\\/20\\\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/53470732229_3da67a2fd4_b.jpg\",\"keywords\":[\"caixas som\",\"Guaruj\u00e1\",\"som nas praias\"],\"articleSection\":[\"Guaruj\u00e1\",\"Pol\u00edcia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/01\\\/20\\\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/01\\\/20\\\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/01\\\/20\\\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia\",\"name\":\"Opera\u00e7\u00e3o de Fiscaliza\u00e7\u00e3o retira 38 equipamentos de som da faixa de areia - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/01\\\/20\\\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/01\\\/20\\\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/53470732229_3da67a2fd4_b.jpg\",\"datePublished\":\"2024-01-20T22:52:12+00:00\",\"description\":\"A primeira semana de apreens\u00e3o de equipamentos de som na faixa de areia das praias de Guaruj\u00e1 demonstra a efetividade da a\u00e7\u00e3o coordenada pela Secretaria Municipal de Defesa e Conviv\u00eancia Social.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/01\\\/20\\\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/01\\\/20\\\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/53470732229_3da67a2fd4_b.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/53470732229_3da67a2fd4_b.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\",\"name\":\"Gustavo Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"caption\":\"Gustavo Silva\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/gustavosilva\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Opera\u00e7\u00e3o de Fiscaliza\u00e7\u00e3o retira 38 equipamentos de som da faixa de areia - Litoral SP","description":"A primeira semana de apreens\u00e3o de equipamentos de som na faixa de areia das praias de Guaruj\u00e1 demonstra a efetividade da a\u00e7\u00e3o coordenada pela Secretaria Municipal de Defesa e Conviv\u00eancia Social.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/20\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia","og_locale":"pt_BR","og_type":"article","og_title":"Opera\u00e7\u00e3o de Fiscaliza\u00e7\u00e3o retira 38 equipamentos de som da faixa de areia - Litoral SP","og_description":"A primeira semana de apreens\u00e3o de equipamentos de som na faixa de areia das praias de Guaruj\u00e1 demonstra a efetividade da a\u00e7\u00e3o coordenada pela Secretaria Municipal de Defesa e Conviv\u00eancia Social.","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/20\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia","og_site_name":"Litoral SP","article_published_time":"2024-01-20T22:52:12+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/01\/53470732229_3da67a2fd4_b.jpg","type":"image\/jpeg"}],"author":"Gustavo Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gustavo Silva","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/20\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/20\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia"},"author":{"name":"Gustavo Silva","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e"},"headline":"Opera\u00e7\u00e3o de Fiscaliza\u00e7\u00e3o retira 38 equipamentos de som da faixa de areia","datePublished":"2024-01-20T22:52:12+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/20\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia"},"wordCount":192,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/20\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/01\/53470732229_3da67a2fd4_b.jpg","keywords":["caixas som","Guaruj\u00e1","som nas praias"],"articleSection":["Guaruj\u00e1","Pol\u00edcia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/20\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/20\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/20\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia","name":"Opera\u00e7\u00e3o de Fiscaliza\u00e7\u00e3o retira 38 equipamentos de som da faixa de areia - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/20\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/20\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/01\/53470732229_3da67a2fd4_b.jpg","datePublished":"2024-01-20T22:52:12+00:00","description":"A primeira semana de apreens\u00e3o de equipamentos de som na faixa de areia das praias de Guaruj\u00e1 demonstra a efetividade da a\u00e7\u00e3o coordenada pela Secretaria Municipal de Defesa e Conviv\u00eancia Social.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/20\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/01\/20\/operacao-de-fiscalizacao-retira-38-equipamentos-de-som-da-faixa-de-areia#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/01\/53470732229_3da67a2fd4_b.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/01\/53470732229_3da67a2fd4_b.jpg","width":1024,"height":768},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e","name":"Gustavo Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","caption":"Gustavo Silva"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/gustavosilva"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/113837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=113837"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/113837\/revisions"}],"predecessor-version":[{"id":113839,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/113837\/revisions\/113839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/113838"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=113837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=113837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=113837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}