{"id":114208,"date":"2024-02-06T19:00:47","date_gmt":"2024-02-06T22:00:47","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/?p=114208"},"modified":"2024-02-06T17:09:20","modified_gmt":"2024-02-06T20:09:20","slug":"unidos-dos-morros-e-tricampea-do-carnaval-santista","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/06\/unidos-dos-morros-e-tricampea-do-carnaval-santista","title":{"rendered":"Unidos dos Morros \u00e9 tricampe\u00e3 do Carnaval Santista"},"content":{"rendered":"<p>A escola de samba Unidos dos Morros \u00e9 a campe\u00e3 do Grupo Especial das escolas de samba da cidade de santos em 2024.<\/p>\n<p>De acordo com as informa\u00e7\u00f5es, a tricampe\u00e3 do carnaval santista conquistou o t\u00edtulo garantindo 269,7 pontos.<\/p>\n<p>Ainda de acordo com as informa\u00e7\u00f5es, a escola levou para a avenida as lendas e a voca\u00e7\u00e3o m\u00edstica que envolvem a cidade de Peru\u00edbe (SP).<\/p>\n<p>Sendo assim, a\u00a0escola de samba<strong>\u00a0Bandeirantes do Sabo\u00f3\u00a0<\/strong>foi a vencedora do Grupo de Acesso ap\u00f3s conquistar 268,5 pontos.<\/p>\n<p>Leia mais<\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/05\/forca-tarefa-localiza-e-autua-construcoes-irregulares-em-santos\">For\u00e7a-tarefa localiza e autua constru\u00e7\u00f5es irregulares em Santos<\/a><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/05\/agentes-da-gcm-em-formacao-participam-de-treinamento-de-brigada-de-incendio\">Agentes da GCM em forma\u00e7\u00e3o participam de treinamento de Brigada de Inc\u00eandio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A escola de samba Unidos dos Morros \u00e9 a campe\u00e3 do Grupo Especial das escolas de samba da cidade de santos em 2024. De acordo com as informa\u00e7\u00f5es, a tricampe\u00e3 do carnaval santista conquistou o t\u00edtulo garantindo 269,7 pontos. Ainda de acordo com as informa\u00e7\u00f5es, a escola levou para a avenida as lendas e a &hellip;<\/p>\n","protected":false},"author":12,"featured_media":114209,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2001,180],"tags":[36309,64536,59157],"class_list":["post-114208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-e-musica","category-santos","tag-escola","tag-escola-de-samba","tag-samba"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unidos dos Morros \u00e9 tricampe\u00e3 do Carnaval Santista - Litoral SP<\/title>\n<meta name=\"description\" content=\"A escola de samba Unidos dos Morros \u00e9 a campe\u00e3 do Grupo Especial das escolas de samba da cidade de santos em 2024.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/06\/unidos-dos-morros-e-tricampea-do-carnaval-santista\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unidos dos Morros \u00e9 tricampe\u00e3 do Carnaval Santista - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"A escola de samba Unidos dos Morros \u00e9 a campe\u00e3 do Grupo Especial das escolas de samba da cidade de santos em 2024.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/06\/unidos-dos-morros-e-tricampea-do-carnaval-santista\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-06T22:00:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/02\/cdcscd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"569\" \/>\n\t<meta property=\"og:image:height\" content=\"371\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gustavo Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/02\\\/06\\\/unidos-dos-morros-e-tricampea-do-carnaval-santista#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/02\\\/06\\\/unidos-dos-morros-e-tricampea-do-carnaval-santista\"},\"author\":{\"name\":\"Gustavo Silva\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\"},\"headline\":\"Unidos dos Morros \u00e9 tricampe\u00e3 do Carnaval Santista\",\"datePublished\":\"2024-02-06T22:00:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/02\\\/06\\\/unidos-dos-morros-e-tricampea-do-carnaval-santista\"},\"wordCount\":120,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/02\\\/06\\\/unidos-dos-morros-e-tricampea-do-carnaval-santista#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/02\\\/cdcscd.jpg\",\"keywords\":[\"ESCOLA\",\"escola de samba\",\"SAMBA\"],\"articleSection\":[\"Cultura e M\u00fasica\",\"Santos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/02\\\/06\\\/unidos-dos-morros-e-tricampea-do-carnaval-santista#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/02\\\/06\\\/unidos-dos-morros-e-tricampea-do-carnaval-santista\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/02\\\/06\\\/unidos-dos-morros-e-tricampea-do-carnaval-santista\",\"name\":\"Unidos dos Morros \u00e9 tricampe\u00e3 do Carnaval Santista - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/02\\\/06\\\/unidos-dos-morros-e-tricampea-do-carnaval-santista#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/02\\\/06\\\/unidos-dos-morros-e-tricampea-do-carnaval-santista#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/02\\\/cdcscd.jpg\",\"datePublished\":\"2024-02-06T22:00:47+00:00\",\"description\":\"A escola de samba Unidos dos Morros \u00e9 a campe\u00e3 do Grupo Especial das escolas de samba da cidade de santos em 2024.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/02\\\/06\\\/unidos-dos-morros-e-tricampea-do-carnaval-santista\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/02\\\/06\\\/unidos-dos-morros-e-tricampea-do-carnaval-santista#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/02\\\/cdcscd.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/02\\\/cdcscd.jpg\",\"width\":569,\"height\":371},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\",\"name\":\"Gustavo Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"caption\":\"Gustavo Silva\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/gustavosilva\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unidos dos Morros \u00e9 tricampe\u00e3 do Carnaval Santista - Litoral SP","description":"A escola de samba Unidos dos Morros \u00e9 a campe\u00e3 do Grupo Especial das escolas de samba da cidade de santos em 2024.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/06\/unidos-dos-morros-e-tricampea-do-carnaval-santista","og_locale":"pt_BR","og_type":"article","og_title":"Unidos dos Morros \u00e9 tricampe\u00e3 do Carnaval Santista - Litoral SP","og_description":"A escola de samba Unidos dos Morros \u00e9 a campe\u00e3 do Grupo Especial das escolas de samba da cidade de santos em 2024.","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/06\/unidos-dos-morros-e-tricampea-do-carnaval-santista","og_site_name":"Litoral SP","article_published_time":"2024-02-06T22:00:47+00:00","og_image":[{"width":569,"height":371,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/02\/cdcscd.jpg","type":"image\/jpeg"}],"author":"Gustavo Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gustavo Silva","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/06\/unidos-dos-morros-e-tricampea-do-carnaval-santista#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/06\/unidos-dos-morros-e-tricampea-do-carnaval-santista"},"author":{"name":"Gustavo Silva","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e"},"headline":"Unidos dos Morros \u00e9 tricampe\u00e3 do Carnaval Santista","datePublished":"2024-02-06T22:00:47+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/06\/unidos-dos-morros-e-tricampea-do-carnaval-santista"},"wordCount":120,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/06\/unidos-dos-morros-e-tricampea-do-carnaval-santista#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/02\/cdcscd.jpg","keywords":["ESCOLA","escola de samba","SAMBA"],"articleSection":["Cultura e M\u00fasica","Santos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/06\/unidos-dos-morros-e-tricampea-do-carnaval-santista#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/06\/unidos-dos-morros-e-tricampea-do-carnaval-santista","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/06\/unidos-dos-morros-e-tricampea-do-carnaval-santista","name":"Unidos dos Morros \u00e9 tricampe\u00e3 do Carnaval Santista - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/06\/unidos-dos-morros-e-tricampea-do-carnaval-santista#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/06\/unidos-dos-morros-e-tricampea-do-carnaval-santista#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/02\/cdcscd.jpg","datePublished":"2024-02-06T22:00:47+00:00","description":"A escola de samba Unidos dos Morros \u00e9 a campe\u00e3 do Grupo Especial das escolas de samba da cidade de santos em 2024.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/06\/unidos-dos-morros-e-tricampea-do-carnaval-santista"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/02\/06\/unidos-dos-morros-e-tricampea-do-carnaval-santista#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/02\/cdcscd.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/02\/cdcscd.jpg","width":569,"height":371},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e","name":"Gustavo Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","caption":"Gustavo Silva"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/gustavosilva"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/114208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=114208"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/114208\/revisions"}],"predecessor-version":[{"id":114210,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/114208\/revisions\/114210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/114209"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=114208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=114208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=114208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}