{"id":117530,"date":"2024-08-07T13:30:20","date_gmt":"2024-08-07T16:30:20","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/?p=117530"},"modified":"2024-08-07T12:33:13","modified_gmt":"2024-08-07T15:33:13","slug":"isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/08\/07\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual","title":{"rendered":"Isaquias Queiroz avan\u00e7a direto \u00e0 semifinal da canoa individual"},"content":{"rendered":"<p>Campe\u00e3o ol\u00edmpico nos Jogos de T\u00f3quio, em 2021, o baiano Isaquias Queiroz iniciou nesta quarta-feira (7) a defesa do t\u00edtulo na prova da C1 1000 metros (canoa individual) na canoagem velocidade. Ele participou da segunda bateria das eliminat\u00f3rias, que classificava os dois primeiros barcos direto para a semifinal.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1606815&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1606815&amp;o=node\" \/><\/p>\n<p>Isaquias fez uma prova tranquila, e liderou o percurso ao lado do tcheco Martin Fuksa. O brasileiro diminuiu o ritmo no meio da competi\u00e7\u00e3o e s\u00f3 administrou a vantagem at\u00e9 cruzar a linha de chegada na 2\u00aa posi\u00e7\u00e3o, com o tempo de 3min53seg94. Agora, ele descansa e s\u00f3 vai disputar a semifinal na sexta-feira (9), a partir das 6h30, no hor\u00e1rio de Bras\u00edlia. A prova que vai definir os medalhistas acontece tamb\u00e9m na sexta, a partir das 8h40.<\/p>\n<p>Antes disso, j\u00e1 amanh\u00e3 (8), Isaquias Queiroz volta \u00e0 \u00e1gua, desta vez ao lado de Jacky Godmann, na briga por um lugar na decis\u00e3o do C2 500 metros. A largada est\u00e1 prevista para 6h20.<\/p>\n<p>Ainda no C1 1000 metros, Mateus Nunes participou da quarta bateria das eliminat\u00f3rias e acabou na 3\u00aa posi\u00e7\u00e3o, com o tempo de 3min52seg60. Com isso, ele vai disputar as quartas de final da canoagem velocidade ainda hoje, para tentar uma vaga na semifinal da prova.<\/p>\n<h2>Outros resultados<\/h2>\n<p>Nas eliminat\u00f3rias da K1 500 metros (caiaque individual) para mulheres, Ana Paula Vergutz terminou a bateria na 5\u00aa posi\u00e7\u00e3o, com o tempo de 1min54seg98, e vai para a disputa de quartas de final. E no K1 1000 metros para homens, quartas de final tamb\u00e9m para Vagner Souta. O brasileiro cruzou a linha de chegada da bateria na 4\u00aa posi\u00e7\u00e3o, com o tempo de 3min46seg17.<\/p>\n<p>Leia mais<\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2024\/08\/06\/luiz-mauricio-da-silva-avanca-a-final-do-lancamento-de-dardo-em-paris\">Luiz Maur\u00edcio da Silva avan\u00e7a \u00e0 final do lan\u00e7amento de dardo em Paris<\/a><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2024\/08\/05\/brasil-termina-em-8o-lugar-no-revezamento-misto-do-triatlo-em-paris\">Isaquias e Jacky se garantem na semi da canoagem velocidade em Paris<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Campe\u00e3o ol\u00edmpico nos Jogos de T\u00f3quio, em 2021, o baiano Isaquias Queiroz iniciou nesta quarta-feira (7) a defesa do t\u00edtulo na prova da C1 1000 metros (canoa individual) na canoagem velocidade. Ele participou da segunda bateria das eliminat\u00f3rias, que classificava os dois primeiros barcos direto para a semifinal. Isaquias fez uma prova tranquila, e liderou &hellip;<\/p>\n","protected":false},"author":12,"featured_media":117531,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35,28092],"tags":[68143,16150,56753],"class_list":["post-117530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte","category-olimpiadas","tag-68143","tag-olimpiadas","tag-paris"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Isaquias Queiroz avan\u00e7a direto \u00e0 semifinal da canoa individual - Litoral SP<\/title>\n<meta name=\"description\" content=\"Campe\u00e3o ol\u00edmpico nos Jogos de T\u00f3quio, em 2021, o baiano Isaquias Queiroz iniciou nesta quarta-feira (7) a defesa do t\u00edtulo na prova da C1 1000 metros (canoa individual) na canoagem velocidade. Ele participou da segunda bateria das eliminat\u00f3rias, que classificava os dois primeiros barcos direto para a semifinal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/08\/07\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isaquias Queiroz avan\u00e7a direto \u00e0 semifinal da canoa individual - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"Campe\u00e3o ol\u00edmpico nos Jogos de T\u00f3quio, em 2021, o baiano Isaquias Queiroz iniciou nesta quarta-feira (7) a defesa do t\u00edtulo na prova da C1 1000 metros (canoa individual) na canoagem velocidade. Ele participou da segunda bateria das eliminat\u00f3rias, que classificava os dois primeiros barcos direto para a semifinal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/08\/07\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-07T16:30:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/08\/vddfvdvc.jpg?v=1723044722\" \/>\n\t<meta property=\"og:image:width\" content=\"878\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gustavo Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/08\\\/07\\\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/08\\\/07\\\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual\"},\"author\":{\"name\":\"Gustavo Silva\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\"},\"headline\":\"Isaquias Queiroz avan\u00e7a direto \u00e0 semifinal da canoa individual\",\"datePublished\":\"2024-08-07T16:30:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/08\\\/07\\\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual\"},\"wordCount\":316,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/08\\\/07\\\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/vddfvdvc.jpg?v=1723044722\",\"keywords\":[\"2024\",\"OLIMP\u00cdADAS\",\"PARIS\"],\"articleSection\":[\"Esporte\",\"Olimp\u00edadas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/08\\\/07\\\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/08\\\/07\\\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/08\\\/07\\\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual\",\"name\":\"Isaquias Queiroz avan\u00e7a direto \u00e0 semifinal da canoa individual - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/08\\\/07\\\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/08\\\/07\\\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/vddfvdvc.jpg?v=1723044722\",\"datePublished\":\"2024-08-07T16:30:20+00:00\",\"description\":\"Campe\u00e3o ol\u00edmpico nos Jogos de T\u00f3quio, em 2021, o baiano Isaquias Queiroz iniciou nesta quarta-feira (7) a defesa do t\u00edtulo na prova da C1 1000 metros (canoa individual) na canoagem velocidade. Ele participou da segunda bateria das eliminat\u00f3rias, que classificava os dois primeiros barcos direto para a semifinal.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/08\\\/07\\\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2024\\\/08\\\/07\\\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/vddfvdvc.jpg?v=1723044722\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/vddfvdvc.jpg?v=1723044722\",\"width\":878,\"height\":485},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\",\"name\":\"Gustavo Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"caption\":\"Gustavo Silva\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/gustavosilva\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Isaquias Queiroz avan\u00e7a direto \u00e0 semifinal da canoa individual - Litoral SP","description":"Campe\u00e3o ol\u00edmpico nos Jogos de T\u00f3quio, em 2021, o baiano Isaquias Queiroz iniciou nesta quarta-feira (7) a defesa do t\u00edtulo na prova da C1 1000 metros (canoa individual) na canoagem velocidade. Ele participou da segunda bateria das eliminat\u00f3rias, que classificava os dois primeiros barcos direto para a semifinal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/08\/07\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual","og_locale":"pt_BR","og_type":"article","og_title":"Isaquias Queiroz avan\u00e7a direto \u00e0 semifinal da canoa individual - Litoral SP","og_description":"Campe\u00e3o ol\u00edmpico nos Jogos de T\u00f3quio, em 2021, o baiano Isaquias Queiroz iniciou nesta quarta-feira (7) a defesa do t\u00edtulo na prova da C1 1000 metros (canoa individual) na canoagem velocidade. Ele participou da segunda bateria das eliminat\u00f3rias, que classificava os dois primeiros barcos direto para a semifinal.","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/08\/07\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual","og_site_name":"Litoral SP","article_published_time":"2024-08-07T16:30:20+00:00","og_image":[{"width":878,"height":485,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/08\/vddfvdvc.jpg?v=1723044722","type":"image\/jpeg"}],"author":"Gustavo Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gustavo Silva","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/08\/07\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/08\/07\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual"},"author":{"name":"Gustavo Silva","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e"},"headline":"Isaquias Queiroz avan\u00e7a direto \u00e0 semifinal da canoa individual","datePublished":"2024-08-07T16:30:20+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/08\/07\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual"},"wordCount":316,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/08\/07\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/08\/vddfvdvc.jpg?v=1723044722","keywords":["2024","OLIMP\u00cdADAS","PARIS"],"articleSection":["Esporte","Olimp\u00edadas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/08\/07\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/08\/07\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/08\/07\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual","name":"Isaquias Queiroz avan\u00e7a direto \u00e0 semifinal da canoa individual - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/08\/07\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/08\/07\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/08\/vddfvdvc.jpg?v=1723044722","datePublished":"2024-08-07T16:30:20+00:00","description":"Campe\u00e3o ol\u00edmpico nos Jogos de T\u00f3quio, em 2021, o baiano Isaquias Queiroz iniciou nesta quarta-feira (7) a defesa do t\u00edtulo na prova da C1 1000 metros (canoa individual) na canoagem velocidade. Ele participou da segunda bateria das eliminat\u00f3rias, que classificava os dois primeiros barcos direto para a semifinal.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/08\/07\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2024\/08\/07\/isaquias-queiroz-avanca-direto-a-semifinal-da-canoa-individual#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/08\/vddfvdvc.jpg?v=1723044722","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2024\/08\/vddfvdvc.jpg?v=1723044722","width":878,"height":485},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e","name":"Gustavo Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","caption":"Gustavo Silva"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/gustavosilva"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/117530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=117530"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/117530\/revisions"}],"predecessor-version":[{"id":117534,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/117530\/revisions\/117534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/117531"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=117530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=117530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=117530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}