{"id":120967,"date":"2025-11-05T10:43:40","date_gmt":"2025-11-05T13:43:40","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/2025\/11\/05\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial"},"modified":"2025-11-05T10:48:31","modified_gmt":"2025-11-05T13:48:31","slug":"tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2025\/11\/05\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial","title":{"rendered":"TSE aprova Partido Miss\u00e3o, nova sigla do MBL que mira a disputa presidencial"},"content":{"rendered":"<p>O Tribunal Superior Eleitoral (TSE) aprovou por unanimidade, nesta segunda-feira (4), o registro do Partido Miss\u00e3o, legenda ligada ao Movimento Brasil Livre (MBL). Com a decis\u00e3o, o Brasil passa a ter 30 partidos pol\u00edticos oficialmente registrados.<\/p>\n<p>Na defesa da cria\u00e7\u00e3o, o advogado Arthur Rollo destacou o car\u00e1ter nacional do movimento e as mais de 590 mil assinaturas coletadas em todo o pa\u00eds. O relator do processo votou pelo deferimento, mas determinou ajustes no estatuto da sigla em at\u00e9 90 dias, para adequa\u00e7\u00e3o \u00e0 legisla\u00e7\u00e3o.<\/p>\n<p>\u00c0 CNN Brasil, o deputado federal Kim Kataguiri (Uni\u00e3o-SP), um dos l\u00edderes do MBL, afirmou que o novo partido pretende lan\u00e7ar pr\u00e9-candidatos \u00e0 Presid\u00eancia da Rep\u00fablica e aos governos de S\u00e3o Paulo e do Rio de Janeiro nas pr\u00f3ximas elei\u00e7\u00f5es.<\/p>\n<p>LEIA MAIS<\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2025\/11\/05\/aviao-de-carga-da-ups-cai-em-louisville-autoridades-confirmam-mortos-e-feridos\">Avi\u00e3o de carga da UPS cai em Louisville; autoridades confirmam mortos e feridos<\/a><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2025\/11\/04\/cyan-resort-em-itupeva-anuncia-novas-vagas-de-emprego-em-diversas-areas\">Cyan Resort, em Itupeva, anuncia novas vagas de emprego em diversas \u00e1reas<\/a><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2025\/11\/04\/vagas-home-office-com-salario-de-ate-r-6-mil-confira-as-oportunidades-abertas\">Vagas Home Office com sal\u00e1rio de at\u00e9 R$ 6 mil; confira as oportunidades abertas<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal Superior Eleitoral (TSE) aprovou por unanimidade, nesta segunda-feira (4), o registro do Partido Miss\u00e3o, legenda ligada ao Movimento Brasil Livre (MBL). Com a decis\u00e3o, o Brasil passa a ter 30 partidos pol\u00edticos oficialmente registrados. Na defesa da cria\u00e7\u00e3o, o advogado Arthur Rollo destacou o car\u00e1ter nacional do movimento e as mais de 590 &hellip;<\/p>\n","protected":false},"author":30,"featured_media":92159,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[69437,60765,69438,110],"class_list":["post-120967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-disputa-presidencial","tag-governos","tag-partido-missao-mbl","tag-tse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TSE aprova Partido Miss\u00e3o, nova sigla do MBL que mira a disputa presidencial - Litoral SP<\/title>\n<meta name=\"description\" content=\"O Tribunal Superior Eleitoral (TSE) aprovou por unanimidade, o registro do Partido Miss\u00e3o, legenda ligada ao Movimento Brasil Livre (MBL).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2025\/11\/05\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TSE aprova Partido Miss\u00e3o, nova sigla do MBL que mira a disputa presidencial - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"O Tribunal Superior Eleitoral (TSE) aprovou por unanimidade, o registro do Partido Miss\u00e3o, legenda ligada ao Movimento Brasil Livre (MBL).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2025\/11\/05\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-05T13:43:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-05T13:48:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/09\/TSE.jpg?v=1664278629\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carina Reifonas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carina Reifonas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2025\\\/11\\\/05\\\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2025\\\/11\\\/05\\\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial\"},\"author\":{\"name\":\"Carina Reifonas\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/1f84d6e94e6a62d2d81199d7503e9e90\"},\"headline\":\"TSE aprova Partido Miss\u00e3o, nova sigla do MBL que mira a disputa presidencial\",\"datePublished\":\"2025-11-05T13:43:40+00:00\",\"dateModified\":\"2025-11-05T13:48:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2025\\\/11\\\/05\\\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial\"},\"wordCount\":192,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2025\\\/11\\\/05\\\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/09\\\/TSE.jpg?v=1664278629\",\"keywords\":[\"disputa presidencial\",\"governos\",\"Partido Miss\u00e3o (MBL)\",\"TSE\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2025\\\/11\\\/05\\\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2025\\\/11\\\/05\\\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2025\\\/11\\\/05\\\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial\",\"name\":\"TSE aprova Partido Miss\u00e3o, nova sigla do MBL que mira a disputa presidencial - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2025\\\/11\\\/05\\\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2025\\\/11\\\/05\\\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/09\\\/TSE.jpg?v=1664278629\",\"datePublished\":\"2025-11-05T13:43:40+00:00\",\"dateModified\":\"2025-11-05T13:48:31+00:00\",\"description\":\"O Tribunal Superior Eleitoral (TSE) aprovou por unanimidade, o registro do Partido Miss\u00e3o, legenda ligada ao Movimento Brasil Livre (MBL).\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2025\\\/11\\\/05\\\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2025\\\/11\\\/05\\\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/09\\\/TSE.jpg?v=1664278629\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/09\\\/TSE.jpg?v=1664278629\",\"width\":1170,\"height\":700,\"caption\":\"Edif\u00edcio sede do Tribunal Superior Eleitoral (TSE). Cr\u00e9ditos: Ag\u00eancia Brasil\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/1f84d6e94e6a62d2d81199d7503e9e90\",\"name\":\"Carina Reifonas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"caption\":\"Carina Reifonas\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/carinareifonas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TSE aprova Partido Miss\u00e3o, nova sigla do MBL que mira a disputa presidencial - Litoral SP","description":"O Tribunal Superior Eleitoral (TSE) aprovou por unanimidade, o registro do Partido Miss\u00e3o, legenda ligada ao Movimento Brasil Livre (MBL).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2025\/11\/05\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial","og_locale":"pt_BR","og_type":"article","og_title":"TSE aprova Partido Miss\u00e3o, nova sigla do MBL que mira a disputa presidencial - Litoral SP","og_description":"O Tribunal Superior Eleitoral (TSE) aprovou por unanimidade, o registro do Partido Miss\u00e3o, legenda ligada ao Movimento Brasil Livre (MBL).","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2025\/11\/05\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial","og_site_name":"Litoral SP","article_published_time":"2025-11-05T13:43:40+00:00","article_modified_time":"2025-11-05T13:48:31+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/09\/TSE.jpg?v=1664278629","type":"image\/jpeg"}],"author":"Carina Reifonas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carina Reifonas","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2025\/11\/05\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2025\/11\/05\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial"},"author":{"name":"Carina Reifonas","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/1f84d6e94e6a62d2d81199d7503e9e90"},"headline":"TSE aprova Partido Miss\u00e3o, nova sigla do MBL que mira a disputa presidencial","datePublished":"2025-11-05T13:43:40+00:00","dateModified":"2025-11-05T13:48:31+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2025\/11\/05\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial"},"wordCount":192,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2025\/11\/05\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/09\/TSE.jpg?v=1664278629","keywords":["disputa presidencial","governos","Partido Miss\u00e3o (MBL)","TSE"],"articleSection":["Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2025\/11\/05\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2025\/11\/05\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2025\/11\/05\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial","name":"TSE aprova Partido Miss\u00e3o, nova sigla do MBL que mira a disputa presidencial - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2025\/11\/05\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2025\/11\/05\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/09\/TSE.jpg?v=1664278629","datePublished":"2025-11-05T13:43:40+00:00","dateModified":"2025-11-05T13:48:31+00:00","description":"O Tribunal Superior Eleitoral (TSE) aprovou por unanimidade, o registro do Partido Miss\u00e3o, legenda ligada ao Movimento Brasil Livre (MBL).","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2025\/11\/05\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2025\/11\/05\/tse-aprova-partido-missao-nova-sigla-do-mbl-que-mira-a-disputa-presidencial#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/09\/TSE.jpg?v=1664278629","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/09\/TSE.jpg?v=1664278629","width":1170,"height":700,"caption":"Edif\u00edcio sede do Tribunal Superior Eleitoral (TSE). Cr\u00e9ditos: Ag\u00eancia Brasil"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/1f84d6e94e6a62d2d81199d7503e9e90","name":"Carina Reifonas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","caption":"Carina Reifonas"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/carinareifonas"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/120967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=120967"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/120967\/revisions"}],"predecessor-version":[{"id":120968,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/120967\/revisions\/120968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/92159"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=120967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=120967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=120967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}