{"id":17352,"date":"2021-10-28T15:51:00","date_gmt":"2021-10-28T18:51:00","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/?p=17352"},"modified":"2021-10-28T15:51:36","modified_gmt":"2021-10-28T18:51:36","slug":"o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/10\/28\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro","title":{"rendered":"O passageiro que tiver com sintomas de Covid-19 vai ficar isolado na cabine do cruzeiro"},"content":{"rendered":"<p>Depois da permiss\u00e3o da realiza\u00e7\u00e3o da temporada de <strong>cruzeiros mar\u00edtimos<\/strong> nos mares brasileiros, uma nova\u00a0 portaria foi publicada no Di\u00e1rio Oficial da Uni\u00e3o nesta quinta-feira (28). O <a href=\"https:\/\/www.gov.br\/saude\/pt-br\">ministro substituto da Sa\u00fade<\/a>, Rodrigo Cruz fez a publica\u00e7\u00e3o.<\/p>\n<p>&#8220;Est\u00e1 autorizada a opera\u00e7\u00e3o de navios de cruzeiro a partir de 1\u00ba de novembro de 2021, tendo em vista o cen\u00e1rio atual de pandemia de Covid-19&#8221;, informa a publica\u00e7\u00e3o. Mas no texto s\u00e3o dadas todas as condi\u00e7\u00f5es necess\u00e1rias para o cumprimento do isolamento e quarentena das embarca\u00e7\u00f5es de cruzeiros para viajantes e funcion\u00e1rios dos navios.<\/p>\n<p>O passageiro que apresentar sinais e sintomas de Covid-19 devem procurar a equipe m\u00e9dica e serem isolados. A determina\u00e7\u00e3o deve ser cumprida at\u00e9 que o teste seja feito. Quem apresentar positivo, detect\u00e1vel e reagente vai ter que ficar isolado numa cabine reservada para quem tem coronav\u00edrus.<\/p>\n<p>Ainda segundo a portaria, o isolamento ser\u00e1 de 10 duas para o quadro de s\u00edndrome gripal leve ou moderado. Mas para quem apresentar s\u00edndromes aguda grave ou cr\u00edtica, a\u00ed ter\u00e1 de cumprir o isolamento de 20 dias.<\/p>\n<p>No entanto, o viajante que der negativo em um novo teste vai permanecer em isolamento na cabine at\u00e9 a remiss\u00e3o dos sintomas. Um novo teste ser\u00e1 feito. &#8220;Atos normativos espec\u00edficos de vigil\u00e2ncia sanit\u00e1ria complementares a esta portaria poder\u00e3o ser editados pela Anvisa&#8221;.<\/p>\n<p><strong>LEIA TAMB\u00c9M<\/strong><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/10\/14\/protocolos-sanitarios-para-a-temporada-de-cruzeiros-sao-discutidas-pela-anvisa\">Protocolos sanit\u00e1rios para a temporada de cruzeiros s\u00e3o discutidas pela Anvisa<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depois da permiss\u00e3o da realiza\u00e7\u00e3o da temporada de cruzeiros mar\u00edtimos nos mares brasileiros, uma nova\u00a0 portaria foi publicada no Di\u00e1rio Oficial da Uni\u00e3o nesta quinta-feira (28). O ministro substituto da Sa\u00fade, Rodrigo Cruz fez a publica\u00e7\u00e3o. &#8220;Est\u00e1 autorizada a opera\u00e7\u00e3o de navios de cruzeiro a partir de 1\u00ba de novembro de 2021, tendo em vista &hellip;<\/p>\n","protected":false},"author":6,"featured_media":17353,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18537,180,775],"tags":[38853,1810,74,39780,986],"class_list":["post-17352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-porto","category-santos","category-turismo","tag-diario-oficial-da-uniao","tag-ministerio-da-saude","tag-porto-de-santos","tag-regras-contra-a-covid","tag-santos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O passageiro que tiver com sintomas de Covid-19 vai ficar isolado na cabine do cruzeiro - Litoral SP<\/title>\n<meta name=\"description\" content=\"Est\u00e1 autorizada a opera\u00e7\u00e3o de navios de cruzeiro a partir de 1\u00ba de novembro de 2021, tendo em vista o cen\u00e1rio atual de pandemia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/10\/28\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O passageiro que tiver com sintomas de Covid-19 vai ficar isolado na cabine do cruzeiro - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"Est\u00e1 autorizada a opera\u00e7\u00e3o de navios de cruzeiro a partir de 1\u00ba de novembro de 2021, tendo em vista o cen\u00e1rio atual de pandemia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/10\/28\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-28T18:51:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-28T18:51:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/10\/image-9-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leonardo Francisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonardo Francisco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/10\\\/28\\\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/10\\\/28\\\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro\"},\"author\":{\"name\":\"Leonardo Francisco\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/0f0b8a5bdafefe82841e07ae8d81ecb3\"},\"headline\":\"O passageiro que tiver com sintomas de Covid-19 vai ficar isolado na cabine do cruzeiro\",\"datePublished\":\"2021-10-28T18:51:00+00:00\",\"dateModified\":\"2021-10-28T18:51:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/10\\\/28\\\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro\"},\"wordCount\":269,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/10\\\/28\\\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/10\\\/image-9-9.jpg\",\"keywords\":[\"DI\u00c1RIO OFICIAL DA UNI\u00c3O\",\"Minist\u00e9rio da Sa\u00fade\",\"porto de santos\",\"REGRAS CONTRA A COVID\",\"Santos\"],\"articleSection\":[\"Porto\",\"Santos\",\"Turismo\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/10\\\/28\\\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/10\\\/28\\\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/10\\\/28\\\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro\",\"name\":\"O passageiro que tiver com sintomas de Covid-19 vai ficar isolado na cabine do cruzeiro - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/10\\\/28\\\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/10\\\/28\\\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/10\\\/image-9-9.jpg\",\"datePublished\":\"2021-10-28T18:51:00+00:00\",\"dateModified\":\"2021-10-28T18:51:36+00:00\",\"description\":\"Est\u00e1 autorizada a opera\u00e7\u00e3o de navios de cruzeiro a partir de 1\u00ba de novembro de 2021, tendo em vista o cen\u00e1rio atual de pandemia\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/10\\\/28\\\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/10\\\/28\\\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/10\\\/image-9-9.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/10\\\/image-9-9.jpg\",\"width\":900,\"height\":600,\"caption\":\"Cr\u00e9ditos: Divulga\u00e7\u00e3o\\\/Costa\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/0f0b8a5bdafefe82841e07ae8d81ecb3\",\"name\":\"Leonardo Francisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"caption\":\"Leonardo Francisco\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/leonardo-francisco\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O passageiro que tiver com sintomas de Covid-19 vai ficar isolado na cabine do cruzeiro - Litoral SP","description":"Est\u00e1 autorizada a opera\u00e7\u00e3o de navios de cruzeiro a partir de 1\u00ba de novembro de 2021, tendo em vista o cen\u00e1rio atual de pandemia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/10\/28\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro","og_locale":"pt_BR","og_type":"article","og_title":"O passageiro que tiver com sintomas de Covid-19 vai ficar isolado na cabine do cruzeiro - Litoral SP","og_description":"Est\u00e1 autorizada a opera\u00e7\u00e3o de navios de cruzeiro a partir de 1\u00ba de novembro de 2021, tendo em vista o cen\u00e1rio atual de pandemia","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/10\/28\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro","og_site_name":"Litoral SP","article_published_time":"2021-10-28T18:51:00+00:00","article_modified_time":"2021-10-28T18:51:36+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/10\/image-9-9.jpg","type":"image\/jpeg"}],"author":"Leonardo Francisco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Leonardo Francisco","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/10\/28\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/10\/28\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro"},"author":{"name":"Leonardo Francisco","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/0f0b8a5bdafefe82841e07ae8d81ecb3"},"headline":"O passageiro que tiver com sintomas de Covid-19 vai ficar isolado na cabine do cruzeiro","datePublished":"2021-10-28T18:51:00+00:00","dateModified":"2021-10-28T18:51:36+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/10\/28\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro"},"wordCount":269,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/10\/28\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/10\/image-9-9.jpg","keywords":["DI\u00c1RIO OFICIAL DA UNI\u00c3O","Minist\u00e9rio da Sa\u00fade","porto de santos","REGRAS CONTRA A COVID","Santos"],"articleSection":["Porto","Santos","Turismo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/10\/28\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/10\/28\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/10\/28\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro","name":"O passageiro que tiver com sintomas de Covid-19 vai ficar isolado na cabine do cruzeiro - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/10\/28\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/10\/28\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/10\/image-9-9.jpg","datePublished":"2021-10-28T18:51:00+00:00","dateModified":"2021-10-28T18:51:36+00:00","description":"Est\u00e1 autorizada a opera\u00e7\u00e3o de navios de cruzeiro a partir de 1\u00ba de novembro de 2021, tendo em vista o cen\u00e1rio atual de pandemia","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/10\/28\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/10\/28\/o-passageiro-que-tiver-com-sintomas-de-covid-19-vai-ficar-isolado-na-cabine-do-cruzeiro#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/10\/image-9-9.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/10\/image-9-9.jpg","width":900,"height":600,"caption":"Cr\u00e9ditos: Divulga\u00e7\u00e3o\/Costa"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/0f0b8a5bdafefe82841e07ae8d81ecb3","name":"Leonardo Francisco","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","caption":"Leonardo Francisco"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/leonardo-francisco"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/17352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=17352"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/17352\/revisions"}],"predecessor-version":[{"id":17354,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/17352\/revisions\/17354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/17353"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=17352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=17352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=17352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}