{"id":1986,"date":"2020-12-28T17:47:38","date_gmt":"2020-12-28T20:47:38","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/28\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan\/"},"modified":"2020-12-28T17:51:28","modified_gmt":"2020-12-28T20:51:28","slug":"china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/28\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan","title":{"rendered":"China condena jornalista a 4 anos de pris\u00e3o por relatar v\u00edrus em Wuhan"},"content":{"rendered":"<p>Um tribunal chin\u00eas imp\u00f4s hoje (28) uma pena de quatro anos de pris\u00e3o a uma jornalista que noticiou da cidade de <a href=\"https:\/\/pt.wikipedia.org\/wiki\/Wuhan\">Wuhan,<\/a> no auge do surto de coronav\u00edrus do ano passado, acusando-a de &#8220;induzir brigas e provocar confus\u00e3o&#8221;, disse o advogado da condenada.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1397450&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1397450&amp;o=node\" \/><\/p>\n<p>Zhang Zhan, de 37 anos, a primeira jornalista cidad\u00e3 que se sabe ter sido julgada, \u00e9 parte de um punhado de pessoas cujos relatos em primeira m\u00e3o de hospitais lotados e ruas vazias pintaram um quadro mais sombrio do epicentro da pandemia do que a narrativa oficial.<\/p>\n<p>&#8220;N\u00e3o entendo. Tudo que ela fez foi dizer algumas palavras verdadeiras, e por isso pegou quatro anos&#8221;, disse Shao Wenxia, a m\u00e3e de Zhang, que acompanhou o julgamento com o marido.<\/p>\n<p>O advogado de Zhang, Ren Quanniu, disse \u00e0 ag\u00eancia de not\u00edcias Reuters: &#8220;Provavelmente apelaremos&#8221;.<\/p>\n<p>&#8220;A senhorita Zhang acredita que est\u00e1 sendo perseguida por exercitar sua liberdade de express\u00e3o&#8221;, havia dito ele antes do julgamento.<\/p>\n<h2>Governo tenta minimizar<\/h2>\n<p>Cr\u00edticos dizem que a China fez com que o julgamento de Zhang acontecesse durante as festas de fim de ano ocidentais deliberadamente para minimizar a aten\u00e7\u00e3o e a vigil\u00e2ncia do Ocidente.<\/p>\n<p>&#8220;A sele\u00e7\u00e3o do per\u00edodo sonolento entre o Natal e o Ano Novo sugere que at\u00e9 Pequim est\u00e1 constrangida por condenar a jornalista cidad\u00e3 Zhang Zhan a quatro anos de pris\u00e3o. A jornalista registrou a vers\u00e3o sem censura do surto de coronav\u00edrus de Wuhan&#8221;, tuitou Kenneth Roth, diretor-executivo da entidade Human Rights Watch, sediada em Genebra.<\/p>\n<p>As cr\u00edticas \u00e0 maneira como a China lidou inicialmente com a crise foram censuradas. Mas as pessoas\u00a0 contaram o que estava acontecendo, como m\u00e9dicos, foram advertidas. Mesmo assim, a m\u00eddia estatal creditou o sucesso do pa\u00eds na conten\u00e7\u00e3o do v\u00edrus \u00e0 lideran\u00e7a do presidente Xi Jinping.<\/p>\n<div class=\"dnd-widget-wrapper context-cheio_8colunas type-image\">\n<div class=\"dnd-atom-rendered\">\n<div class=\"shadow overflow-hidden rounded-lg d-block zoom-on-hover-sm shadow-hover w-100\">O v\u00edrus se disseminou em todo o mundo, j\u00e1 infectou mais de 80 milh\u00f5es de pessoas e matou mais de 1,76 milh\u00e3o. Mas n\u00e3o \u00e9 s\u00f3, paralisou as viagens a\u00e9reas, enquanto na\u00e7\u00f5es erguiam barreiras de prote\u00e7\u00e3o que transtornaram ind\u00fastrias e meios de subsist\u00eancia.<\/div>\n<\/div>\n<\/div>\n<p>Em Xangai, a pol\u00edcia refor\u00e7ou a seguran\u00e7a diante do tribunal onde o julgamento come\u00e7ou sete meses ap\u00f3s a deten\u00e7\u00e3o de Zhang, mas alguns apoiadores n\u00e3o se intimidaram.<\/p>\n<p>Jornalistas estrangeiros foram impedidos de ingressar no tribunal &#8220;devido \u00e0 epidemia&#8221;, disseram autoridades de seguran\u00e7a da corte. (agenciabrasil)<\/p>\n<p><strong>LEIA TAMB\u00c9M<\/strong><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2020\/12\/28\/raio-em-pista-interdita-aeroporto-de-viracopos-por-uma-hora\/\">Raio em pista interdita Aeroporto de Viracopos por uma hora<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um tribunal chin\u00eas imp\u00f4s hoje (28) uma pena de quatro anos de pris\u00e3o a uma jornalista que noticiou da cidade de Wuhan, no auge do surto de coronav\u00edrus do ano passado, acusando-a de &#8220;induzir brigas e provocar confus\u00e3o&#8221;, disse o advogado da condenada. Zhang Zhan, de 37 anos, a primeira jornalista cidad\u00e3 que se sabe &hellip;<\/p>\n","protected":false},"author":5,"featured_media":1987,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[6454,6455,6456,6457,6458],"class_list":["post-1986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-china-condena","tag-china-condena-jornalistas","tag-denunciaram-covid-19","tag-jornalistas-condenados","tag-wuhan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>China condena jornalista a 4 anos de pris\u00e3o por relatar v\u00edrus em Wuhan - Litoral SP<\/title>\n<meta name=\"description\" content=\"Um tribunal chin\u00eas imp\u00f4s hoje (28) uma pena de quatro anos de pris\u00e3o a uma jornalista que noticiou da cidade de Wuhan, no auge do surto de coronav\u00edrus\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/28\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"China condena jornalista a 4 anos de pris\u00e3o por relatar v\u00edrus em Wuhan - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"Um tribunal chin\u00eas imp\u00f4s hoje (28) uma pena de quatro anos de pris\u00e3o a uma jornalista que noticiou da cidade de Wuhan, no auge do surto de coronav\u00edrus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/28\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-28T20:47:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-28T20:51:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/12\/zhang_zhan_jornalista_chinamcajr_2812203594.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Patr\u00edcia Prado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patr\u00edcia Prado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/28\\\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/28\\\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan\"},\"author\":{\"name\":\"Patr\u00edcia Prado\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/e1b0bd8c2637e2c1b6ddcbc2c33b116f\"},\"headline\":\"China condena jornalista a 4 anos de pris\u00e3o por relatar v\u00edrus em Wuhan\",\"datePublished\":\"2020-12-28T20:47:38+00:00\",\"dateModified\":\"2020-12-28T20:51:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/28\\\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan\"},\"wordCount\":438,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/28\\\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/12\\\/zhang_zhan_jornalista_chinamcajr_2812203594.jpg\",\"keywords\":[\"CHINA CONDENA\",\"CHINA CONDENA JORNALISTAS\",\"DENUNCIARAM COVID-19\",\"JORNALISTAS CONDENADOS\",\"WUHAN\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/28\\\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/28\\\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/28\\\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan\",\"name\":\"China condena jornalista a 4 anos de pris\u00e3o por relatar v\u00edrus em Wuhan - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/28\\\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/28\\\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/12\\\/zhang_zhan_jornalista_chinamcajr_2812203594.jpg\",\"datePublished\":\"2020-12-28T20:47:38+00:00\",\"dateModified\":\"2020-12-28T20:51:28+00:00\",\"description\":\"Um tribunal chin\u00eas imp\u00f4s hoje (28) uma pena de quatro anos de pris\u00e3o a uma jornalista que noticiou da cidade de Wuhan, no auge do surto de coronav\u00edrus\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/28\\\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/28\\\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/12\\\/zhang_zhan_jornalista_chinamcajr_2812203594.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/12\\\/zhang_zhan_jornalista_chinamcajr_2812203594.jpg\",\"width\":1170,\"height\":700,\"caption\":\"Citizen-journalist Zhang Zhan is seen in Wuhan, Hubei province, China in this handout picture taken on May 3, 2020. Handout via REUTERS ATTENTION EDITORS - THIS IMAGE WAS PROVIDED BY A THIRD PARTY. NO RESALES. NO ARCHIVES.\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/e1b0bd8c2637e2c1b6ddcbc2c33b116f\",\"name\":\"Patr\u00edcia Prado\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92e358bef22cfcec15e054ae4d9fee04dadf0c772dc4a17b382b8a34a15354c2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92e358bef22cfcec15e054ae4d9fee04dadf0c772dc4a17b382b8a34a15354c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92e358bef22cfcec15e054ae4d9fee04dadf0c772dc4a17b382b8a34a15354c2?s=96&d=mm&r=g\",\"caption\":\"Patr\u00edcia Prado\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/patricia-prado\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"China condena jornalista a 4 anos de pris\u00e3o por relatar v\u00edrus em Wuhan - Litoral SP","description":"Um tribunal chin\u00eas imp\u00f4s hoje (28) uma pena de quatro anos de pris\u00e3o a uma jornalista que noticiou da cidade de Wuhan, no auge do surto de coronav\u00edrus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/28\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan","og_locale":"pt_BR","og_type":"article","og_title":"China condena jornalista a 4 anos de pris\u00e3o por relatar v\u00edrus em Wuhan - Litoral SP","og_description":"Um tribunal chin\u00eas imp\u00f4s hoje (28) uma pena de quatro anos de pris\u00e3o a uma jornalista que noticiou da cidade de Wuhan, no auge do surto de coronav\u00edrus","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/28\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan","og_site_name":"Litoral SP","article_published_time":"2020-12-28T20:47:38+00:00","article_modified_time":"2020-12-28T20:51:28+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/12\/zhang_zhan_jornalista_chinamcajr_2812203594.jpg","type":"image\/jpeg"}],"author":"Patr\u00edcia Prado","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Patr\u00edcia Prado","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/28\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/28\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan"},"author":{"name":"Patr\u00edcia Prado","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/e1b0bd8c2637e2c1b6ddcbc2c33b116f"},"headline":"China condena jornalista a 4 anos de pris\u00e3o por relatar v\u00edrus em Wuhan","datePublished":"2020-12-28T20:47:38+00:00","dateModified":"2020-12-28T20:51:28+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/28\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan"},"wordCount":438,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/28\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/12\/zhang_zhan_jornalista_chinamcajr_2812203594.jpg","keywords":["CHINA CONDENA","CHINA CONDENA JORNALISTAS","DENUNCIARAM COVID-19","JORNALISTAS CONDENADOS","WUHAN"],"articleSection":["Mundo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/28\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/28\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/28\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan","name":"China condena jornalista a 4 anos de pris\u00e3o por relatar v\u00edrus em Wuhan - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/28\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/28\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/12\/zhang_zhan_jornalista_chinamcajr_2812203594.jpg","datePublished":"2020-12-28T20:47:38+00:00","dateModified":"2020-12-28T20:51:28+00:00","description":"Um tribunal chin\u00eas imp\u00f4s hoje (28) uma pena de quatro anos de pris\u00e3o a uma jornalista que noticiou da cidade de Wuhan, no auge do surto de coronav\u00edrus","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/28\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/28\/china-condena-jornalista-a-4-anos-de-prisao-por-relatar-virus-em-wuhan#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/12\/zhang_zhan_jornalista_chinamcajr_2812203594.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/12\/zhang_zhan_jornalista_chinamcajr_2812203594.jpg","width":1170,"height":700,"caption":"Citizen-journalist Zhang Zhan is seen in Wuhan, Hubei province, China in this handout picture taken on May 3, 2020. Handout via REUTERS ATTENTION EDITORS - THIS IMAGE WAS PROVIDED BY A THIRD PARTY. NO RESALES. NO ARCHIVES."},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/e1b0bd8c2637e2c1b6ddcbc2c33b116f","name":"Patr\u00edcia Prado","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/92e358bef22cfcec15e054ae4d9fee04dadf0c772dc4a17b382b8a34a15354c2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/92e358bef22cfcec15e054ae4d9fee04dadf0c772dc4a17b382b8a34a15354c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/92e358bef22cfcec15e054ae4d9fee04dadf0c772dc4a17b382b8a34a15354c2?s=96&d=mm&r=g","caption":"Patr\u00edcia Prado"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/patricia-prado"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/1986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=1986"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/1986\/revisions"}],"predecessor-version":[{"id":1988,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/1986\/revisions\/1988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/1987"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=1986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=1986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=1986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}