{"id":22472,"date":"2022-01-29T18:13:54","date_gmt":"2022-01-29T21:13:54","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/01\/29\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo"},"modified":"2022-01-29T18:16:29","modified_gmt":"2022-01-29T21:16:29","slug":"com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/01\/29\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo","title":{"rendered":"Com reservas, Palmeiras arranca empate contra o S\u00e3o Bernardo"},"content":{"rendered":"<p>O <strong>Palmeiras<\/strong> segue invicto no <a href=\"https:\/\/futebolpaulista.com.br\/Home\/\">Campeonoato Paulista<\/a>, mas desta vez sem os 100% de aproveitamento. No ABC Paulista, o Verd\u00e3o encarou o <strong>S\u00e3o Bernardo<\/strong>, neste s\u00e1bado (29) e escapou de uma derrota garantindo o empate por 1 a 1. As duas equipes lideram seus respectivos grupos no Paulist\u00e3o.<\/p>\n<p>O t\u00e9cnico Abel Ferreira optou por escalar uma equipe praticamente reserva, com a inten\u00e7\u00e3o de dar rod\u00e1gem e observar quem ir\u00e1 integrar o elenco que jogar\u00e1 o Mundial de Clubes, em fevereiro. Apenas Piquerez e Gustavo Scarpa jogaram, mas somente no segundo tempo.<\/p>\n<p>No primeiro tempo, as duas equipes fizeram uma partida moviimentada e bom boas chances. O Palmeiras poderia abrir o placar aos 19 minutos, quando Wesley sofrer p\u00eanalti. Mas Rafael Navarro parou em Alex Alves na cobran\u00e7a. O Bern\u00f4 ent\u00e3o se animou, passou a dominar e aos 38 chegou ao gol. Mateus Dav\u00f3 ganhou de Renan e rolou para Silvinho abrir o placar.<\/p>\n<p>Veio o segundo tempo e o Palmeiras veio com uma mudan\u00e7a. Patrick de Paula entrou no lugar de Gabriel Menino e quase empatou em uma finaliza\u00e7\u00e7\u00e3o de fora da \u00e1rea. Aos 19 minutos Rafael Navarro caiu na \u00e1rea e ap\u00f3s o \u00e1rbitro consultar o VAR, o p\u00eanalti foi marcado. Desta vez Wesley cobrou e empatou o jogo em S\u00e3o Bernardo do Campo.<\/p>\n<p>Da\u00ed em diante o jogo seguiu movimentado, mas sem maiores chances claras de gol. O empate acabou sendo o resultado mais justo para as duas equipes.<\/p>\n<h3>Futuro<\/h3>\n<p>O resultado mant\u00e9m o Verd\u00e3o na lideran\u00e7a do Grupo C, agora com sete pontos. O pr\u00f3ximo jogo do Palmeiras ser\u00e1 na ter\u00e7a-feira (1\u00ba de fevereiro), contra o \u00c1gua Santa, no Allianz Parque, um dia antes do embarque para Abu Dhabi.<\/p>\n<p>J\u00e1 o S\u00e3o Bernardo soma quatro pontos e lidera o Grupo B com quatro pontos. Na pr\u00f3xima rodada, o compromisso ser\u00e1 contra o Santo Andr\u00e9, na quarta-feira (2 de fevereiro(, fora de casa.<\/p>\n<p><strong>LEIA TAMB\u00c9M<\/strong><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2022\/01\/29\/tom-brady-da-adeus-a-nfl-diz-imprensa-americana\">Tom Brady d\u00e1 adeus \u00e0 NFL, diz imprensa americana<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Palmeiras segue invicto no Campeonoato Paulista, mas desta vez sem os 100% de aproveitamento. No ABC Paulista, o Verd\u00e3o encarou o S\u00e3o Bernardo, neste s\u00e1bado (29) e escapou de uma derrota garantindo o empate por 1 a 1. As duas equipes lideram seus respectivos grupos no Paulist\u00e3o. O t\u00e9cnico Abel Ferreira optou por escalar &hellip;<\/p>\n","protected":false},"author":6,"featured_media":22473,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[3712,48881,1416,40947,40948],"class_list":["post-22472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte","tag-campeonato-paulista","tag-estadio-primeiro-de-maio","tag-palmeiras","tag-paulistao-2022","tag-sao-bernardo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Com reservas, Palmeiras arranca empate contra o S\u00e3o Bernardo - Litoral SP<\/title>\n<meta name=\"description\" content=\"O Palmeiras segue invicto no Campeonoato Paulista, mas desta vez sem os 100% de aproveitamento. No ABC Paulista, o Verd\u00e3o encarou o S\u00e3o Bernardo,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/01\/29\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Com reservas, Palmeiras arranca empate contra o S\u00e3o Bernardo - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"O Palmeiras segue invicto no Campeonoato Paulista, mas desta vez sem os 100% de aproveitamento. No ABC Paulista, o Verd\u00e3o encarou o S\u00e3o Bernardo,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/01\/29\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-29T21:13:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-29T21:16:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/01\/agif22012917314582.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leonardo Francisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonardo Francisco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/01\\\/29\\\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/01\\\/29\\\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo\"},\"author\":{\"name\":\"Leonardo Francisco\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/0f0b8a5bdafefe82841e07ae8d81ecb3\"},\"headline\":\"Com reservas, Palmeiras arranca empate contra o S\u00e3o Bernardo\",\"datePublished\":\"2022-01-29T21:13:54+00:00\",\"dateModified\":\"2022-01-29T21:16:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/01\\\/29\\\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo\"},\"wordCount\":349,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/01\\\/29\\\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/01\\\/agif22012917314582.jpg\",\"keywords\":[\"CAMPEONATO PAULISTA\",\"EST\u00c1DIO PRIMEIRO DE MAIO\",\"Palmeiras\",\"PAULIST\u00c3O 2022\",\"S\u00c3O BERNARDO\"],\"articleSection\":[\"Esporte\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/01\\\/29\\\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/01\\\/29\\\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/01\\\/29\\\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo\",\"name\":\"Com reservas, Palmeiras arranca empate contra o S\u00e3o Bernardo - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/01\\\/29\\\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/01\\\/29\\\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/01\\\/agif22012917314582.jpg\",\"datePublished\":\"2022-01-29T21:13:54+00:00\",\"dateModified\":\"2022-01-29T21:16:29+00:00\",\"description\":\"O Palmeiras segue invicto no Campeonoato Paulista, mas desta vez sem os 100% de aproveitamento. No ABC Paulista, o Verd\u00e3o encarou o S\u00e3o Bernardo,\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/01\\\/29\\\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/01\\\/29\\\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/01\\\/agif22012917314582.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/01\\\/agif22012917314582.jpg\",\"width\":640,\"height\":360,\"caption\":\"As duas equipes permanecem invictas e l\u00edderes de seus grupos. Cr\u00e9ditos: AGIF.\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/0f0b8a5bdafefe82841e07ae8d81ecb3\",\"name\":\"Leonardo Francisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"caption\":\"Leonardo Francisco\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/leonardo-francisco\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Com reservas, Palmeiras arranca empate contra o S\u00e3o Bernardo - Litoral SP","description":"O Palmeiras segue invicto no Campeonoato Paulista, mas desta vez sem os 100% de aproveitamento. No ABC Paulista, o Verd\u00e3o encarou o S\u00e3o Bernardo,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/01\/29\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo","og_locale":"pt_BR","og_type":"article","og_title":"Com reservas, Palmeiras arranca empate contra o S\u00e3o Bernardo - Litoral SP","og_description":"O Palmeiras segue invicto no Campeonoato Paulista, mas desta vez sem os 100% de aproveitamento. No ABC Paulista, o Verd\u00e3o encarou o S\u00e3o Bernardo,","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/01\/29\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo","og_site_name":"Litoral SP","article_published_time":"2022-01-29T21:13:54+00:00","article_modified_time":"2022-01-29T21:16:29+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/01\/agif22012917314582.jpg","type":"image\/jpeg"}],"author":"Leonardo Francisco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Leonardo Francisco","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/01\/29\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/01\/29\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo"},"author":{"name":"Leonardo Francisco","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/0f0b8a5bdafefe82841e07ae8d81ecb3"},"headline":"Com reservas, Palmeiras arranca empate contra o S\u00e3o Bernardo","datePublished":"2022-01-29T21:13:54+00:00","dateModified":"2022-01-29T21:16:29+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/01\/29\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo"},"wordCount":349,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/01\/29\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/01\/agif22012917314582.jpg","keywords":["CAMPEONATO PAULISTA","EST\u00c1DIO PRIMEIRO DE MAIO","Palmeiras","PAULIST\u00c3O 2022","S\u00c3O BERNARDO"],"articleSection":["Esporte"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/01\/29\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/01\/29\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/01\/29\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo","name":"Com reservas, Palmeiras arranca empate contra o S\u00e3o Bernardo - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/01\/29\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/01\/29\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/01\/agif22012917314582.jpg","datePublished":"2022-01-29T21:13:54+00:00","dateModified":"2022-01-29T21:16:29+00:00","description":"O Palmeiras segue invicto no Campeonoato Paulista, mas desta vez sem os 100% de aproveitamento. No ABC Paulista, o Verd\u00e3o encarou o S\u00e3o Bernardo,","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/01\/29\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/01\/29\/com-reservas-palmeiras-arranca-empate-contra-o-sao-bernardo#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/01\/agif22012917314582.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/01\/agif22012917314582.jpg","width":640,"height":360,"caption":"As duas equipes permanecem invictas e l\u00edderes de seus grupos. Cr\u00e9ditos: AGIF."},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/0f0b8a5bdafefe82841e07ae8d81ecb3","name":"Leonardo Francisco","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","caption":"Leonardo Francisco"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/leonardo-francisco"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/22472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=22472"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/22472\/revisions"}],"predecessor-version":[{"id":22474,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/22472\/revisions\/22474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/22473"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=22472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=22472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=22472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}