{"id":23028,"date":"2022-02-08T16:16:10","date_gmt":"2022-02-08T19:16:10","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/?p=23028"},"modified":"2022-02-08T16:17:15","modified_gmt":"2022-02-08T19:17:15","slug":"corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/02\/08\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja","title":{"rendered":"Corpo de jovem que desapareceu no mar \u00e9 encontrado em praia de Guaruj\u00e1"},"content":{"rendered":"<p>Nesta ter\u00e7a-feira (8), foi <strong>encontrado o corpo de uma jovem de 14 anos<\/strong> que desapareceu no \u00faltimo domingo (6). Ela se afogou na Praia do Perequ\u00ea, no <a href=\"https:\/\/www.guaruja.sp.gov.br\/\">Guaruj\u00e1<\/a> e dois dias depois ela foi encontrada, mas sem vida.<\/p>\n<p>De acordo com o Grupamento de Bombeiros Mar\u00edtimos (GBMar), a menina foi arrastada pela correnteza e depois desapareceu no mar. Os bombeiros fizeram pelas buscas e nesta ter\u00e7a ela foi encontrada na Praia de Camburizinho. O namorado da jovem tamb\u00e9m estava sofrendo afogamento, mas ele foi salvo.<\/p>\n<p>A jovem morava em S\u00e3o Paulo e estava com parentes curtindo o final de semana, quando desapareceu no mar. Os parentes da v\u00edtima j\u00e1 fizeram o reconhecimento de corpo.<\/p>\n<p><strong>LEIA TAMB\u00c9M<\/strong><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/02\/07\/corpo-de-menino-que-desapareceu-em-rio-de-caraguatatuba-e-encontrado\">Corpo de menino que desapareceu em rio de Caraguatatuba \u00e9 encontrado<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta ter\u00e7a-feira (8), foi encontrado o corpo de uma jovem de 14 anos que desapareceu no \u00faltimo domingo (6). Ela se afogou na Praia do Perequ\u00ea, no Guaruj\u00e1 e dois dias depois ela foi encontrada, mas sem vida. De acordo com o Grupamento de Bombeiros Mar\u00edtimos (GBMar), a menina foi arrastada pela correnteza e depois &hellip;<\/p>\n","protected":false},"author":6,"featured_media":23029,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[187,10,45592],"tags":[10574,1006,30939,49657,19350],"class_list":["post-23028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guaruja","category-policia","category-praia","tag-grupamento-de-bombeiros-maritimos","tag-guaruja","tag-jovem-desaparecida","tag-praia-do-camburizinho","tag-praia-do-pereque"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corpo de jovem que desapareceu no mar \u00e9 encontrado em praia de Guaruj\u00e1 - Litoral SP<\/title>\n<meta name=\"description\" content=\"encontrado o corpo de uma jovem de 14 anos que desapareceu no \u00faltimo domingo (6). Ela se afogou na Praia do Perequ\u00ea, no Guaruj\u00e1 e dois\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/02\/08\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corpo de jovem que desapareceu no mar \u00e9 encontrado em praia de Guaruj\u00e1 - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"encontrado o corpo de uma jovem de 14 anos que desapareceu no \u00faltimo domingo (6). Ela se afogou na Praia do Perequ\u00ea, no Guaruj\u00e1 e dois\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/02\/08\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-08T19:16:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-08T19:17:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/02\/whatsapp-image-2022-02-07-at-23-22-49.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"984\" \/>\n\t<meta property=\"og:image:height\" content=\"860\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leonardo Francisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonardo Francisco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/02\\\/08\\\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/02\\\/08\\\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja\"},\"author\":{\"name\":\"Leonardo Francisco\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/0f0b8a5bdafefe82841e07ae8d81ecb3\"},\"headline\":\"Corpo de jovem que desapareceu no mar \u00e9 encontrado em praia de Guaruj\u00e1\",\"datePublished\":\"2022-02-08T19:16:10+00:00\",\"dateModified\":\"2022-02-08T19:17:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/02\\\/08\\\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja\"},\"wordCount\":142,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/02\\\/08\\\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/02\\\/whatsapp-image-2022-02-07-at-23-22-49.jpeg\",\"keywords\":[\"GRUPAMENTO DE BOMBEIROS MAR\u00cdTIMOS\",\"GUARUJ\u00c1\",\"JOVEM DESAPARECIDA\",\"PRAIA DO CAMBURIZINHO\",\"PRAIA DO PEREQU\u00ca\"],\"articleSection\":[\"Guaruj\u00e1\",\"Pol\u00edcia\",\"Praia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/02\\\/08\\\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/02\\\/08\\\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/02\\\/08\\\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja\",\"name\":\"Corpo de jovem que desapareceu no mar \u00e9 encontrado em praia de Guaruj\u00e1 - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/02\\\/08\\\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/02\\\/08\\\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/02\\\/whatsapp-image-2022-02-07-at-23-22-49.jpeg\",\"datePublished\":\"2022-02-08T19:16:10+00:00\",\"dateModified\":\"2022-02-08T19:17:15+00:00\",\"description\":\"encontrado o corpo de uma jovem de 14 anos que desapareceu no \u00faltimo domingo (6). Ela se afogou na Praia do Perequ\u00ea, no Guaruj\u00e1 e dois\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/02\\\/08\\\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/02\\\/08\\\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/02\\\/whatsapp-image-2022-02-07-at-23-22-49.jpeg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/02\\\/whatsapp-image-2022-02-07-at-23-22-49.jpeg\",\"width\":984,\"height\":860,\"caption\":\"Cr\u00e9ditos: Arquivo Pessoal.\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/0f0b8a5bdafefe82841e07ae8d81ecb3\",\"name\":\"Leonardo Francisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"caption\":\"Leonardo Francisco\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/leonardo-francisco\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corpo de jovem que desapareceu no mar \u00e9 encontrado em praia de Guaruj\u00e1 - Litoral SP","description":"encontrado o corpo de uma jovem de 14 anos que desapareceu no \u00faltimo domingo (6). Ela se afogou na Praia do Perequ\u00ea, no Guaruj\u00e1 e dois","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/02\/08\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja","og_locale":"pt_BR","og_type":"article","og_title":"Corpo de jovem que desapareceu no mar \u00e9 encontrado em praia de Guaruj\u00e1 - Litoral SP","og_description":"encontrado o corpo de uma jovem de 14 anos que desapareceu no \u00faltimo domingo (6). Ela se afogou na Praia do Perequ\u00ea, no Guaruj\u00e1 e dois","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/02\/08\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja","og_site_name":"Litoral SP","article_published_time":"2022-02-08T19:16:10+00:00","article_modified_time":"2022-02-08T19:17:15+00:00","og_image":[{"width":984,"height":860,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/02\/whatsapp-image-2022-02-07-at-23-22-49.jpeg","type":"image\/jpeg"}],"author":"Leonardo Francisco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Leonardo Francisco","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/02\/08\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/02\/08\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja"},"author":{"name":"Leonardo Francisco","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/0f0b8a5bdafefe82841e07ae8d81ecb3"},"headline":"Corpo de jovem que desapareceu no mar \u00e9 encontrado em praia de Guaruj\u00e1","datePublished":"2022-02-08T19:16:10+00:00","dateModified":"2022-02-08T19:17:15+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/02\/08\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja"},"wordCount":142,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/02\/08\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/02\/whatsapp-image-2022-02-07-at-23-22-49.jpeg","keywords":["GRUPAMENTO DE BOMBEIROS MAR\u00cdTIMOS","GUARUJ\u00c1","JOVEM DESAPARECIDA","PRAIA DO CAMBURIZINHO","PRAIA DO PEREQU\u00ca"],"articleSection":["Guaruj\u00e1","Pol\u00edcia","Praia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/02\/08\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/02\/08\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/02\/08\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja","name":"Corpo de jovem que desapareceu no mar \u00e9 encontrado em praia de Guaruj\u00e1 - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/02\/08\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/02\/08\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/02\/whatsapp-image-2022-02-07-at-23-22-49.jpeg","datePublished":"2022-02-08T19:16:10+00:00","dateModified":"2022-02-08T19:17:15+00:00","description":"encontrado o corpo de uma jovem de 14 anos que desapareceu no \u00faltimo domingo (6). Ela se afogou na Praia do Perequ\u00ea, no Guaruj\u00e1 e dois","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/02\/08\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/02\/08\/corpo-de-jovem-que-desapareceu-no-mar-e-encontrado-em-praia-de-guaruja#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/02\/whatsapp-image-2022-02-07-at-23-22-49.jpeg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/02\/whatsapp-image-2022-02-07-at-23-22-49.jpeg","width":984,"height":860,"caption":"Cr\u00e9ditos: Arquivo Pessoal."},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/0f0b8a5bdafefe82841e07ae8d81ecb3","name":"Leonardo Francisco","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","caption":"Leonardo Francisco"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/leonardo-francisco"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/23028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=23028"}],"version-history":[{"count":2,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/23028\/revisions"}],"predecessor-version":[{"id":23031,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/23028\/revisions\/23031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/23029"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=23028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=23028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=23028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}