{"id":27421,"date":"2022-04-27T13:00:03","date_gmt":"2022-04-27T16:00:03","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/?p=27421"},"modified":"2022-04-27T13:00:03","modified_gmt":"2022-04-27T16:00:03","slug":"dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/04\/27\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe","title":{"rendered":"Dupla \u00e9 detida sob acusa\u00e7\u00e3o de tr\u00e1fico de drogas em Peru\u00edbe"},"content":{"rendered":"<p>Um homem de 21 anos foi preso e um <strong>adolescente de 17 anos<\/strong> foi apreendido nessa ter\u00e7a-feira (26), em <a href=\"http:\/\/www.peruibe.sp.gov.br\/\">Peru\u00edbe<\/a>. A dupla \u00e9 acusada de cometer o tr\u00e1fico de drogas na cidade e ambos foram flagrados comercializando os entorpecentes.<\/p>\n<p>De acordo com a Pol\u00edcia Civil, a equipe da Delegacia de Investiga\u00e7\u00f5es Sobre Entorpecentes (Dise) de Itanha\u00e9m, o caso ocorria no bairro Est\u00e2ncia Antonio Novaes e os policiais monitoravam os suspeitos de forma dissimulada. De repente visualizaram usu\u00e1rios adquirindo os entorpecentes com a dupla. Para despistar qualquer suspeita, os acusados escondiam as drogas debaixo de uma pedra encostada em um muro de um bar.<\/p>\n<p>Os policiais fizeram a abordagem e no loval foram encontrados 32 pinos com coca\u00edna, tr\u00eas por\u00e7\u00f5es de maconha, R$ 53 e dois celulares. Ap\u00f3s os procedimentos, o homem foi preso e levado para o sistema penitenci\u00e1rio e o menor acabou sendo encaminhado \u00e0 Funda\u00e7\u00e3o Casa.<\/p>\n<p><strong>LEIA TAMB\u00c9M<\/strong><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/04\/27\/homem-com-mais-de-20-kg-de-drogas-e-preso-em-mongagua\">Homem com mais de 20 Kg de drogas \u00e9 preso em Mongagu\u00e1<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem de 21 anos foi preso e um adolescente de 17 anos foi apreendido nessa ter\u00e7a-feira (26), em Peru\u00edbe. A dupla \u00e9 acusada de cometer o tr\u00e1fico de drogas na cidade e ambos foram flagrados comercializando os entorpecentes. De acordo com a Pol\u00edcia Civil, a equipe da Delegacia de Investiga\u00e7\u00f5es Sobre Entorpecentes (Dise) de &hellip;<\/p>\n","protected":false},"author":6,"featured_media":27422,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[185,10],"tags":[25993,6342,25660,1060,41734,61],"class_list":["post-27421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-peruibe","category-policia","tag-dise-de-itanhaem","tag-homem-preso","tag-menor-apreendido","tag-peruibe","tag-policia-ciivl","tag-trafico-de-drogas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dupla \u00e9 detida sob acusa\u00e7\u00e3o de tr\u00e1fico de drogas em Peru\u00edbe - Litoral SP<\/title>\n<meta name=\"description\" content=\"Um homem de 21 anos foi preso e um adolescente de 17 anos foi apreendido nessa ter\u00e7a-feira (26), em Peru\u00edbe. A dupla \u00e9 acusada\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/04\/27\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dupla \u00e9 detida sob acusa\u00e7\u00e3o de tr\u00e1fico de drogas em Peru\u00edbe - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"Um homem de 21 anos foi preso e um adolescente de 17 anos foi apreendido nessa ter\u00e7a-feira (26), em Peru\u00edbe. A dupla \u00e9 acusada\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/04\/27\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-27T16:00:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/04\/whatsapp-image-2022-04-27-at-10-46-19-e1651075163682.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"587\" \/>\n\t<meta property=\"og:image:height\" content=\"604\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leonardo Francisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonardo Francisco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/04\\\/27\\\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/04\\\/27\\\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe\"},\"author\":{\"name\":\"Leonardo Francisco\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/0f0b8a5bdafefe82841e07ae8d81ecb3\"},\"headline\":\"Dupla \u00e9 detida sob acusa\u00e7\u00e3o de tr\u00e1fico de drogas em Peru\u00edbe\",\"datePublished\":\"2022-04-27T16:00:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/04\\\/27\\\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe\"},\"wordCount\":181,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/04\\\/27\\\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/whatsapp-image-2022-04-27-at-10-46-19-e1651075163682.jpeg\",\"keywords\":[\"DISE DE ITANHA\u00c9M\",\"HOMEM PRESO\",\"MENOR APREENDIDO\",\"PERU\u00cdBE\",\"POL\u00cdCIA CIIVL\",\"TR\u00c1FICO DE DROGAS\"],\"articleSection\":[\"Peru\u00edbe\",\"Pol\u00edcia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/04\\\/27\\\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/04\\\/27\\\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/04\\\/27\\\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe\",\"name\":\"Dupla \u00e9 detida sob acusa\u00e7\u00e3o de tr\u00e1fico de drogas em Peru\u00edbe - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/04\\\/27\\\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/04\\\/27\\\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/whatsapp-image-2022-04-27-at-10-46-19-e1651075163682.jpeg\",\"datePublished\":\"2022-04-27T16:00:03+00:00\",\"description\":\"Um homem de 21 anos foi preso e um adolescente de 17 anos foi apreendido nessa ter\u00e7a-feira (26), em Peru\u00edbe. A dupla \u00e9 acusada\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/04\\\/27\\\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/04\\\/27\\\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/whatsapp-image-2022-04-27-at-10-46-19-e1651075163682.jpeg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/whatsapp-image-2022-04-27-at-10-46-19-e1651075163682.jpeg\",\"width\":587,\"height\":604,\"caption\":\"Cr\u00e9ditos: Divulga\u00e7\u00e3o\\\/Pol\u00edcia Civil\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/0f0b8a5bdafefe82841e07ae8d81ecb3\",\"name\":\"Leonardo Francisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"caption\":\"Leonardo Francisco\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/leonardo-francisco\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dupla \u00e9 detida sob acusa\u00e7\u00e3o de tr\u00e1fico de drogas em Peru\u00edbe - Litoral SP","description":"Um homem de 21 anos foi preso e um adolescente de 17 anos foi apreendido nessa ter\u00e7a-feira (26), em Peru\u00edbe. A dupla \u00e9 acusada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/04\/27\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe","og_locale":"pt_BR","og_type":"article","og_title":"Dupla \u00e9 detida sob acusa\u00e7\u00e3o de tr\u00e1fico de drogas em Peru\u00edbe - Litoral SP","og_description":"Um homem de 21 anos foi preso e um adolescente de 17 anos foi apreendido nessa ter\u00e7a-feira (26), em Peru\u00edbe. A dupla \u00e9 acusada","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/04\/27\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe","og_site_name":"Litoral SP","article_published_time":"2022-04-27T16:00:03+00:00","og_image":[{"width":587,"height":604,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/04\/whatsapp-image-2022-04-27-at-10-46-19-e1651075163682.jpeg","type":"image\/jpeg"}],"author":"Leonardo Francisco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Leonardo Francisco","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/04\/27\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/04\/27\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe"},"author":{"name":"Leonardo Francisco","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/0f0b8a5bdafefe82841e07ae8d81ecb3"},"headline":"Dupla \u00e9 detida sob acusa\u00e7\u00e3o de tr\u00e1fico de drogas em Peru\u00edbe","datePublished":"2022-04-27T16:00:03+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/04\/27\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe"},"wordCount":181,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/04\/27\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/04\/whatsapp-image-2022-04-27-at-10-46-19-e1651075163682.jpeg","keywords":["DISE DE ITANHA\u00c9M","HOMEM PRESO","MENOR APREENDIDO","PERU\u00cdBE","POL\u00cdCIA CIIVL","TR\u00c1FICO DE DROGAS"],"articleSection":["Peru\u00edbe","Pol\u00edcia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/04\/27\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/04\/27\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/04\/27\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe","name":"Dupla \u00e9 detida sob acusa\u00e7\u00e3o de tr\u00e1fico de drogas em Peru\u00edbe - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/04\/27\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/04\/27\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/04\/whatsapp-image-2022-04-27-at-10-46-19-e1651075163682.jpeg","datePublished":"2022-04-27T16:00:03+00:00","description":"Um homem de 21 anos foi preso e um adolescente de 17 anos foi apreendido nessa ter\u00e7a-feira (26), em Peru\u00edbe. A dupla \u00e9 acusada","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/04\/27\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/04\/27\/dupla-e-detida-sob-acusacao-de-trafico-de-drogas-em-peruibe#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/04\/whatsapp-image-2022-04-27-at-10-46-19-e1651075163682.jpeg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/04\/whatsapp-image-2022-04-27-at-10-46-19-e1651075163682.jpeg","width":587,"height":604,"caption":"Cr\u00e9ditos: Divulga\u00e7\u00e3o\/Pol\u00edcia Civil"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/0f0b8a5bdafefe82841e07ae8d81ecb3","name":"Leonardo Francisco","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","caption":"Leonardo Francisco"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/leonardo-francisco"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/27421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=27421"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/27421\/revisions"}],"predecessor-version":[{"id":27423,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/27421\/revisions\/27423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/27422"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=27421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=27421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=27421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}