{"id":28303,"date":"2022-05-18T14:05:23","date_gmt":"2022-05-18T17:05:23","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/?p=28303"},"modified":"2022-05-18T14:05:23","modified_gmt":"2022-05-18T17:05:23","slug":"rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/05\/18\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral","title":{"rendered":"Rajadas de vento causam a paraliza\u00e7\u00e3o da travessia de balsas no litoral"},"content":{"rendered":"<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"49\" data-block-id=\"2\">\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">Rajadas de vento causaram a paraliza\u00e7\u00e3o da travessia de balsas entre Guaruj\u00e1 e Santos na manh\u00e3 desta quarta-feira(18). Devido aos fortes ventos, motoristas tiveram que esperar a retomada do servi\u00e7o.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">De acordo com o Departamento Hidrovi\u00e1rio (DH)\u00a0 os servi\u00e7os ficaram paralisados de 2h35 e 5h55. Diversos motoristas tiveram que utilizar a estrada para chegar as cidades vizinhas.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">Ainda de acordo com o Departamento os usu\u00e1rios do servi\u00e7o entre Vicente de Carvalho e Santos tamb\u00e9m tiveram que esperar o tempo normalizar para que pudessem atravessar de um lado para o outro. Sendo assim os moradores n\u00e3o tinham op\u00e7\u00e3o de atravessar de carro.<\/p>\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><strong>Ventania no Litoral Paulista<\/strong><\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">A Defesa Civil de S\u00e3o Paulo e a Marinha do Brasil apontou que existe um alerta de ventania e ressaca no Litoral Paulista. As rajadas podem alcan\u00e7ar a velocidade de at\u00e9 88km\/h.<\/p>\n<\/div>\n<div class=\"wall protected-content\">\n<div class=\"row medium-uncollapsed content-media content-photo\" data-block-type=\"backstage-photo\" data-block-id=\"4\">\n<div class=\"mc-column content-media__container\">\n<div class=\"content-media-container glb-skeleton-box\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"62\" data-block-id=\"8\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><strong>Leia mais<\/strong><\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\"><a href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/05\/12\/brasil-tera-semana-de-frio-extremo-e-muita-chuva\">Brasil ter\u00e1 semana de frio extremo e muita chuva<\/a><\/p>\n<\/div>\n<div class=\"row medium-uncollapsed content-media content-photo\" data-block-type=\"backstage-photo\" data-block-id=\"9\">\n<div class=\"mc-column content-media__container\">\n<div class=\"content-media-container glb-skeleton-box\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Rajadas de vento causaram a paraliza\u00e7\u00e3o da travessia de balsas entre Guaruj\u00e1 e Santos na manh\u00e3 desta quarta-feira(18). Devido aos fortes ventos, motoristas tiveram que esperar a retomada do servi\u00e7o. De acordo com o Departamento Hidrovi\u00e1rio (DH)\u00a0 os servi\u00e7os ficaram paralisados de 2h35 e 5h55. Diversos motoristas tiveram que utilizar a estrada para chegar as &hellip;<\/p>\n","protected":false},"author":12,"featured_media":28304,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[187,180],"tags":[56514,18842,56515],"class_list":["post-28303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guaruja","category-santos","tag-paralisacao-das-balsas","tag-rajadas-de-vento","tag-santos-e-guaruja-balsas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rajadas de vento causam a paraliza\u00e7\u00e3o da travessia de balsas no litoral -<\/title>\n<meta name=\"description\" content=\"Rajadas de vento causaram a paraliza\u00e7\u00e3o da travessia de balsas entre Guaruj\u00e1, Vicente de Carvalho e Santos na manh\u00e3 desta quarta-feira(18).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/05\/18\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rajadas de vento causam a paraliza\u00e7\u00e3o da travessia de balsas no litoral -\" \/>\n<meta property=\"og:description\" content=\"Rajadas de vento causaram a paraliza\u00e7\u00e3o da travessia de balsas entre Guaruj\u00e1, Vicente de Carvalho e Santos na manh\u00e3 desta quarta-feira(18).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/05\/18\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-18T17:05:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/05\/2019212_balsa-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gustavo Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/05\\\/18\\\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/05\\\/18\\\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral\"},\"author\":{\"name\":\"Gustavo Silva\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\"},\"headline\":\"Rajadas de vento causam a paraliza\u00e7\u00e3o da travessia de balsas no litoral\",\"datePublished\":\"2022-05-18T17:05:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/05\\\/18\\\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral\"},\"wordCount\":173,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/05\\\/18\\\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/05\\\/2019212_balsa-scaled.jpg\",\"keywords\":[\"paralisa\u00e7\u00e3o das balsas\",\"RAJADAS DE VENTO\",\"santos e guaruj\u00e1 balsas\"],\"articleSection\":[\"Guaruj\u00e1\",\"Santos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/05\\\/18\\\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/05\\\/18\\\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/05\\\/18\\\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral\",\"name\":\"Rajadas de vento causam a paraliza\u00e7\u00e3o da travessia de balsas no litoral -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/05\\\/18\\\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/05\\\/18\\\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/05\\\/2019212_balsa-scaled.jpg\",\"datePublished\":\"2022-05-18T17:05:23+00:00\",\"description\":\"Rajadas de vento causaram a paraliza\u00e7\u00e3o da travessia de balsas entre Guaruj\u00e1, Vicente de Carvalho e Santos na manh\u00e3 desta quarta-feira(18).\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/05\\\/18\\\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/05\\\/18\\\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/05\\\/2019212_balsa-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/05\\\/2019212_balsa-scaled.jpg\",\"width\":1620,\"height\":1080,\"caption\":\"Rajadas de vento causam a paraliza\u00e7\u00e3o da travessia de balsas no litoral\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\",\"name\":\"Gustavo Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"caption\":\"Gustavo Silva\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/gustavosilva\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rajadas de vento causam a paraliza\u00e7\u00e3o da travessia de balsas no litoral -","description":"Rajadas de vento causaram a paraliza\u00e7\u00e3o da travessia de balsas entre Guaruj\u00e1, Vicente de Carvalho e Santos na manh\u00e3 desta quarta-feira(18).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/05\/18\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral","og_locale":"pt_BR","og_type":"article","og_title":"Rajadas de vento causam a paraliza\u00e7\u00e3o da travessia de balsas no litoral -","og_description":"Rajadas de vento causaram a paraliza\u00e7\u00e3o da travessia de balsas entre Guaruj\u00e1, Vicente de Carvalho e Santos na manh\u00e3 desta quarta-feira(18).","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/05\/18\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral","og_site_name":"Litoral SP","article_published_time":"2022-05-18T17:05:23+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/05\/2019212_balsa-scaled.jpg","type":"image\/jpeg"}],"author":"Gustavo Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gustavo Silva","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/05\/18\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/05\/18\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral"},"author":{"name":"Gustavo Silva","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e"},"headline":"Rajadas de vento causam a paraliza\u00e7\u00e3o da travessia de balsas no litoral","datePublished":"2022-05-18T17:05:23+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/05\/18\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral"},"wordCount":173,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/05\/18\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/05\/2019212_balsa-scaled.jpg","keywords":["paralisa\u00e7\u00e3o das balsas","RAJADAS DE VENTO","santos e guaruj\u00e1 balsas"],"articleSection":["Guaruj\u00e1","Santos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/05\/18\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/05\/18\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/05\/18\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral","name":"Rajadas de vento causam a paraliza\u00e7\u00e3o da travessia de balsas no litoral -","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/05\/18\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/05\/18\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/05\/2019212_balsa-scaled.jpg","datePublished":"2022-05-18T17:05:23+00:00","description":"Rajadas de vento causaram a paraliza\u00e7\u00e3o da travessia de balsas entre Guaruj\u00e1, Vicente de Carvalho e Santos na manh\u00e3 desta quarta-feira(18).","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/05\/18\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/05\/18\/rajadas-de-vento-causam-a-paralizacao-da-travessia-de-balsas-no-litoral#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/05\/2019212_balsa-scaled.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/05\/2019212_balsa-scaled.jpg","width":1620,"height":1080,"caption":"Rajadas de vento causam a paraliza\u00e7\u00e3o da travessia de balsas no litoral"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e","name":"Gustavo Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","caption":"Gustavo Silva"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/gustavosilva"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/28303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=28303"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/28303\/revisions"}],"predecessor-version":[{"id":28305,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/28303\/revisions\/28305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/28304"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=28303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=28303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=28303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}