{"id":6097,"date":"2021-03-23T18:29:16","date_gmt":"2021-03-23T21:29:16","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/03\/23\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol"},"modified":"2021-03-23T18:57:30","modified_gmt":"2021-03-23T21:57:30","slug":"pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/03\/23\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol","title":{"rendered":"Pres. da CBF: Globo e patrocinadores n\u00e3o querem lockdown no futebol"},"content":{"rendered":"<p>O presidente da <a href=\"https:\/\/www.cbf.com.br\/\">Confedera\u00e7\u00e3o Brasileira de Futebol<\/a> (CBF), Rog\u00e9rio Caboclo, participou de uma reuni\u00e3o com presidentes de alguns clubes brasileiros e um dos temas discutidos foi a <strong>paralisa\u00e7\u00e3o<\/strong> das competi\u00e7\u00f5es nacionais, como a Copa do Brasil. Ele descartou qualquer possibilidade do esporte parar, mesmo com a pandemia do coronav\u00edrus estar no pior momento.<\/p>\n<p>O encontro por v\u00eddeo chamada aconteceu no \u00faltimo dia 10 de mar\u00e7o e foi feito com presidentes dos clubes das S\u00e9ries A e B do futebol brasileiro e enquanto alguns estaduais, como o Paulista, Goiano, Mineiro e Cearense pararam as atividades, o presidente da CBF defendeu que os jogos devem seguir, em se tratando de competi\u00e7\u00f5es nacionais. Partidas da Copa do Brasil j\u00e1 est\u00e3o marcadas.<\/p>\n<blockquote><p>Eu vou mandar no futebol brasileiro e vou determinar que vai ter competi\u00e7\u00e3o. Porque voc\u00eas est\u00e3o f&#8230; se n\u00e3o tiver. Eu assumo o \u00f4nus por todos voc\u00eas &#8211; disse Caboclo aos presidentes de clubes.<\/p><\/blockquote>\n<h3>Motivos<\/h3>\n<p>Um dos motivos alegados para a continua\u00e7\u00e3o do futebol no Brasil se deve a emissora detentora dos direitos de transmiss\u00e3o, no caso a Rede Globo e tamb\u00e9m aos patrocinadores, onde segundo ele, n\u00e3o querem que o futebol pare.<\/p>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"103\" data-block-id=\"10\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Eu n\u00e3o abrirei m\u00e3o, a n\u00e3o ser sob doutorado dos senhores, de jogar as competi\u00e7\u00f5es nacionais, o que repercutir\u00e1 nas internacionais e incorporar\u00e1 as estaduais&#8230; Ent\u00e3o, por gentileza, vamos pensar agora: n\u00f3s podemos parar o futebol? A Rede Globo n\u00e3o quer. Eu estou assegurando que n\u00e3o. Ningu\u00e9m quer, seus patrocinadores n\u00e3o querem. E, se parar, sabe quando n\u00f3s temos a seguran\u00e7a de dizer que a gente pode voltar? Nunca. No dia em que o governador do Mauricio disser que pode. No dia em que o prefeito de S\u00e3o Nunca disser que pode&#8230; Eu n\u00e3o vou estar \u00e0 merc\u00ea de nenhum deles&#8221;, comentou.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"19\" data-block-id=\"11\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Em certa parte da reuni\u00e3o, houve o seguinte di\u00e1logo entre o presidente do Palmeiras, Maur\u00edcio Galiotte, e Rog\u00e9rio Caboclo.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"39\" data-block-id=\"12\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Galiotte &#8211; Podemos voltar a discutir esse assunto em outro momento?<br \/>\nCaboclo &#8211; N\u00e3o, por que em outro momento?<br \/>\nGaliotte &#8211; Porque acho que a discuss\u00e3o \u00e9 um pouco mais ampla, mas vou encerrar aqui a minha coloca\u00e7\u00e3o.<br \/>\nCaboclo &#8211; \u00d3timo.<\/p>\n<\/div>\n<h3>Resposta da Globo<\/h3>\n<article>\n<div class=\"wall protected-content\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"61\" data-block-id=\"17\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><em>&#8220;Como vem fazendo desde o in\u00edcio da pandemia h\u00e1 mais de um ano, a Globo segue respeitando as orienta\u00e7\u00f5es dadas pelas autoridades competentes e acompanhando as decis\u00f5es dos organizadores das competi\u00e7\u00f5es. Entendemos que o momento \u00e9 de cautela, e que a prioridade \u00e9 a seguran\u00e7a de todos. Vamos seguir e respeitar todos os protocolos que forem definidos e decididos pelas entidades.\u201d<\/em><\/p>\n<\/div>\n<div data-track-category=\"multicontent\" data-track-action=\"ultimo chunk conteudo\" data-track-noninteraction=\"false\" data-track-scroll=\"view\"><strong>Leia tamb\u00e9m<\/strong><\/div>\n<\/div>\n<\/article>\n<div data-track-category=\"multicontent\" data-track-action=\"ultimo chunk conteudo\" data-track-noninteraction=\"false\" data-track-scroll=\"view\"><\/div>\n<div data-track-category=\"multicontent\" data-track-action=\"ultimo chunk conteudo\" data-track-noninteraction=\"false\" data-track-scroll=\"view\"><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2021\/03\/22\/meninas-de-araraquara-sao-donas-da-america\">Meninas de Araraquara s\u00e3o donas da Am\u00e9rica<\/a><\/div>\n<div class=\"mc-column entities\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O presidente da Confedera\u00e7\u00e3o Brasileira de Futebol (CBF), Rog\u00e9rio Caboclo, participou de uma reuni\u00e3o com presidentes de alguns clubes brasileiros e um dos temas discutidos foi a paralisa\u00e7\u00e3o das competi\u00e7\u00f5es nacionais, como a Copa do Brasil. Ele descartou qualquer possibilidade do esporte parar, mesmo com a pandemia do coronav\u00edrus estar no pior momento. O encontro &hellip;<\/p>\n","protected":false},"author":6,"featured_media":6098,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[15059,16445,1219,16446,16447,1980],"class_list":["post-6097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte","tag-cbf","tag-clu8bes","tag-futebol","tag-presidente-rogerio-caboclo","tag-presidentes","tag-reuniao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pres. da CBF: Globo e patrocinadores n\u00e3o querem lockdown no futebol - Litoral SP<\/title>\n<meta name=\"description\" content=\"O presidente da Confedera\u00e7\u00e3o Brasileira de Futebol (CBF), Rog\u00e9rio Caboclo, participou de uma reuni\u00e3o com presidentes de alguns clubes brasileiros\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/03\/23\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pres. da CBF: Globo e patrocinadores n\u00e3o querem lockdown no futebol - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"O presidente da Confedera\u00e7\u00e3o Brasileira de Futebol (CBF), Rog\u00e9rio Caboclo, participou de uma reuni\u00e3o com presidentes de alguns clubes brasileiros\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/03\/23\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-23T21:29:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-23T21:57:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/03\/caboclo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"984\" \/>\n\t<meta property=\"og:image:height\" content=\"647\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leonardo Francisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonardo Francisco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/03\\\/23\\\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/03\\\/23\\\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol\"},\"author\":{\"name\":\"Leonardo Francisco\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/0f0b8a5bdafefe82841e07ae8d81ecb3\"},\"headline\":\"Pres. da CBF: Globo e patrocinadores n\u00e3o querem lockdown no futebol\",\"datePublished\":\"2021-03-23T21:29:16+00:00\",\"dateModified\":\"2021-03-23T21:57:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/03\\\/23\\\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol\"},\"wordCount\":482,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/03\\\/23\\\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/03\\\/caboclo.jpg\",\"keywords\":[\"CBF\",\"CLU8BES\",\"FUTEBOL\",\"PRESIDENTE ROG\u00c9RIO CABOCLO\",\"PRESIDENTES\",\"REUNI\u00c3O\"],\"articleSection\":[\"Esporte\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/03\\\/23\\\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/03\\\/23\\\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/03\\\/23\\\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol\",\"name\":\"Pres. da CBF: Globo e patrocinadores n\u00e3o querem lockdown no futebol - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/03\\\/23\\\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/03\\\/23\\\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/03\\\/caboclo.jpg\",\"datePublished\":\"2021-03-23T21:29:16+00:00\",\"dateModified\":\"2021-03-23T21:57:30+00:00\",\"description\":\"O presidente da Confedera\u00e7\u00e3o Brasileira de Futebol (CBF), Rog\u00e9rio Caboclo, participou de uma reuni\u00e3o com presidentes de alguns clubes brasileiros\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/03\\\/23\\\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/03\\\/23\\\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/03\\\/caboclo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/03\\\/caboclo.jpg\",\"width\":984,\"height\":647,\"caption\":\"Cr\u00e9ditos: Divulga\u00e7\u00e3o\\\/CBF\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/0f0b8a5bdafefe82841e07ae8d81ecb3\",\"name\":\"Leonardo Francisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"caption\":\"Leonardo Francisco\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/leonardo-francisco\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pres. da CBF: Globo e patrocinadores n\u00e3o querem lockdown no futebol - Litoral SP","description":"O presidente da Confedera\u00e7\u00e3o Brasileira de Futebol (CBF), Rog\u00e9rio Caboclo, participou de uma reuni\u00e3o com presidentes de alguns clubes brasileiros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/03\/23\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol","og_locale":"pt_BR","og_type":"article","og_title":"Pres. da CBF: Globo e patrocinadores n\u00e3o querem lockdown no futebol - Litoral SP","og_description":"O presidente da Confedera\u00e7\u00e3o Brasileira de Futebol (CBF), Rog\u00e9rio Caboclo, participou de uma reuni\u00e3o com presidentes de alguns clubes brasileiros","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/03\/23\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol","og_site_name":"Litoral SP","article_published_time":"2021-03-23T21:29:16+00:00","article_modified_time":"2021-03-23T21:57:30+00:00","og_image":[{"width":984,"height":647,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/03\/caboclo.jpg","type":"image\/jpeg"}],"author":"Leonardo Francisco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Leonardo Francisco","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/03\/23\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/03\/23\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol"},"author":{"name":"Leonardo Francisco","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/0f0b8a5bdafefe82841e07ae8d81ecb3"},"headline":"Pres. da CBF: Globo e patrocinadores n\u00e3o querem lockdown no futebol","datePublished":"2021-03-23T21:29:16+00:00","dateModified":"2021-03-23T21:57:30+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/03\/23\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol"},"wordCount":482,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/03\/23\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/03\/caboclo.jpg","keywords":["CBF","CLU8BES","FUTEBOL","PRESIDENTE ROG\u00c9RIO CABOCLO","PRESIDENTES","REUNI\u00c3O"],"articleSection":["Esporte"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/03\/23\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/03\/23\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/03\/23\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol","name":"Pres. da CBF: Globo e patrocinadores n\u00e3o querem lockdown no futebol - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/03\/23\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/03\/23\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/03\/caboclo.jpg","datePublished":"2021-03-23T21:29:16+00:00","dateModified":"2021-03-23T21:57:30+00:00","description":"O presidente da Confedera\u00e7\u00e3o Brasileira de Futebol (CBF), Rog\u00e9rio Caboclo, participou de uma reuni\u00e3o com presidentes de alguns clubes brasileiros","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/03\/23\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/03\/23\/pres-da-cbf-globo-e-patrocinadores-nao-querem-lockdown-no-futebol#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/03\/caboclo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/03\/caboclo.jpg","width":984,"height":647,"caption":"Cr\u00e9ditos: Divulga\u00e7\u00e3o\/CBF"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/0f0b8a5bdafefe82841e07ae8d81ecb3","name":"Leonardo Francisco","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","caption":"Leonardo Francisco"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/leonardo-francisco"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/6097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=6097"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/6097\/revisions"}],"predecessor-version":[{"id":6099,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/6097\/revisions\/6099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/6098"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=6097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=6097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=6097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}