{"id":7856,"date":"2021-04-29T19:30:05","date_gmt":"2021-04-29T22:30:05","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/04\/29\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19"},"modified":"2021-04-29T19:32:47","modified_gmt":"2021-04-29T22:32:47","slug":"assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/04\/29\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19","title":{"rendered":"Assim como Serrana, Botucatu tamb\u00e9m far\u00e1 vacina em massa contra a Covid-19"},"content":{"rendered":"<p>Chegou a vez de <a href=\"https:\/\/www.botucatu.sp.gov.br\/\">Botucatu<\/a> ter a <strong>vacina\u00e7\u00e3o em massa<\/strong> contra a Covid-19. Assim como aconteceu em Serrana, Botucatu tamb\u00e9m participar\u00e1 de um teste sobre a efic\u00e1cia e a transmiss\u00e3o do coronav\u00edrus quando tem vacina em massa.<\/p>\n<p>O projeto \u00e9 do Minist\u00e9rio da Sa\u00fade, onde ser\u00e3o doadas doses da vacina Oxford\/AstraZeneca. Botucatu tem 148 mil habitantes, segundo o IBGE. Mas a vacina\u00e7\u00e3o deve atingir apenas os maiores de 18 anos, excluindo a popula\u00e7\u00e3o que j\u00e1 foi vacinada e os n\u00e3o vacin\u00e1veis.<\/p>\n<p>O estudo foi aprovado pela Comiss\u00e3o Nacional de \u00c9tica em Pesquisa (Conep) e as doses da vacina ser\u00e3o doadas pelo Programa Nacional de Imuniza\u00e7\u00e3o (PNI) do governo federal.\u00a0Cerca de 105 mil habitantes acima de 18 anos come\u00e7am a ser vacinados em duas semanas.<\/p>\n<p>O sequenciamento das amostras coletadas vai ser feito pelo laborat\u00f3rio do Hospital das Cl\u00ednicas de Botucatu. O tempo do estudo ser\u00e1 de oito meses. Nesse per\u00edodo, ser\u00e3o sequenciados os casos positivos para saber qual a cepa e a efetividade do imunizante.<\/p>\n<h3>Estudo da Coronavac<\/h3>\n<p>O estudo \u00e9 semelhante ao que j\u00e1 foi realizado em Serrana, outra cidade do interior paulista, com a vacina Coronavac, produzida pelo Instituto Butantan. No estudo cl\u00ednico da Coronavac, coordenado pelo Instituto Butantan, 98% dos moradores de Serrana cadastrados receberam as duas doses, entre meados de fevereiro e o in\u00edcio de abril deste ano.<\/p>\n<p>A imuniza\u00e7\u00e3o atingiu 28,3 mil dos 45,6 mil habitantes, \u00edndice de 60% da popula\u00e7\u00e3o total. Os dados ainda est\u00e3o em an\u00e1lise, j\u00e1 que os vacinados ser\u00e3o acompanhados durante um ano. O Butantan pretende divulgar os primeiros dados em maio.<\/p>\n<p><strong>LEIA TAMB\u00c9M<\/strong><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2021\/04\/28\/producao-da-butanvac-vai-comecar\">Produ\u00e7\u00e3o da Butanvac vai come\u00e7ar<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chegou a vez de Botucatu ter a vacina\u00e7\u00e3o em massa contra a Covid-19. Assim como aconteceu em Serrana, Botucatu tamb\u00e9m participar\u00e1 de um teste sobre a efic\u00e1cia e a transmiss\u00e3o do coronav\u00edrus quando tem vacina em massa. O projeto \u00e9 do Minist\u00e9rio da Sa\u00fade, onde ser\u00e3o doadas doses da vacina Oxford\/AstraZeneca. Botucatu tem 148 mil &hellip;<\/p>\n","protected":false},"author":6,"featured_media":4734,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[4052,14259,13417,5797,15482],"class_list":["post-7856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude","tag-butantan","tag-ministeiro-da-saude","tag-oxford-astrazeneca","tag-vacina-contra-covid","tag-vacinacao-em-massa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Assim como Serrana, Botucatu tamb\u00e9m far\u00e1 vacina em massa contra a Covid-19 - Litoral SP<\/title>\n<meta name=\"description\" content=\"Chegou a vez de Botucatu ter a vacina\u00e7\u00e3o em massa contra a Covid-19. Assim como aconteceu em Serrana, Botucatu tamb\u00e9m participar\u00e1 de um\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/04\/29\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assim como Serrana, Botucatu tamb\u00e9m far\u00e1 vacina em massa contra a Covid-19 - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"Chegou a vez de Botucatu ter a vacina\u00e7\u00e3o em massa contra a Covid-19. Assim como aconteceu em Serrana, Botucatu tamb\u00e9m participar\u00e1 de um\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/04\/29\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-29T22:30:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-29T22:32:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/02\/vacina-oxford.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1008\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leonardo Francisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonardo Francisco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/04\\\/29\\\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/04\\\/29\\\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19\"},\"author\":{\"name\":\"Leonardo Francisco\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/0f0b8a5bdafefe82841e07ae8d81ecb3\"},\"headline\":\"Assim como Serrana, Botucatu tamb\u00e9m far\u00e1 vacina em massa contra a Covid-19\",\"datePublished\":\"2021-04-29T22:30:05+00:00\",\"dateModified\":\"2021-04-29T22:32:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/04\\\/29\\\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19\"},\"wordCount\":303,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/04\\\/29\\\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/02\\\/vacina-oxford.jpeg\",\"keywords\":[\"Butantan\",\"MINIST\u00c9IRO DA SA\u00daDE\",\"OXFORD\\\/ASTRAZENECA\",\"VACINA CONTRA COVID\",\"VACINA\u00c7\u00c3O EM MASSA\"],\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/04\\\/29\\\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/04\\\/29\\\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/04\\\/29\\\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19\",\"name\":\"Assim como Serrana, Botucatu tamb\u00e9m far\u00e1 vacina em massa contra a Covid-19 - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/04\\\/29\\\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/04\\\/29\\\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/02\\\/vacina-oxford.jpeg\",\"datePublished\":\"2021-04-29T22:30:05+00:00\",\"dateModified\":\"2021-04-29T22:32:47+00:00\",\"description\":\"Chegou a vez de Botucatu ter a vacina\u00e7\u00e3o em massa contra a Covid-19. Assim como aconteceu em Serrana, Botucatu tamb\u00e9m participar\u00e1 de um\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/04\\\/29\\\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2021\\\/04\\\/29\\\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/02\\\/vacina-oxford.jpeg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/02\\\/vacina-oxford.jpeg\",\"width\":1008,\"height\":567,\"caption\":\"Assim como Serrana, Botucatu tamb\u00e9m far\u00e1 vacina em massa contra a Covid-19\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/0f0b8a5bdafefe82841e07ae8d81ecb3\",\"name\":\"Leonardo Francisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"caption\":\"Leonardo Francisco\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/leonardo-francisco\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assim como Serrana, Botucatu tamb\u00e9m far\u00e1 vacina em massa contra a Covid-19 - Litoral SP","description":"Chegou a vez de Botucatu ter a vacina\u00e7\u00e3o em massa contra a Covid-19. Assim como aconteceu em Serrana, Botucatu tamb\u00e9m participar\u00e1 de um","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/04\/29\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19","og_locale":"pt_BR","og_type":"article","og_title":"Assim como Serrana, Botucatu tamb\u00e9m far\u00e1 vacina em massa contra a Covid-19 - Litoral SP","og_description":"Chegou a vez de Botucatu ter a vacina\u00e7\u00e3o em massa contra a Covid-19. Assim como aconteceu em Serrana, Botucatu tamb\u00e9m participar\u00e1 de um","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/04\/29\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19","og_site_name":"Litoral SP","article_published_time":"2021-04-29T22:30:05+00:00","article_modified_time":"2021-04-29T22:32:47+00:00","og_image":[{"width":1008,"height":567,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/02\/vacina-oxford.jpeg","type":"image\/jpeg"}],"author":"Leonardo Francisco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Leonardo Francisco","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/04\/29\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/04\/29\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19"},"author":{"name":"Leonardo Francisco","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/0f0b8a5bdafefe82841e07ae8d81ecb3"},"headline":"Assim como Serrana, Botucatu tamb\u00e9m far\u00e1 vacina em massa contra a Covid-19","datePublished":"2021-04-29T22:30:05+00:00","dateModified":"2021-04-29T22:32:47+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/04\/29\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19"},"wordCount":303,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/04\/29\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/02\/vacina-oxford.jpeg","keywords":["Butantan","MINIST\u00c9IRO DA SA\u00daDE","OXFORD\/ASTRAZENECA","VACINA CONTRA COVID","VACINA\u00c7\u00c3O EM MASSA"],"articleSection":["Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/04\/29\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/04\/29\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/04\/29\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19","name":"Assim como Serrana, Botucatu tamb\u00e9m far\u00e1 vacina em massa contra a Covid-19 - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/04\/29\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/04\/29\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/02\/vacina-oxford.jpeg","datePublished":"2021-04-29T22:30:05+00:00","dateModified":"2021-04-29T22:32:47+00:00","description":"Chegou a vez de Botucatu ter a vacina\u00e7\u00e3o em massa contra a Covid-19. Assim como aconteceu em Serrana, Botucatu tamb\u00e9m participar\u00e1 de um","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/04\/29\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2021\/04\/29\/assim-como-serrana-botucatu-tambem-fara-vacina-em-massa-contra-a-covid-19#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/02\/vacina-oxford.jpeg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2021\/02\/vacina-oxford.jpeg","width":1008,"height":567,"caption":"Assim como Serrana, Botucatu tamb\u00e9m far\u00e1 vacina em massa contra a Covid-19"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/0f0b8a5bdafefe82841e07ae8d81ecb3","name":"Leonardo Francisco","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","caption":"Leonardo Francisco"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/leonardo-francisco"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/7856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=7856"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/7856\/revisions"}],"predecessor-version":[{"id":7857,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/7856\/revisions\/7857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/4734"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=7856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=7856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=7856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}