{"id":85674,"date":"2022-06-07T14:05:24","date_gmt":"2022-06-07T17:05:24","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/?p=85674"},"modified":"2022-06-07T14:07:28","modified_gmt":"2022-06-07T17:07:28","slug":"criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/06\/07\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador","title":{"rendered":"Criminosos roubam casa em Praia Grande ap\u00f3s descuido de morador"},"content":{"rendered":"<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"57\" data-block-id=\"2\">\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">Tr\u00eas criminosos roubaram uma casa em Praia Grande ap\u00f3s descuido de seu morador nesta \u00faltima ter\u00e7a-feira (3) no bairro Maracan\u00e3.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">De acordo com a pol\u00edcia, o dono da casa deixou uma das portas abertas ao sair para almo\u00e7ar, facilitando assim a entrada dos bandidos que perceberam a movimenta\u00e7\u00e3o a seu favor.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-85676\" src=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/06\/2-4-300x184.jpg\" alt=\"Criminosos roubam casa em Praia Grande ap\u00f3s descuido de morador\" width=\"300\" height=\"184\" srcset=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/06\/2-4-300x184.jpg 300w, https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/06\/2-4.jpg 582w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">Ainda de acordo com as autoridades, da casa que fica na Rua Jos\u00e9 Agapito Cardoso foram levados um notebook, uma televis\u00e3o, um micro-ondas e um celular. O preju\u00edzo chega a R$ 9 mil.<\/p>\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Segundo o morador, ele se sentiu seguro tendo em vista que os cachorros do vizinho estavam soltos, o que poderia afugentar poss\u00edveis bandidos, o que n\u00e3o aconteceu.<\/p>\n<\/div>\n<div class=\"wall protected-content\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"38\" data-block-id=\"3\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Sendo assim, a v\u00edtima registrou boletim de ocorr\u00eancia no 3\u00b0 Distrito Policial de Praia Grande o caso ser\u00e1 investigado pelas equipes.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"37\" data-block-id=\"8\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Leia mais<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\"><a href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/06\/03\/adolescente-e-homens-sao-presos-por-trafico-em-praia-grande\">Adolescente e homens s\u00e3o presos por tr\u00e1fico em Praia Grande<\/a><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tr\u00eas criminosos roubaram uma casa em Praia Grande ap\u00f3s descuido de seu morador nesta \u00faltima ter\u00e7a-feira (3) no bairro Maracan\u00e3. De acordo com a pol\u00edcia, o dono da casa deixou uma das portas abertas ao sair para almo\u00e7ar, facilitando assim a entrada dos bandidos que perceberam a movimenta\u00e7\u00e3o a seu favor. Ainda de acordo com &hellip;<\/p>\n","protected":false},"author":12,"featured_media":85675,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[182],"tags":[29582,56980,1101],"class_list":["post-85674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-praia-grande","tag-bairro-maracana","tag-furto-casa","tag-praia-grande"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Criminosos roubam casa em Praia Grande ap\u00f3s descuido de morador -<\/title>\n<meta name=\"description\" content=\"Tr\u00eas criminosos roubaram uma casa em Praia Grande ap\u00f3s descuido de seu morador nesta \u00faltima ter\u00e7a-feira (3) no bairro Maracan\u00e3.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/06\/07\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Criminosos roubam casa em Praia Grande ap\u00f3s descuido de morador -\" \/>\n<meta property=\"og:description\" content=\"Tr\u00eas criminosos roubaram uma casa em Praia Grande ap\u00f3s descuido de seu morador nesta \u00faltima ter\u00e7a-feira (3) no bairro Maracan\u00e3.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/06\/07\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-07T17:05:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-07T17:07:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/06\/1-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"581\" \/>\n\t<meta property=\"og:image:height\" content=\"348\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gustavo Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/06\\\/07\\\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/06\\\/07\\\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador\"},\"author\":{\"name\":\"Gustavo Silva\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\"},\"headline\":\"Criminosos roubam casa em Praia Grande ap\u00f3s descuido de morador\",\"datePublished\":\"2022-06-07T17:05:24+00:00\",\"dateModified\":\"2022-06-07T17:07:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/06\\\/07\\\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador\"},\"wordCount\":166,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/06\\\/07\\\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/1-7.jpg\",\"keywords\":[\"BAIRRO MARACAN\u00c3\",\"furto casa\",\"PRAIA GRANDE\"],\"articleSection\":[\"Praia Grande\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/06\\\/07\\\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/06\\\/07\\\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/06\\\/07\\\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador\",\"name\":\"Criminosos roubam casa em Praia Grande ap\u00f3s descuido de morador -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/06\\\/07\\\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/06\\\/07\\\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/1-7.jpg\",\"datePublished\":\"2022-06-07T17:05:24+00:00\",\"dateModified\":\"2022-06-07T17:07:28+00:00\",\"description\":\"Tr\u00eas criminosos roubaram uma casa em Praia Grande ap\u00f3s descuido de seu morador nesta \u00faltima ter\u00e7a-feira (3) no bairro Maracan\u00e3.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/06\\\/07\\\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/06\\\/07\\\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/1-7.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/06\\\/1-7.jpg\",\"width\":581,\"height\":348,\"caption\":\"Criminosos roubam casa em Praia Grande ap\u00f3s descuido de morador\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\",\"name\":\"Gustavo Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"caption\":\"Gustavo Silva\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/gustavosilva\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Criminosos roubam casa em Praia Grande ap\u00f3s descuido de morador -","description":"Tr\u00eas criminosos roubaram uma casa em Praia Grande ap\u00f3s descuido de seu morador nesta \u00faltima ter\u00e7a-feira (3) no bairro Maracan\u00e3.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/06\/07\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador","og_locale":"pt_BR","og_type":"article","og_title":"Criminosos roubam casa em Praia Grande ap\u00f3s descuido de morador -","og_description":"Tr\u00eas criminosos roubaram uma casa em Praia Grande ap\u00f3s descuido de seu morador nesta \u00faltima ter\u00e7a-feira (3) no bairro Maracan\u00e3.","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/06\/07\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador","og_site_name":"Litoral SP","article_published_time":"2022-06-07T17:05:24+00:00","article_modified_time":"2022-06-07T17:07:28+00:00","og_image":[{"width":581,"height":348,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/06\/1-7.jpg","type":"image\/jpeg"}],"author":"Gustavo Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gustavo Silva","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/06\/07\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/06\/07\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador"},"author":{"name":"Gustavo Silva","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e"},"headline":"Criminosos roubam casa em Praia Grande ap\u00f3s descuido de morador","datePublished":"2022-06-07T17:05:24+00:00","dateModified":"2022-06-07T17:07:28+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/06\/07\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador"},"wordCount":166,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/06\/07\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/06\/1-7.jpg","keywords":["BAIRRO MARACAN\u00c3","furto casa","PRAIA GRANDE"],"articleSection":["Praia Grande"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/06\/07\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/06\/07\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/06\/07\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador","name":"Criminosos roubam casa em Praia Grande ap\u00f3s descuido de morador -","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/06\/07\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/06\/07\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/06\/1-7.jpg","datePublished":"2022-06-07T17:05:24+00:00","dateModified":"2022-06-07T17:07:28+00:00","description":"Tr\u00eas criminosos roubaram uma casa em Praia Grande ap\u00f3s descuido de seu morador nesta \u00faltima ter\u00e7a-feira (3) no bairro Maracan\u00e3.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/06\/07\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/06\/07\/criminosos-roubam-casa-em-praia-grande-apos-descuido-de-morador#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/06\/1-7.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/06\/1-7.jpg","width":581,"height":348,"caption":"Criminosos roubam casa em Praia Grande ap\u00f3s descuido de morador"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e","name":"Gustavo Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","caption":"Gustavo Silva"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/gustavosilva"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/85674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=85674"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/85674\/revisions"}],"predecessor-version":[{"id":85677,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/85674\/revisions\/85677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/85675"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=85674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=85674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=85674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}