{"id":89299,"date":"2022-07-31T13:42:47","date_gmt":"2022-07-31T16:42:47","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/?p=89299"},"modified":"2022-07-31T13:42:47","modified_gmt":"2022-07-31T16:42:47","slug":"carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/07\/31\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas","title":{"rendered":"Carros furam bloqueio para feira livre de Santos e atropelam duas pessoas"},"content":{"rendered":"<p><strong>Duas pessoas foram atropeladas<\/strong> depois que dois carros invadiram o bloqueio para a realiza\u00e7\u00e3o de uma feira livre na Encruzilhada, em <a href=\"https:\/\/www.santos.sp.gov.br\/\">Santos<\/a>. O acidente ocorreu neste domingo (31) e as v\u00edtimas foram socorridas. Um dos motoristas que provocou o acidente foi preso.<\/p>\n<p>A Companhia de Engenharia de Tr\u00e1fego (CET-Santos) informou em nota que o caso aconteceu \u00e0s 3h50, na Rua Vidal Sion, pr\u00f3ximo da Avenida Senador Feij\u00f3. Os carros furaram o bloqueio feito pelos agentes de tr\u00e2nsito para a montagem da feira livre, que ocorre na Avenida Francisco Glic\u00e9rio.<\/p>\n<p>Ap\u00f3s a invas\u00e3o, dois homens que faziam a montagem das barracas ficaram feridos. Uma das v\u00edtimas foi levada para pronto atendimento da Santa Casa de Santos e a outra para Unidade de Pronto Atendimento de Santos (UPA) Central. A prefeitura n\u00e3o informou o estado de sa\u00fade dos dois homens.<\/p>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"34\" data-block-id=\"6\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Equipes da Pol\u00edcia Militar e do Corpo de Bombeiros atuaram no local do acidente. Por conta do caso, a CET-Santos implantou bloqueio, entre a Senador Feij\u00f3 at\u00e9 pr\u00f3ximo \u00e0 esta\u00e7\u00e3o do VLT, para trabalho da per\u00edcia. O local foi liberado por volta das 6h.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"37\" data-block-id=\"8\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Segundo a Pol\u00edcia Militar, o motorista de um dos carros foi detido e encaminhado para a Central de Pol\u00edcia Judici\u00e1ria (CPJ), onde o caso foi registrado. A Pol\u00edcia Civil n\u00e3o informou se o homem continuou preso.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\"><strong>LEIA TAMB\u00c9M<\/strong><\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\"><a href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/07\/30\/delegacia-online-24-horas-para-mulheres-e-disponibilizado-em-bertioga\">Delegacia online 24 horas para mulheres \u00e9 disponibilizado em Bertioga<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Duas pessoas foram atropeladas depois que dois carros invadiram o bloqueio para a realiza\u00e7\u00e3o de uma feira livre na Encruzilhada, em Santos. O acidente ocorreu neste domingo (31) e as v\u00edtimas foram socorridas. Um dos motoristas que provocou o acidente foi preso. A Companhia de Engenharia de Tr\u00e1fego (CET-Santos) informou em nota que o caso &hellip;<\/p>\n","protected":false},"author":6,"featured_media":21737,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,180,5],"tags":[4630,4868,58577,986],"class_list":["post-89299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","category-santos","category-transito","tag-atropelamento","tag-feira-livre","tag-invasao-de-bloqueio","tag-santos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carros furam bloqueio para feira livre de Santos e atropelam duas pessoas - Litoral SP<\/title>\n<meta name=\"description\" content=\"foram atropeladas depois que dois carros invadiram o bloqueio para a realiza\u00e7\u00e3o de uma feira livre na Encruzilhada, em Santos. O acidente\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/07\/31\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carros furam bloqueio para feira livre de Santos e atropelam duas pessoas - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"foram atropeladas depois que dois carros invadiram o bloqueio para a realiza\u00e7\u00e3o de uma feira livre na Encruzilhada, em Santos. O acidente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/07\/31\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-31T16:42:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/01\/delegacia-policia.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"984\" \/>\n\t<meta property=\"og:image:height\" content=\"651\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leonardo Francisco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonardo Francisco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/07\\\/31\\\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/07\\\/31\\\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas\"},\"author\":{\"name\":\"Leonardo Francisco\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/0f0b8a5bdafefe82841e07ae8d81ecb3\"},\"headline\":\"Carros furam bloqueio para feira livre de Santos e atropelam duas pessoas\",\"datePublished\":\"2022-07-31T16:42:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/07\\\/31\\\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas\"},\"wordCount\":259,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/07\\\/31\\\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/01\\\/delegacia-policia.jpeg\",\"keywords\":[\"atropelamento\",\"FEIRA LIVRE\",\"INVAS\u00c3O DE BLOQUEIO\",\"Santos\"],\"articleSection\":[\"Pol\u00edcia\",\"Santos\",\"Tr\u00e2nsito\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/07\\\/31\\\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/07\\\/31\\\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/07\\\/31\\\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas\",\"name\":\"Carros furam bloqueio para feira livre de Santos e atropelam duas pessoas - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/07\\\/31\\\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/07\\\/31\\\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/01\\\/delegacia-policia.jpeg\",\"datePublished\":\"2022-07-31T16:42:47+00:00\",\"description\":\"foram atropeladas depois que dois carros invadiram o bloqueio para a realiza\u00e7\u00e3o de uma feira livre na Encruzilhada, em Santos. O acidente\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/07\\\/31\\\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/07\\\/31\\\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/01\\\/delegacia-policia.jpeg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/01\\\/delegacia-policia.jpeg\",\"width\":984,\"height\":651,\"caption\":\"Foto: Divulga\u00e7\u00e3o\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/0f0b8a5bdafefe82841e07ae8d81ecb3\",\"name\":\"Leonardo Francisco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g\",\"caption\":\"Leonardo Francisco\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/leonardo-francisco\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carros furam bloqueio para feira livre de Santos e atropelam duas pessoas - Litoral SP","description":"foram atropeladas depois que dois carros invadiram o bloqueio para a realiza\u00e7\u00e3o de uma feira livre na Encruzilhada, em Santos. O acidente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/07\/31\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas","og_locale":"pt_BR","og_type":"article","og_title":"Carros furam bloqueio para feira livre de Santos e atropelam duas pessoas - Litoral SP","og_description":"foram atropeladas depois que dois carros invadiram o bloqueio para a realiza\u00e7\u00e3o de uma feira livre na Encruzilhada, em Santos. O acidente","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/07\/31\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas","og_site_name":"Litoral SP","article_published_time":"2022-07-31T16:42:47+00:00","og_image":[{"width":984,"height":651,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/01\/delegacia-policia.jpeg","type":"image\/jpeg"}],"author":"Leonardo Francisco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Leonardo Francisco","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/07\/31\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/07\/31\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas"},"author":{"name":"Leonardo Francisco","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/0f0b8a5bdafefe82841e07ae8d81ecb3"},"headline":"Carros furam bloqueio para feira livre de Santos e atropelam duas pessoas","datePublished":"2022-07-31T16:42:47+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/07\/31\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas"},"wordCount":259,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/07\/31\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/01\/delegacia-policia.jpeg","keywords":["atropelamento","FEIRA LIVRE","INVAS\u00c3O DE BLOQUEIO","Santos"],"articleSection":["Pol\u00edcia","Santos","Tr\u00e2nsito"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/07\/31\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/07\/31\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/07\/31\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas","name":"Carros furam bloqueio para feira livre de Santos e atropelam duas pessoas - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/07\/31\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/07\/31\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/01\/delegacia-policia.jpeg","datePublished":"2022-07-31T16:42:47+00:00","description":"foram atropeladas depois que dois carros invadiram o bloqueio para a realiza\u00e7\u00e3o de uma feira livre na Encruzilhada, em Santos. O acidente","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/07\/31\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/07\/31\/carros-furam-bloqueio-para-feira-livre-de-santos-e-atropelam-duas-pessoas#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/01\/delegacia-policia.jpeg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/01\/delegacia-policia.jpeg","width":984,"height":651,"caption":"Foto: Divulga\u00e7\u00e3o"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/0f0b8a5bdafefe82841e07ae8d81ecb3","name":"Leonardo Francisco","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7358cb406a99b682ec6df1e77e31ae82e63601f6784e8a3df411d72b37864da?s=96&d=mm&r=g","caption":"Leonardo Francisco"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/leonardo-francisco"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/89299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=89299"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/89299\/revisions"}],"predecessor-version":[{"id":89300,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/89299\/revisions\/89300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/21737"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=89299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=89299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=89299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}