{"id":94102,"date":"2022-10-28T14:27:16","date_gmt":"2022-10-28T17:27:16","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/?p=94102"},"modified":"2022-10-28T14:27:16","modified_gmt":"2022-10-28T17:27:16","slug":"servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/10\/28\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao","title":{"rendered":"Servidores de Santos comemoram data especial com muita dan\u00e7a e divers\u00e3o"},"content":{"rendered":"<p>Momentos para servidores de Santos encontrarem os amigos fora do expediente e comemorar. A Noite do Servidor, que n\u00e3o era realizada h\u00e1 dois anos em raz\u00e3o da pandemia de covid-19, levou cerca de 1.200 funcion\u00e1rios da Prefeitura de Santos ao Clube dos Ingleses, na noite de quinta-feira (27).<\/p>\n<p>A festa, organizada pelo Programa de Promo\u00e7\u00e3o \u00e0 Sa\u00fade e Qualidade de Vida do Servidor Municipal &#8211; ComViver, marcou mais uma celebra\u00e7\u00e3o pelo Dia do Servidor P\u00fablico, que ocorre nesta sexta-feira (28).<\/p>\n<p>Ao som da banda Trilha Sonora, a pista de dan\u00e7a foi endere\u00e7o certo de quem adora dan\u00e7ar.<\/p>\n<p>O primeiro som a rolar foi mais lento. Depois, para come\u00e7ar a esquentar o clima, entrou em cena muito forr\u00f3, pagode e sertanejo. E ningu\u00e9m quis ficar parado. A anima\u00e7\u00e3o come\u00e7ou a tomar conta da festa e do sal\u00e3o.<\/p>\n<p>O primeiro baile p\u00f3s-pandemia foi muito aguardado pela professora e orientadora Lu\u00edsa de Moura Sim\u00f5es. Ela trouxe o marido, Humberto Sim\u00f5es, para aproveitar todos os ritmos e comemorar os mais de 30 anos de Prefeitura.<\/p>\n<p>\u201cA gente estava ansioso para retornar e ver os amigos numa confraterniza\u00e7\u00e3o. Todas as festas dos servidores foram \u00f3timas e est\u00e1 tamb\u00e9m ser\u00e1. A gente curte bem um pagode para dan\u00e7ar. Mas o importante mesmo \u00e9 comemorar depois de tudo que passamos nesses \u00faltimos dois anos\u201d.<\/p>\n<p>Ela faz quest\u00e3o de relembrar os motivos da comemora\u00e7\u00e3o. \u201cAl\u00e9m de estarmos vivos, \u00e9 Dia do Servidor. E ser servidor \u00e9 aquele que est\u00e1 se doando. \u00c9 uma profiss\u00e3o, mas voc\u00ea est\u00e1 l\u00e1 para mais, para servir ao outro n\u00e3o importa em qual setor esteja\u201d, acrescenta Lu\u00edsa.<\/p>\n<p>J\u00e1 a agente de sa\u00fade Maria Am\u00e9lia dos Santos combinou com um grupo de amigos do setor de Sa\u00fade e a reuni\u00e3o no baile uniu mais de dez colegas. Tudo era motivo de festa para ela, que estava estreando no evento.<\/p>\n<p>\u201c\u00c9 o primeiro baile que participo. Vim com salto mais baixinho para dan\u00e7ar a noite toda. Gosto de todos os estilos. Est\u00e1 maravilhoso. Tenho 22 anos como agente de sa\u00fade e cinco de servidora. Trabalho no Castelo e adoro cuidar das pessoas\u201d.<\/p>\n<p>Entre um bate-papo e um petisco, a inspetora de alunos Marli Lima Siqueira tamb\u00e9m diz que estava com saudades do Baile do Servidor. Ela est\u00e1 h\u00e1 12 anos na \u00e1rea da Educa\u00e7\u00e3o.<\/p>\n<p>\u201cGosto muito do baile. \u00c9 muito organizado. A gente se diverte bastante e temos que comemorar a data. Trabalho muito. Trabalho em escola, com crian\u00e7a, e dou o meu melhor. Tenho muito orgulho do que fa\u00e7o\u201d.<\/p>\n<p><strong>BRINDES<\/strong><\/p>\n<p>Durante a noite, ainda houve sorteio de diversos brindes. Al\u00e9m de celebrar a data, o evento ainda despertou a solidariedade dos servidores. Para participar do baile, eles trocaram uma lata ou pacote de 400g de leite em p\u00f3 integral pelo convite. Os alimentos arrecadados ser\u00e3o encaminhados ao Fundo Social de Solidariedade de Santos (FSS), que repassar\u00e1 \u00e0s mais de 100 entidades cadastradas na institui\u00e7\u00e3o. No Munic\u00edpio h\u00e1 mais de 11 mil servidores que atuam na Administra\u00e7\u00e3o Municipal.<\/p>\n<p><strong>Leia mais<\/strong><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/10\/28\/investigador-da-policia-civil-e-baleado-durante-operacao-em-santos\">Investigador da Pol\u00edcia Civil \u00e9 baleado durante opera\u00e7\u00e3o em Santos<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Momentos para servidores de Santos encontrarem os amigos fora do expediente e comemorar. A Noite do Servidor, que n\u00e3o era realizada h\u00e1 dois anos em raz\u00e3o da pandemia de covid-19, levou cerca de 1.200 funcion\u00e1rios da Prefeitura de Santos ao Clube dos Ingleses, na noite de quinta-feira (27). A festa, organizada pelo Programa de Promo\u00e7\u00e3o &hellip;<\/p>\n","protected":false},"author":12,"featured_media":94103,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2001,180],"tags":[60479,986,60478],"class_list":["post-94102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-e-musica","category-santos","tag-noite-do-servidor","tag-santos","tag-servidores-de-santos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servidores de Santos comemoram data especial com muita dan\u00e7a e divers\u00e3o - Litoral SP<\/title>\n<meta name=\"description\" content=\"Servidores de Santos comemoram a &#039;Noite do Servidor&#039;, que n\u00e3o era realizada h\u00e1 dois anos em raz\u00e3o da pandemia de covid-19.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/10\/28\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servidores de Santos comemoram data especial com muita dan\u00e7a e divers\u00e3o - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"Servidores de Santos comemoram a &#039;Noite do Servidor&#039;, que n\u00e3o era realizada h\u00e1 dois anos em raz\u00e3o da pandemia de covid-19.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/10\/28\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-28T17:27:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/10\/WhatsApp-Image-2022-10-28-at-13.18.05.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gustavo Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/10\\\/28\\\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/10\\\/28\\\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao\"},\"author\":{\"name\":\"Gustavo Silva\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\"},\"headline\":\"Servidores de Santos comemoram data especial com muita dan\u00e7a e divers\u00e3o\",\"datePublished\":\"2022-10-28T17:27:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/10\\\/28\\\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao\"},\"wordCount\":547,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/10\\\/28\\\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/10\\\/WhatsApp-Image-2022-10-28-at-13.18.05.jpeg\",\"keywords\":[\"Noite do Servidor\",\"Santos\",\"Servidores de Santos\"],\"articleSection\":[\"Cultura e M\u00fasica\",\"Santos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/10\\\/28\\\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/10\\\/28\\\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/10\\\/28\\\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao\",\"name\":\"Servidores de Santos comemoram data especial com muita dan\u00e7a e divers\u00e3o - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/10\\\/28\\\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/10\\\/28\\\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/10\\\/WhatsApp-Image-2022-10-28-at-13.18.05.jpeg\",\"datePublished\":\"2022-10-28T17:27:16+00:00\",\"description\":\"Servidores de Santos comemoram a 'Noite do Servidor', que n\u00e3o era realizada h\u00e1 dois anos em raz\u00e3o da pandemia de covid-19.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/10\\\/28\\\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2022\\\/10\\\/28\\\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/10\\\/WhatsApp-Image-2022-10-28-at-13.18.05.jpeg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/10\\\/WhatsApp-Image-2022-10-28-at-13.18.05.jpeg\",\"width\":1600,\"height\":1067,\"caption\":\"Servidores de Santos comemoram data especial com muita dan\u00e7a e divers\u00e3o\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\",\"name\":\"Gustavo Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"caption\":\"Gustavo Silva\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/gustavosilva\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servidores de Santos comemoram data especial com muita dan\u00e7a e divers\u00e3o - Litoral SP","description":"Servidores de Santos comemoram a 'Noite do Servidor', que n\u00e3o era realizada h\u00e1 dois anos em raz\u00e3o da pandemia de covid-19.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/10\/28\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao","og_locale":"pt_BR","og_type":"article","og_title":"Servidores de Santos comemoram data especial com muita dan\u00e7a e divers\u00e3o - Litoral SP","og_description":"Servidores de Santos comemoram a 'Noite do Servidor', que n\u00e3o era realizada h\u00e1 dois anos em raz\u00e3o da pandemia de covid-19.","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/10\/28\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao","og_site_name":"Litoral SP","article_published_time":"2022-10-28T17:27:16+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/10\/WhatsApp-Image-2022-10-28-at-13.18.05.jpeg","type":"image\/jpeg"}],"author":"Gustavo Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gustavo Silva","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/10\/28\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/10\/28\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao"},"author":{"name":"Gustavo Silva","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e"},"headline":"Servidores de Santos comemoram data especial com muita dan\u00e7a e divers\u00e3o","datePublished":"2022-10-28T17:27:16+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/10\/28\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao"},"wordCount":547,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/10\/28\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/10\/WhatsApp-Image-2022-10-28-at-13.18.05.jpeg","keywords":["Noite do Servidor","Santos","Servidores de Santos"],"articleSection":["Cultura e M\u00fasica","Santos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/10\/28\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/10\/28\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/10\/28\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao","name":"Servidores de Santos comemoram data especial com muita dan\u00e7a e divers\u00e3o - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/10\/28\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/10\/28\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/10\/WhatsApp-Image-2022-10-28-at-13.18.05.jpeg","datePublished":"2022-10-28T17:27:16+00:00","description":"Servidores de Santos comemoram a 'Noite do Servidor', que n\u00e3o era realizada h\u00e1 dois anos em raz\u00e3o da pandemia de covid-19.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/10\/28\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2022\/10\/28\/servidores-de-santos-comemoram-data-especial-com-muita-danca-e-diversao#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/10\/WhatsApp-Image-2022-10-28-at-13.18.05.jpeg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2022\/10\/WhatsApp-Image-2022-10-28-at-13.18.05.jpeg","width":1600,"height":1067,"caption":"Servidores de Santos comemoram data especial com muita dan\u00e7a e divers\u00e3o"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e","name":"Gustavo Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","caption":"Gustavo Silva"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/gustavosilva"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/94102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=94102"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/94102\/revisions"}],"predecessor-version":[{"id":94104,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/94102\/revisions\/94104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/94103"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=94102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=94102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=94102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}