{"id":951,"date":"2020-12-07T18:50:35","date_gmt":"2020-12-07T21:50:35","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/07\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa\/"},"modified":"2020-12-07T18:53:12","modified_gmt":"2020-12-07T21:53:12","slug":"jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/07\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa","title":{"rendered":"Jovens do sexo masculino se arriscam mais em ultrapassagem perigosa"},"content":{"rendered":"<p>Estudo da Universidade de S\u00e3o Paulo (USP) mostrou que homens de 18 a 25 anos tem probabilidade 42% maior de se arriscar em manobras de ultrapassagem do que mulheres e mais homens velhos. As pistas simples s\u00e3o consideradas as mais perigosas das rodovias. O trabalho foi desenvolvido pela Escola de Engenharia da Universidade de S\u00e3o Carlos.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1395747&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1395747&amp;o=node\" \/><\/p>\n<p>Foram convidados 100 volunt\u00e1rios de todas as faixas et\u00e1rias e com habilita\u00e7\u00e3o para participar de experimentos em um simulador de dire\u00e7\u00e3o, capaz de reproduzir virtualmente qualquer tipo de rodovia de forma realista. Uma rodovia de pista simples com m\u00e3o dupla foi projetada para a pesquisa, propondo aos motoristas que fizessem as ultrapassagens no momento em que julgassem adequado.<\/p>\n<p>\u201cA pesquisa comprovou que jovens do sexo masculino tendem a se arriscar mais neste tipo de ultrapassagem perigosa. Observamos que eles colavam bastante na traseira do ve\u00edculo da frente e realizavam v\u00e1rias tentativas malsucedidas de ultrapassagem, tendo que retornar \u00e0 posi\u00e7\u00e3o de origem. Muitas vezes eles faziam ultrapassagens enquanto um ve\u00edculo vinha no sentido oposto, ao contr\u00e1rio das mulheres, que esperavam o carro passar\u201d, disse a professora Ana Paula Larocca, do Departamento de Engenharia de Transportes (STT) da universidade e coordenadora do estudo.<\/p>\n<p>Segundo a professora, esse comportamento mais agressivo dos homens dessa faixa et\u00e1ria pode ser explicado por um maior excesso de confian\u00e7a. Sendo assim, acaba elevando o risco da condu\u00e7\u00e3o. \u201cTanto \u00e9 que eles fazem parte do grupo que mais se envolve em acidentes.\u201d A pesquisa mostrou ainda que homens da faixa et\u00e1ria seguinte, de 25 a 35 anos, t\u00eam 36% mais chances de se arriscar em ultrapassagens em pista simples do que homens mais velhos e mulheres.<\/p>\n<p>&nbsp;<\/p>\n<h3>Dados apresentados e divulgados<\/h3>\n<p>Os resultados da pesquisa geraram dois artigos que foram publicados em<a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S1369847819302955%20e%20https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S1369847820305003\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a0revista cient\u00edfica internacional<\/a>. O estudo faz parte da tese de doutorado de Aurenice da Cruz Figueira.<\/p>\n<p>Dados apresentados pelos pesquisadores, com base no banco de dados da Pol\u00edcia Rodovi\u00e1ria Federal (Datatram), mostram que 94% dos condutores envolvidos anualmente em acidentes de colis\u00e3o frontal no Brasil s\u00e3o homens. Sendo assim,\u00a0 entre 2008 e 2018 ocorreram 15 mil mortes, sendo que motoristas entre 20 e 50 anos s\u00e3o os que mais aparecem nas trag\u00e9dias.<\/p>\n<p>\u201cNo mesmo per\u00edodo, ocorreram ao todo no pa\u00eds 1,5 milh\u00e3o de acidentes em rodovias federais e, embora as colis\u00f5es frontais representem apenas 3,2% do total. Elas s\u00e3o respons\u00e1veis por 31% das mortes: em dez anos, foram registrados 25 mil \u00f3bitos. Al\u00e9m de 17 mil feridos graves e 25 mil feridos leves\u201d, divulgaram os pesquisadores.<\/p>\n<p>Para a coordenadora do estudo, resultados como os deste trabalho podem colaborar para a cria\u00e7\u00e3o de campanhas de conscientiza\u00e7\u00e3o. Al\u00e9m de est\u00edmulo ao bom comportamento e de percep\u00e7\u00e3o de risco voltadas a esse p\u00fablico. Outras poss\u00edveis a\u00e7\u00f5es seriam a instala\u00e7\u00e3o de novas placas, estabelecimento de normas t\u00e9cnicas, obras de infraestrutura e at\u00e9 a reformula\u00e7\u00e3o da geometria da rodovia. (agenciabrasil)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>LEIA TAMB\u00c9M<\/strong><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2020\/12\/07\/conheca-as-curiosidades-e-lendas-sobre-a-harley-davidson\/\">Conhe\u00e7a as curiosidades e lendas sobre a Harley-Davidson<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudo da Universidade de S\u00e3o Paulo (USP) mostrou que homens de 18 a 25 anos tem probabilidade 42% maior de se arriscar em manobras de ultrapassagem do que mulheres e mais homens velhos. As pistas simples s\u00e3o consideradas as mais perigosas das rodovias. O trabalho foi desenvolvido pela Escola de Engenharia da Universidade de S\u00e3o &hellip;<\/p>\n","protected":false},"author":5,"featured_media":952,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[1720,3595,3596,3597],"class_list":["post-951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-transito","tag-estudo","tag-homens-se-arriscam-mais","tag-probabilidades","tag-ultrapassagem"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jovens do sexo masculino se arriscam mais em ultrapassagem perigosa - Litoral SP<\/title>\n<meta name=\"description\" content=\"Estudo da Universidade de S\u00e3o Paulo (USP) mostrou que homens de 18 a 25 anos tem probabilidade 42% maior de se arriscar em manobras\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/07\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jovens do sexo masculino se arriscam mais em ultrapassagem perigosa - Litoral SP\" \/>\n<meta property=\"og:description\" content=\"Estudo da Universidade de S\u00e3o Paulo (USP) mostrou que homens de 18 a 25 anos tem probabilidade 42% maior de se arriscar em manobras\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/07\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa\" \/>\n<meta property=\"og:site_name\" content=\"Litoral SP\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-07T21:50:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-07T21:53:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/12\/rodovias.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Patr\u00edcia Prado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patr\u00edcia Prado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/07\\\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/07\\\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa\"},\"author\":{\"name\":\"Patr\u00edcia Prado\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/e1b0bd8c2637e2c1b6ddcbc2c33b116f\"},\"headline\":\"Jovens do sexo masculino se arriscam mais em ultrapassagem perigosa\",\"datePublished\":\"2020-12-07T21:50:35+00:00\",\"dateModified\":\"2020-12-07T21:53:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/07\\\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa\"},\"wordCount\":520,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/07\\\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/12\\\/rodovias.jpg\",\"keywords\":[\"ESTUDO\",\"HOMENS SE ARRISCAM MAIS\",\"PROBABILIDADES\",\"ULTRAPASSAGEM\"],\"articleSection\":[\"Tr\u00e2nsito\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/07\\\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/07\\\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/07\\\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa\",\"name\":\"Jovens do sexo masculino se arriscam mais em ultrapassagem perigosa - Litoral SP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/07\\\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/07\\\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/12\\\/rodovias.jpg\",\"datePublished\":\"2020-12-07T21:50:35+00:00\",\"dateModified\":\"2020-12-07T21:53:12+00:00\",\"description\":\"Estudo da Universidade de S\u00e3o Paulo (USP) mostrou que homens de 18 a 25 anos tem probabilidade 42% maior de se arriscar em manobras\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/07\\\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/2020\\\/12\\\/07\\\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/12\\\/rodovias.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/12\\\/rodovias.jpg\",\"width\":1170,\"height\":700,\"caption\":\"S\u00c3O PAULO, SP, BRASIL, 11-05-2013, 11h30: Movimenta\u00e7\u00e3o na rodovia dos Bandeirantes, em S\u00e3o Paulo. (Foto: Marcelo Camargo\\\/ABr)\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"name\":\"Litoral SP\",\"description\":\"Rede NoticiaZ\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#organization\",\"name\":\"Litoral SP\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/11\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Litoral SP\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/#\\\/schema\\\/person\\\/e1b0bd8c2637e2c1b6ddcbc2c33b116f\",\"name\":\"Patr\u00edcia Prado\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92e358bef22cfcec15e054ae4d9fee04dadf0c772dc4a17b382b8a34a15354c2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92e358bef22cfcec15e054ae4d9fee04dadf0c772dc4a17b382b8a34a15354c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92e358bef22cfcec15e054ae4d9fee04dadf0c772dc4a17b382b8a34a15354c2?s=96&d=mm&r=g\",\"caption\":\"Patr\u00edcia Prado\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/litoralsp\\\/author\\\/patricia-prado\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jovens do sexo masculino se arriscam mais em ultrapassagem perigosa - Litoral SP","description":"Estudo da Universidade de S\u00e3o Paulo (USP) mostrou que homens de 18 a 25 anos tem probabilidade 42% maior de se arriscar em manobras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/07\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa","og_locale":"pt_BR","og_type":"article","og_title":"Jovens do sexo masculino se arriscam mais em ultrapassagem perigosa - Litoral SP","og_description":"Estudo da Universidade de S\u00e3o Paulo (USP) mostrou que homens de 18 a 25 anos tem probabilidade 42% maior de se arriscar em manobras","og_url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/07\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa","og_site_name":"Litoral SP","article_published_time":"2020-12-07T21:50:35+00:00","article_modified_time":"2020-12-07T21:53:12+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/12\/rodovias.jpg","type":"image\/jpeg"}],"author":"Patr\u00edcia Prado","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Patr\u00edcia Prado","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/07\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/07\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa"},"author":{"name":"Patr\u00edcia Prado","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/e1b0bd8c2637e2c1b6ddcbc2c33b116f"},"headline":"Jovens do sexo masculino se arriscam mais em ultrapassagem perigosa","datePublished":"2020-12-07T21:50:35+00:00","dateModified":"2020-12-07T21:53:12+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/07\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa"},"wordCount":520,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/07\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/12\/rodovias.jpg","keywords":["ESTUDO","HOMENS SE ARRISCAM MAIS","PROBABILIDADES","ULTRAPASSAGEM"],"articleSection":["Tr\u00e2nsito"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/07\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/07\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/07\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa","name":"Jovens do sexo masculino se arriscam mais em ultrapassagem perigosa - Litoral SP","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/07\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/07\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/12\/rodovias.jpg","datePublished":"2020-12-07T21:50:35+00:00","dateModified":"2020-12-07T21:53:12+00:00","description":"Estudo da Universidade de S\u00e3o Paulo (USP) mostrou que homens de 18 a 25 anos tem probabilidade 42% maior de se arriscar em manobras","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/07\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/2020\/12\/07\/jovens-do-sexo-masculino-se-arriscam-mais-em-ultrapassagem-perigosa#primaryimage","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/12\/rodovias.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/12\/rodovias.jpg","width":1170,"height":700,"caption":"S\u00c3O PAULO, SP, BRASIL, 11-05-2013, 11h30: Movimenta\u00e7\u00e3o na rodovia dos Bandeirantes, em S\u00e3o Paulo. (Foto: Marcelo Camargo\/ABr)"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#website","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","name":"Litoral SP","description":"Rede NoticiaZ","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/litoralsp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#organization","name":"Litoral SP","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-content\/uploads\/sites\/3\/2020\/11\/logo.jpg","width":400,"height":250,"caption":"Litoral SP"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/litoralsp\/#\/schema\/person\/e1b0bd8c2637e2c1b6ddcbc2c33b116f","name":"Patr\u00edcia Prado","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/92e358bef22cfcec15e054ae4d9fee04dadf0c772dc4a17b382b8a34a15354c2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/92e358bef22cfcec15e054ae4d9fee04dadf0c772dc4a17b382b8a34a15354c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/92e358bef22cfcec15e054ae4d9fee04dadf0c772dc4a17b382b8a34a15354c2?s=96&d=mm&r=g","caption":"Patr\u00edcia Prado"},"url":"https:\/\/redenoticiaz.com.br\/litoralsp\/author\/patricia-prado"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/comments?post=951"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/951\/revisions"}],"predecessor-version":[{"id":953,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/posts\/951\/revisions\/953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media\/952"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/media?parent=951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/categories?post=951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/litoralsp\/wp-json\/wp\/v2\/tags?post=951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}