{"id":107874,"date":"2023-07-07T09:47:21","date_gmt":"2023-07-07T12:47:21","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/?p=107874"},"modified":"2023-07-07T09:47:21","modified_gmt":"2023-07-07T12:47:21","slug":"relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/07\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes","title":{"rendered":"Relat\u00f3rio do Conselho Tutelar revela dados alarmantes sobre crian\u00e7as e adolescentes"},"content":{"rendered":"<p>Relat\u00f3rio do Conselho Tutelar de Gua\u00edra traz as estat\u00edsticas de atendimento em junho de 2023, revelando dados que preocupam. No per\u00edodo, foram assistidas 84 crian\u00e7as, 88 adolescentes e 104 adultos, apontando para uma demanda significativa no munic\u00edpio. As ocorr\u00eancias relacionadas a problemas familiares s\u00e3o especialmente alarmantes, com registros de 15 casos de maus tratos, 56 problemas de comportamento, 18 situa\u00e7\u00f5es de abandono intelectual e 12 supostos estupros de vulner\u00e1veis.<\/p>\n<div class=\"flex-1 overflow-hidden\">\n<div class=\"react-scroll-to-bottom--css-tueie-79elbk h-full dark:bg-gray-800\">\n<div class=\"react-scroll-to-bottom--css-tueie-1n7m0yu\">\n<div class=\"flex flex-col text-sm dark:bg-gray-800\">\n<div class=\"group w-full text-gray-800 dark:text-gray-100 border-b border-black\/10 dark:border-gray-900\/50 bg-gray-50 dark:bg-[#444654]\">\n<div class=\"flex p-4 gap-4 text-base md:gap-6 md:max-w-2xl lg:max-w-[38rem] xl:max-w-3xl md:py-6 lg:px-0 m-auto\">\n<div class=\"relative flex w-[calc(100%-50px)] flex-col gap-1 md:gap-3 lg:w-[calc(100%-115px)]\">\n<div class=\"flex flex-grow flex-col gap-3\">\n<div class=\"min-h-[20px] flex items-start overflow-x-auto whitespace-pre-wrap break-words flex-col gap-4\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>Al\u00e9m disso, o relat\u00f3rio apresento pela pagina sefeguaira, mostrou outros dados preocupantes, como 1 caso de prostitui\u00e7\u00e3o envolvendo a genitora, 1 caso de prostitui\u00e7\u00e3o envolvendo um adolescente, al\u00e9m de 2 pais usu\u00e1rios de drogas e 6 pais com problemas relacionados ao consumo de \u00e1lcool. Tamb\u00e9m foram registrados 14 casos de drogadi\u00e7\u00e3o e 2 casos de bullying.<\/p>\n<p>LEIA MAIS<\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/barretos-regiao\/sp\/2023\/07\/07\/policia-encontra-armas-de-fogo-em-casa-de-suspeito-de-tentativa-de-homicidio\">Pol\u00edcia encontra armas de fogo em casa de suspeito de tentativa de homic\u00eddio<\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"group w-full text-gray-800 dark:text-gray-100 border-b border-black\/10 dark:border-gray-900\/50 dark:bg-gray-800\">\n<div class=\"flex p-4 gap-4 text-base md:gap-6 md:max-w-2xl lg:max-w-[38rem] xl:max-w-3xl md:py-6 lg:px-0 m-auto\">\n<div class=\"flex-shrink-0 flex flex-col relative items-end\">\n<div class=\"text-xs flex items-center justify-center gap-1 invisible absolute left-0 top-2 -ml-4 -translate-x-full group-hover:visible !invisible\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Relat\u00f3rio do Conselho Tutelar de Gua\u00edra traz as estat\u00edsticas de atendimento em junho de 2023, revelando dados que preocupam. No per\u00edodo, foram assistidas 84 crian\u00e7as, 88 adolescentes e 104 adultos, apontando para uma demanda significativa no munic\u00edpio. As ocorr\u00eancias relacionadas a problemas familiares s\u00e3o especialmente alarmantes, com registros de 15 casos de maus tratos, 56 &hellip;<\/p>\n","protected":false},"author":30,"featured_media":107875,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[22433,13564,16890,25393],"class_list":["post-107874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-bullying","tag-conselho-tutelar","tag-criancas-e-adolescentes","tag-ocorrencias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Relat\u00f3rio do Conselho Tutelar revela dados alarmantes sobre crian\u00e7as e adolescentes - Ribeir\u00e3o Preto e Regi\u00e3o<\/title>\n<meta name=\"description\" content=\"Relat\u00f3rio do Conselho Tutelar de Gua\u00edra traz as estat\u00edsticas de atendimento em junho de 2023, revelando dados que preocupam.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/07\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Relat\u00f3rio do Conselho Tutelar revela dados alarmantes sobre crian\u00e7as e adolescentes - Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Relat\u00f3rio do Conselho Tutelar de Gua\u00edra traz as estat\u00edsticas de atendimento em junho de 2023, revelando dados que preocupam.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/07\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes\" \/>\n<meta property=\"og:site_name\" content=\"Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/redenoticiaz.barretos\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-07T12:47:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/07\/Cidade-de-Guaira.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1640\" \/>\n\t<meta property=\"og:image:height\" content=\"924\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Carina Reifonas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:site\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carina Reifonas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/07\\\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/07\\\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes\"},\"author\":{\"name\":\"Carina Reifonas\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/person\\\/1f84d6e94e6a62d2d81199d7503e9e90\"},\"headline\":\"Relat\u00f3rio do Conselho Tutelar revela dados alarmantes sobre crian\u00e7as e adolescentes\",\"datePublished\":\"2023-07-07T12:47:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/07\\\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes\"},\"wordCount\":160,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/07\\\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/07\\\/Cidade-de-Guaira.png\",\"keywords\":[\"bullying\",\"conselho tutelar\",\"CRIAN\u00c7AS E ADOLESCENTES\",\"ocorr\u00eancias\"],\"articleSection\":[\"Pol\u00edcia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/07\\\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/07\\\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/07\\\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes\",\"name\":\"Relat\u00f3rio do Conselho Tutelar revela dados alarmantes sobre crian\u00e7as e adolescentes - Ribeir\u00e3o Preto e Regi\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/07\\\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/07\\\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/07\\\/Cidade-de-Guaira.png\",\"datePublished\":\"2023-07-07T12:47:21+00:00\",\"description\":\"Relat\u00f3rio do Conselho Tutelar de Gua\u00edra traz as estat\u00edsticas de atendimento em junho de 2023, revelando dados que preocupam.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/07\\\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/07\\\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/07\\\/Cidade-de-Guaira.png\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/07\\\/Cidade-de-Guaira.png\",\"width\":1640,\"height\":924,\"caption\":\"Relat\u00f3rio do Conselho Tutelar revela dados alarmantes sobre crian\u00e7as e adolescentes. Cr\u00e9dito: Reprodu\u00e7\u00e3o\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"description\":\"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Ribeir\u00e3o Preto e Regi\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/redenoticiaz.barretos\",\"https:\\\/\\\/x.com\\\/RN_barretos\",\"https:\\\/\\\/www.instagram.com\\\/redenoticiaz.barretos\\\/?igshid=YmMyMTA2M2Y\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rede-noticiaz-barretos-e-regio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/person\\\/1f84d6e94e6a62d2d81199d7503e9e90\",\"name\":\"Carina Reifonas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"caption\":\"Carina Reifonas\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/author\\\/carinareifonas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Relat\u00f3rio do Conselho Tutelar revela dados alarmantes sobre crian\u00e7as e adolescentes - Ribeir\u00e3o Preto e Regi\u00e3o","description":"Relat\u00f3rio do Conselho Tutelar de Gua\u00edra traz as estat\u00edsticas de atendimento em junho de 2023, revelando dados que preocupam.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/07\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes","og_locale":"pt_BR","og_type":"article","og_title":"Relat\u00f3rio do Conselho Tutelar revela dados alarmantes sobre crian\u00e7as e adolescentes - Ribeir\u00e3o Preto e Regi\u00e3o","og_description":"Relat\u00f3rio do Conselho Tutelar de Gua\u00edra traz as estat\u00edsticas de atendimento em junho de 2023, revelando dados que preocupam.","og_url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/07\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes","og_site_name":"Ribeir\u00e3o Preto e Regi\u00e3o","article_publisher":"https:\/\/m.facebook.com\/redenoticiaz.barretos","article_published_time":"2023-07-07T12:47:21+00:00","og_image":[{"width":1640,"height":924,"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/07\/Cidade-de-Guaira.png","type":"image\/png"}],"author":"Carina Reifonas","twitter_card":"summary_large_image","twitter_creator":"@RN_barretos","twitter_site":"@RN_barretos","twitter_misc":{"Escrito por":"Carina Reifonas","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/07\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/07\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes"},"author":{"name":"Carina Reifonas","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/person\/1f84d6e94e6a62d2d81199d7503e9e90"},"headline":"Relat\u00f3rio do Conselho Tutelar revela dados alarmantes sobre crian\u00e7as e adolescentes","datePublished":"2023-07-07T12:47:21+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/07\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes"},"wordCount":160,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/07\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/07\/Cidade-de-Guaira.png","keywords":["bullying","conselho tutelar","CRIAN\u00c7AS E ADOLESCENTES","ocorr\u00eancias"],"articleSection":["Pol\u00edcia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/07\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/07\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/07\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes","name":"Relat\u00f3rio do Conselho Tutelar revela dados alarmantes sobre crian\u00e7as e adolescentes - Ribeir\u00e3o Preto e Regi\u00e3o","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/07\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/07\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/07\/Cidade-de-Guaira.png","datePublished":"2023-07-07T12:47:21+00:00","description":"Relat\u00f3rio do Conselho Tutelar de Gua\u00edra traz as estat\u00edsticas de atendimento em junho de 2023, revelando dados que preocupam.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/07\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/07\/relatorio-do-conselho-tutelar-revela-dados-alarmantes-sobre-criancas-e-adolescentes#primaryimage","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/07\/Cidade-de-Guaira.png","contentUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/07\/Cidade-de-Guaira.png","width":1640,"height":924,"caption":"Relat\u00f3rio do Conselho Tutelar revela dados alarmantes sobre crian\u00e7as e adolescentes. Cr\u00e9dito: Reprodu\u00e7\u00e3o"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","name":"Ribeir\u00e3o Preto e Regi\u00e3o","description":"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization","name":"Ribeir\u00e3o Preto e Regi\u00e3o","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","width":400,"height":250,"caption":"Ribeir\u00e3o Preto e Regi\u00e3o"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/redenoticiaz.barretos","https:\/\/x.com\/RN_barretos","https:\/\/www.instagram.com\/redenoticiaz.barretos\/?igshid=YmMyMTA2M2Y","https:\/\/www.linkedin.com\/company\/rede-noticiaz-barretos-e-regio\/"]},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/person\/1f84d6e94e6a62d2d81199d7503e9e90","name":"Carina Reifonas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","caption":"Carina Reifonas"},"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/author\/carinareifonas"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/107874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/comments?post=107874"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/107874\/revisions"}],"predecessor-version":[{"id":107876,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/107874\/revisions\/107876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media\/107875"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media?parent=107874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/categories?post=107874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/tags?post=107874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}