{"id":108616,"date":"2023-07-25T15:04:30","date_gmt":"2023-07-25T18:04:30","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/sp\/2023\/07\/25\/papa-francisco-apoia-pessoa-transgenero"},"modified":"2023-07-25T15:05:09","modified_gmt":"2023-07-25T18:05:09","slug":"papa-francisco-apoia-pessoa-transgenero","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/25\/papa-francisco-apoia-pessoa-transgenero","title":{"rendered":"Papa Francisco apoia pessoa transg\u00eanero"},"content":{"rendered":"<p>O papa Francisco disse a uma pessoa transg\u00eanero que &#8220;Deus nos ama como somos&#8221;. Os coment\u00e1rios, divulgados pela m\u00eddia do Vaticano nesta ter\u00e7a-feira (25), ocorreram em um\u00a0<em>podcast<\/em>\u00a0no qual Francisco ouviu e respondeu a mensagens de \u00e1udio de jovens antes de um festival da juventude cat\u00f3lica do qual ele participar\u00e1 em Portugal na pr\u00f3xima semana.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1545423&amp;o=node\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1545423&amp;o=node\" \/><\/p>\n<p>De acordo com as informa\u00e7\u00f5es, um dos jovens era Giona, italiana de 20 e poucos anos que disse estar &#8220;dividida pela dicotomia entre a f\u00e9 [cat\u00f3lica] e a identidade transg\u00eanero&#8221;.<\/p>\n<p>Ainda de acordo com as informa\u00e7\u00f5es, Francisco respondeu que &#8220;o Senhor sempre caminha conosco&#8230; Mesmo que sejamos pecadores, Ele se aproxima para nos ajudar. O Senhor nos ama como somos, este \u00e9 o amor louco de Deus&#8221;.<\/p>\n<p>A Igreja Cat\u00f3lica ensina que os membros da comunidade LGBT devem ser tratados com respeito, compaix\u00e3o e sensibilidade, e seus direitos humanos respeitados.<\/p>\n<p>Se a Igreja pode e deve ser mais acolhedora com as pessoas LGBT, por exemplo, oferecendo b\u00ean\u00e7\u00e3os para uni\u00f5es do mesmo sexo, \u00e9 um tema particularmente delicado.<\/p>\n<p>Francisco disse a famosa frase &#8220;quem sou eu para julgar&#8221; ao responder uma pergunta especifica sobre homossexuais, e classificou as leis que criminalizam membros da comunidade LGBT como um pecado e uma injusti\u00e7a.<\/p>\n<p><strong>Leia mais<\/strong><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/litoralsp\/2023\/07\/25\/nova-musa-da-privacy-andressa-urach-viraliza-respondendo-seguidores-nas-redes-sociais\">Nova Musa da Privacy: Andressa Urach viraliza respondendo seguidores nas redes sociais<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O papa Francisco disse a uma pessoa transg\u00eanero que &#8220;Deus nos ama como somos&#8221;. Os coment\u00e1rios, divulgados pela m\u00eddia do Vaticano nesta ter\u00e7a-feira (25), ocorreram em um\u00a0podcast\u00a0no qual Francisco ouviu e respondeu a mensagens de \u00e1udio de jovens antes de um festival da juventude cat\u00f3lica do qual ele participar\u00e1 em Portugal na pr\u00f3xima semana. De &hellip;<\/p>\n","protected":false},"author":12,"featured_media":108617,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[28207,19862,23547,28208],"class_list":["post-108616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-apoio-gay-papa","tag-papa","tag-papa-francisco","tag-pessoas-lgbt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Papa Francisco apoia pessoa transg\u00eanero - Ribeir\u00e3o Preto e Regi\u00e3o<\/title>\n<meta name=\"description\" content=\"um dos jovens era Giona, italiana de 20 e poucos anos que disse estar &quot;dividida pela dicotomia entre a f\u00e9 [cat\u00f3lica] e a identidade transg\u00eanero&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/25\/papa-francisco-apoia-pessoa-transgenero\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papa Francisco apoia pessoa transg\u00eanero - Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"og:description\" content=\"um dos jovens era Giona, italiana de 20 e poucos anos que disse estar &quot;dividida pela dicotomia entre a f\u00e9 [cat\u00f3lica] e a identidade transg\u00eanero&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/25\/papa-francisco-apoia-pessoa-transgenero\" \/>\n<meta property=\"og:site_name\" content=\"Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/redenoticiaz.barretos\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-25T18:04:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-25T18:05:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/07\/2022-09-05t134733z_1_lynxmpei840fv_rtroptp_4_pope-cardinals-mass.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gustavo Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:site\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/25\\\/papa-francisco-apoia-pessoa-transgenero#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/25\\\/papa-francisco-apoia-pessoa-transgenero\"},\"author\":{\"name\":\"Gustavo Silva\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\"},\"headline\":\"Papa Francisco apoia pessoa transg\u00eanero\",\"datePublished\":\"2023-07-25T18:04:30+00:00\",\"dateModified\":\"2023-07-25T18:05:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/25\\\/papa-francisco-apoia-pessoa-transgenero\"},\"wordCount\":238,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/25\\\/papa-francisco-apoia-pessoa-transgenero#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/07\\\/2022-09-05t134733z_1_lynxmpei840fv_rtroptp_4_pope-cardinals-mass.jpg\",\"keywords\":[\"apoio gay papa\",\"papa\",\"PAPA FRANCISCO\",\"pessoas LGBT\"],\"articleSection\":[\"Mundo\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/25\\\/papa-francisco-apoia-pessoa-transgenero#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/25\\\/papa-francisco-apoia-pessoa-transgenero\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/25\\\/papa-francisco-apoia-pessoa-transgenero\",\"name\":\"Papa Francisco apoia pessoa transg\u00eanero - Ribeir\u00e3o Preto e Regi\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/25\\\/papa-francisco-apoia-pessoa-transgenero#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/25\\\/papa-francisco-apoia-pessoa-transgenero#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/07\\\/2022-09-05t134733z_1_lynxmpei840fv_rtroptp_4_pope-cardinals-mass.jpg\",\"datePublished\":\"2023-07-25T18:04:30+00:00\",\"dateModified\":\"2023-07-25T18:05:09+00:00\",\"description\":\"um dos jovens era Giona, italiana de 20 e poucos anos que disse estar \\\"dividida pela dicotomia entre a f\u00e9 [cat\u00f3lica] e a identidade transg\u00eanero\\\"\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/25\\\/papa-francisco-apoia-pessoa-transgenero\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/07\\\/25\\\/papa-francisco-apoia-pessoa-transgenero#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/07\\\/2022-09-05t134733z_1_lynxmpei840fv_rtroptp_4_pope-cardinals-mass.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/07\\\/2022-09-05t134733z_1_lynxmpei840fv_rtroptp_4_pope-cardinals-mass.jpg\",\"width\":1170,\"height\":700,\"caption\":\"Papa Francisco apoia pessoa transg\u00eanero\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"description\":\"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Ribeir\u00e3o Preto e Regi\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/redenoticiaz.barretos\",\"https:\\\/\\\/x.com\\\/RN_barretos\",\"https:\\\/\\\/www.instagram.com\\\/redenoticiaz.barretos\\\/?igshid=YmMyMTA2M2Y\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rede-noticiaz-barretos-e-regio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/person\\\/16057b37a3c0ee6b096d7f887c566e2e\",\"name\":\"Gustavo Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g\",\"caption\":\"Gustavo Silva\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/author\\\/gustavosilva\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papa Francisco apoia pessoa transg\u00eanero - Ribeir\u00e3o Preto e Regi\u00e3o","description":"um dos jovens era Giona, italiana de 20 e poucos anos que disse estar \"dividida pela dicotomia entre a f\u00e9 [cat\u00f3lica] e a identidade transg\u00eanero\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/25\/papa-francisco-apoia-pessoa-transgenero","og_locale":"pt_BR","og_type":"article","og_title":"Papa Francisco apoia pessoa transg\u00eanero - Ribeir\u00e3o Preto e Regi\u00e3o","og_description":"um dos jovens era Giona, italiana de 20 e poucos anos que disse estar \"dividida pela dicotomia entre a f\u00e9 [cat\u00f3lica] e a identidade transg\u00eanero\"","og_url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/25\/papa-francisco-apoia-pessoa-transgenero","og_site_name":"Ribeir\u00e3o Preto e Regi\u00e3o","article_publisher":"https:\/\/m.facebook.com\/redenoticiaz.barretos","article_published_time":"2023-07-25T18:04:30+00:00","article_modified_time":"2023-07-25T18:05:09+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/07\/2022-09-05t134733z_1_lynxmpei840fv_rtroptp_4_pope-cardinals-mass.jpg","type":"image\/jpeg"}],"author":"Gustavo Silva","twitter_card":"summary_large_image","twitter_creator":"@RN_barretos","twitter_site":"@RN_barretos","twitter_misc":{"Escrito por":"Gustavo Silva","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/25\/papa-francisco-apoia-pessoa-transgenero#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/25\/papa-francisco-apoia-pessoa-transgenero"},"author":{"name":"Gustavo Silva","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e"},"headline":"Papa Francisco apoia pessoa transg\u00eanero","datePublished":"2023-07-25T18:04:30+00:00","dateModified":"2023-07-25T18:05:09+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/25\/papa-francisco-apoia-pessoa-transgenero"},"wordCount":238,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/25\/papa-francisco-apoia-pessoa-transgenero#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/07\/2022-09-05t134733z_1_lynxmpei840fv_rtroptp_4_pope-cardinals-mass.jpg","keywords":["apoio gay papa","papa","PAPA FRANCISCO","pessoas LGBT"],"articleSection":["Mundo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/25\/papa-francisco-apoia-pessoa-transgenero#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/25\/papa-francisco-apoia-pessoa-transgenero","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/25\/papa-francisco-apoia-pessoa-transgenero","name":"Papa Francisco apoia pessoa transg\u00eanero - Ribeir\u00e3o Preto e Regi\u00e3o","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/25\/papa-francisco-apoia-pessoa-transgenero#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/25\/papa-francisco-apoia-pessoa-transgenero#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/07\/2022-09-05t134733z_1_lynxmpei840fv_rtroptp_4_pope-cardinals-mass.jpg","datePublished":"2023-07-25T18:04:30+00:00","dateModified":"2023-07-25T18:05:09+00:00","description":"um dos jovens era Giona, italiana de 20 e poucos anos que disse estar \"dividida pela dicotomia entre a f\u00e9 [cat\u00f3lica] e a identidade transg\u00eanero\"","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/25\/papa-francisco-apoia-pessoa-transgenero"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/07\/25\/papa-francisco-apoia-pessoa-transgenero#primaryimage","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/07\/2022-09-05t134733z_1_lynxmpei840fv_rtroptp_4_pope-cardinals-mass.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/07\/2022-09-05t134733z_1_lynxmpei840fv_rtroptp_4_pope-cardinals-mass.jpg","width":1170,"height":700,"caption":"Papa Francisco apoia pessoa transg\u00eanero"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","name":"Ribeir\u00e3o Preto e Regi\u00e3o","description":"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization","name":"Ribeir\u00e3o Preto e Regi\u00e3o","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","width":400,"height":250,"caption":"Ribeir\u00e3o Preto e Regi\u00e3o"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/redenoticiaz.barretos","https:\/\/x.com\/RN_barretos","https:\/\/www.instagram.com\/redenoticiaz.barretos\/?igshid=YmMyMTA2M2Y","https:\/\/www.linkedin.com\/company\/rede-noticiaz-barretos-e-regio\/"]},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/person\/16057b37a3c0ee6b096d7f887c566e2e","name":"Gustavo Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ee4e82f93b26de0a7cf4ea5eb7893da637ed6bb0c9170c58065944c56e28a33?s=96&d=mm&r=g","caption":"Gustavo Silva"},"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/author\/gustavosilva"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/108616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/comments?post=108616"}],"version-history":[{"count":0,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/108616\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media\/108617"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media?parent=108616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/categories?post=108616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/tags?post=108616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}