{"id":110069,"date":"2023-08-30T15:04:02","date_gmt":"2023-08-30T18:04:02","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/?p=110069"},"modified":"2023-08-30T15:04:02","modified_gmt":"2023-08-30T18:04:02","slug":"duas-pessoas-sao-presas-em-olimpia","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/08\/30\/duas-pessoas-sao-presas-em-olimpia","title":{"rendered":"Duas pessoas s\u00e3o presas em Ol\u00edmpia"},"content":{"rendered":"<p>Um homem de 29 anos e uma mulher de 37 anos foram presos por tr\u00e1fico de entorpecente no bairro S\u00e3o Jos\u00e9, em Ol\u00edmpia, na madrugada de ter\u00e7a-feira (29). Ambos foram denunciados, pela venda de drogas.<\/p>\n<p>No local indicado pela den\u00fancia, a pol\u00edcia encontrou diversas pessoas aparentemente usu\u00e1rios de drogas deixando o local. O casal tamb\u00e9m foi localizado.<\/p>\n<p>Durante a revista pessoal, a pol\u00edcia encontrou com o homem, uma bolsa contendo 40 pedras de crack e 31 microtubos de coca\u00edna, al\u00e9m de R$ 24,00.<\/p>\n<p>Ele alegou que a droga pertencia \u00e0 mulher e a subst\u00e2ncia seria para uso pr\u00f3prio.<\/p>\n<p>Na delegacia, a mulher alegou que encontrou com homem no caminho da casa da av\u00f3 e parou apenas para pedir um trago no crack, quando chegaram os policiais.<\/p>\n<p>O caso foi apresentado no Plant\u00e3o Policial em Barretos. Os dois foram autuados em flagrante e ficaram \u00e0 disposi\u00e7\u00e3o da Justi\u00e7a.<\/p>\n<p>LEIA MAIS<\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/barretos-regiao\/sp\/2023\/08\/30\/video-elevador-de-predio-residencial-despenca-e-deixa-tres-feridos\">V\u00cdDEO \u2013 Casal \u00e9 flagrado fazendo sexo em festa universit\u00e1ria<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem de 29 anos e uma mulher de 37 anos foram presos por tr\u00e1fico de entorpecente no bairro S\u00e3o Jos\u00e9, em Ol\u00edmpia, na madrugada de ter\u00e7a-feira (29). Ambos foram denunciados, pela venda de drogas. No local indicado pela den\u00fancia, a pol\u00edcia encontrou diversas pessoas aparentemente usu\u00e1rios de drogas deixando o local. O casal tamb\u00e9m &hellip;<\/p>\n","protected":false},"author":30,"featured_media":110070,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[16914,814,10389,5935],"class_list":["post-110069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-delegacia","tag-olimpia","tag-presos","tag-trafico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Duas pessoas s\u00e3o presas em Ol\u00edmpia - Ribeir\u00e3o Preto e Regi\u00e3o<\/title>\n<meta name=\"description\" content=\"Um homem de 29 anos e uma mulher de 37 anos foram presos por tr\u00e1fico de entorpecente no bairro S\u00e3o Jos\u00e9, em Ol\u00edmpia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/08\/30\/duas-pessoas-sao-presas-em-olimpia\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Duas pessoas s\u00e3o presas em Ol\u00edmpia - Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Um homem de 29 anos e uma mulher de 37 anos foram presos por tr\u00e1fico de entorpecente no bairro S\u00e3o Jos\u00e9, em Ol\u00edmpia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/08\/30\/duas-pessoas-sao-presas-em-olimpia\" \/>\n<meta property=\"og:site_name\" content=\"Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/redenoticiaz.barretos\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-30T18:04:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/08\/Viatura-da-PM-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"911\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carina Reifonas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:site\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carina Reifonas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/08\\\/30\\\/duas-pessoas-sao-presas-em-olimpia#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/08\\\/30\\\/duas-pessoas-sao-presas-em-olimpia\"},\"author\":{\"name\":\"Carina Reifonas\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/person\\\/1f84d6e94e6a62d2d81199d7503e9e90\"},\"headline\":\"Duas pessoas s\u00e3o presas em Ol\u00edmpia\",\"datePublished\":\"2023-08-30T18:04:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/08\\\/30\\\/duas-pessoas-sao-presas-em-olimpia\"},\"wordCount\":175,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/08\\\/30\\\/duas-pessoas-sao-presas-em-olimpia#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/08\\\/Viatura-da-PM-1.jpg\",\"keywords\":[\"DELEGACIA\",\"OLIMP\u00cdA\",\"PRESOS\",\"Tr\u00e1fico\"],\"articleSection\":[\"Pol\u00edcia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/08\\\/30\\\/duas-pessoas-sao-presas-em-olimpia#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/08\\\/30\\\/duas-pessoas-sao-presas-em-olimpia\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/08\\\/30\\\/duas-pessoas-sao-presas-em-olimpia\",\"name\":\"Duas pessoas s\u00e3o presas em Ol\u00edmpia - Ribeir\u00e3o Preto e Regi\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/08\\\/30\\\/duas-pessoas-sao-presas-em-olimpia#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/08\\\/30\\\/duas-pessoas-sao-presas-em-olimpia#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/08\\\/Viatura-da-PM-1.jpg\",\"datePublished\":\"2023-08-30T18:04:02+00:00\",\"description\":\"Um homem de 29 anos e uma mulher de 37 anos foram presos por tr\u00e1fico de entorpecente no bairro S\u00e3o Jos\u00e9, em Ol\u00edmpia.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/08\\\/30\\\/duas-pessoas-sao-presas-em-olimpia\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/08\\\/30\\\/duas-pessoas-sao-presas-em-olimpia#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/08\\\/Viatura-da-PM-1.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/08\\\/Viatura-da-PM-1.jpg\",\"width\":960,\"height\":911,\"caption\":\"Cr\u00e9dito: Divulga\u00e7\u00e3o\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"description\":\"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Ribeir\u00e3o Preto e Regi\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/redenoticiaz.barretos\",\"https:\\\/\\\/x.com\\\/RN_barretos\",\"https:\\\/\\\/www.instagram.com\\\/redenoticiaz.barretos\\\/?igshid=YmMyMTA2M2Y\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rede-noticiaz-barretos-e-regio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/person\\\/1f84d6e94e6a62d2d81199d7503e9e90\",\"name\":\"Carina Reifonas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"caption\":\"Carina Reifonas\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/author\\\/carinareifonas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Duas pessoas s\u00e3o presas em Ol\u00edmpia - Ribeir\u00e3o Preto e Regi\u00e3o","description":"Um homem de 29 anos e uma mulher de 37 anos foram presos por tr\u00e1fico de entorpecente no bairro S\u00e3o Jos\u00e9, em Ol\u00edmpia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/08\/30\/duas-pessoas-sao-presas-em-olimpia","og_locale":"pt_BR","og_type":"article","og_title":"Duas pessoas s\u00e3o presas em Ol\u00edmpia - Ribeir\u00e3o Preto e Regi\u00e3o","og_description":"Um homem de 29 anos e uma mulher de 37 anos foram presos por tr\u00e1fico de entorpecente no bairro S\u00e3o Jos\u00e9, em Ol\u00edmpia.","og_url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/08\/30\/duas-pessoas-sao-presas-em-olimpia","og_site_name":"Ribeir\u00e3o Preto e Regi\u00e3o","article_publisher":"https:\/\/m.facebook.com\/redenoticiaz.barretos","article_published_time":"2023-08-30T18:04:02+00:00","og_image":[{"width":960,"height":911,"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/08\/Viatura-da-PM-1.jpg","type":"image\/jpeg"}],"author":"Carina Reifonas","twitter_card":"summary_large_image","twitter_creator":"@RN_barretos","twitter_site":"@RN_barretos","twitter_misc":{"Escrito por":"Carina Reifonas","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/08\/30\/duas-pessoas-sao-presas-em-olimpia#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/08\/30\/duas-pessoas-sao-presas-em-olimpia"},"author":{"name":"Carina Reifonas","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/person\/1f84d6e94e6a62d2d81199d7503e9e90"},"headline":"Duas pessoas s\u00e3o presas em Ol\u00edmpia","datePublished":"2023-08-30T18:04:02+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/08\/30\/duas-pessoas-sao-presas-em-olimpia"},"wordCount":175,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/08\/30\/duas-pessoas-sao-presas-em-olimpia#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/08\/Viatura-da-PM-1.jpg","keywords":["DELEGACIA","OLIMP\u00cdA","PRESOS","Tr\u00e1fico"],"articleSection":["Pol\u00edcia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/08\/30\/duas-pessoas-sao-presas-em-olimpia#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/08\/30\/duas-pessoas-sao-presas-em-olimpia","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/08\/30\/duas-pessoas-sao-presas-em-olimpia","name":"Duas pessoas s\u00e3o presas em Ol\u00edmpia - Ribeir\u00e3o Preto e Regi\u00e3o","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/08\/30\/duas-pessoas-sao-presas-em-olimpia#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/08\/30\/duas-pessoas-sao-presas-em-olimpia#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/08\/Viatura-da-PM-1.jpg","datePublished":"2023-08-30T18:04:02+00:00","description":"Um homem de 29 anos e uma mulher de 37 anos foram presos por tr\u00e1fico de entorpecente no bairro S\u00e3o Jos\u00e9, em Ol\u00edmpia.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/08\/30\/duas-pessoas-sao-presas-em-olimpia"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/08\/30\/duas-pessoas-sao-presas-em-olimpia#primaryimage","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/08\/Viatura-da-PM-1.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/08\/Viatura-da-PM-1.jpg","width":960,"height":911,"caption":"Cr\u00e9dito: Divulga\u00e7\u00e3o"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","name":"Ribeir\u00e3o Preto e Regi\u00e3o","description":"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization","name":"Ribeir\u00e3o Preto e Regi\u00e3o","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","width":400,"height":250,"caption":"Ribeir\u00e3o Preto e Regi\u00e3o"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/redenoticiaz.barretos","https:\/\/x.com\/RN_barretos","https:\/\/www.instagram.com\/redenoticiaz.barretos\/?igshid=YmMyMTA2M2Y","https:\/\/www.linkedin.com\/company\/rede-noticiaz-barretos-e-regio\/"]},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/person\/1f84d6e94e6a62d2d81199d7503e9e90","name":"Carina Reifonas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","caption":"Carina Reifonas"},"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/author\/carinareifonas"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/110069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/comments?post=110069"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/110069\/revisions"}],"predecessor-version":[{"id":110071,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/110069\/revisions\/110071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media\/110070"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media?parent=110069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/categories?post=110069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/tags?post=110069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}