{"id":111036,"date":"2023-09-24T16:00:29","date_gmt":"2023-09-24T19:00:29","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/?p=111036"},"modified":"2023-09-22T17:59:35","modified_gmt":"2023-09-22T20:59:35","slug":"aumentam-casos-de-demencia-no-brasil","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/09\/24\/aumentam-casos-de-demencia-no-brasil","title":{"rendered":"Aumentam casos de dem\u00eancia no Brasil"},"content":{"rendered":"<p>Imagine um mundo onde os adultos s\u00e3o minoria. Jovens e crian\u00e7as seguem a mesma tend\u00eancia, o que acontece sobretudo pela menor taxa de nascimentos e maior longevidade. Esta realidade j\u00e1 est\u00e1 se desenhando segundo especialistas que estudam o envelhecimento.<\/p>\n<p>Em um levantamento conclu\u00eddo neste ano, a psiquiatra Cleusa Ferri da Universidade Federal de S\u00e3o Paulo (Unifesp) compilou um estudo que aponta pelo menos 1,76 milh\u00e3o de pessoas possuem alguma forma de dem\u00eancia no Brasil, sem contar os subdiagn\u00f3sticos.<\/p>\n<p>Com o envelhecimento da popula\u00e7\u00e3o esses casos podem chegar a 5,5 milh\u00f5es at\u00e9 2050. A iniciativa, que tem a participa\u00e7\u00e3o de profissionais de neurologia, geriatria e sa\u00fade mental, quer mobilizar o governo e contribuir para cria\u00e7\u00e3o de uma estrat\u00e9gia nacional para lidar com o tema.<\/p>\n<p>Diante da realidade que se apresenta \u2013 e que confirma que estamos, de fato, vivendo mais, estar\u00edamos tamb\u00e9m melhorando nossa qualidade de vida para, al\u00e9m de viver mais, tamb\u00e9m viver melhor?<\/p>\n<p>Uma das principais consequ\u00eancia do aumento da expectativa de vida, segundo os especialistas em envelhecimento \u00e9 tamb\u00e9m o aumento de doen\u00e7as cr\u00f4nicas ligadas ao envelhecimento, em especial as doen\u00e7as neurodegenerativas, principalmente Doen\u00e7a de Alzheimer.<\/p>\n<p>A Doen\u00e7a de Alzheimer \u00e9 uma das formas mais comuns de dem\u00eancia, trata-se de uma condi\u00e7\u00e3o progressiva causada pelo ac\u00famulo das prote\u00ednas tau e beta-amil\u00f3ide no c\u00e9rebro. Essas prote\u00ednas deterioram as regi\u00f5es e estruturas cerebrais. Quando essas prote\u00ednas n\u00e3o desempenham suas fun\u00e7\u00f5es adequadamente, as sinapses, que s\u00e3o as conex\u00f5es entre os neur\u00f4nios, deixam de funcionar, resultando na morte desses neur\u00f4nios devido a esse mau funcionamento.<\/p>\n<p>No entanto, \u00e9 poss\u00edvel promover a sa\u00fade cerebral ao longo da vida para retardar o aparecimento dos sintomas da Doen\u00e7a de Alzheimer. Nesse contexto, a ado\u00e7\u00e3o de h\u00e1bitos saud\u00e1veis, o manejo do estresse, a alimenta\u00e7\u00e3o adequada, a pr\u00e1tica regular de exerc\u00edcios f\u00edsicos e a gin\u00e1stica para o c\u00e9rebro ou treino cerebral desempenham um papel crucial para prevenir o aparecimento desta e de outras dem\u00eancias.<\/p>\n<p>&#8220;A luta contra a Doen\u00e7a de Alzheimer \u00e9 complexa, uma vez que ainda n\u00e3o temos uma cura definitiva. Al\u00e9m disso, cuidados com a qualidade do sono, sa\u00fade vascular, atividade f\u00edsica regular, dieta equilibrada e estimula\u00e7\u00e3o cognitiva ou gin\u00e1stica para o c\u00e9rebro desempenham um papel fundamental na redu\u00e7\u00e3o dos riscos&#8221;, alertou a assessoria cient\u00edfica do M\u00e9todo SUPERA \u2013 Gin\u00e1stica para o c\u00e9rebro, professora- doutora pela USP (Universidade de S\u00e3o Paulo), Thais Bento Lima.<\/p>\n<p>O que posso fazer hoje para reduzir o risco de desenvolver a Doen\u00e7a de Alzheimer? Dado que o Alzheimer \u00e9 uma condi\u00e7\u00e3o multifatorial, a preven\u00e7\u00e3o deve envolver diversos fatores. O primeiro passo \u00e9 cuidar da sa\u00fade geral do organismo, controlando doen\u00e7as cr\u00f4nicas como diabetes, obesidade, doen\u00e7as cardiovasculares e hipertens\u00e3o, al\u00e9m de incorporar atividades f\u00edsicas e uma alimenta\u00e7\u00e3o equilibrada.<\/p>\n<p>Uma vez que o corpo est\u00e1 saud\u00e1vel, \u00e9 importante tamb\u00e9m monitorar de perto o desempenho das habilidades mentais, com a pr\u00e1tica de gin\u00e1stica para o c\u00e9rebro e utilizando estrat\u00e9gias de mem\u00f3ria e est\u00edmulos cognitivos para prevenir ou postergar o aparecimento dos sintomas da doen\u00e7a. Ao estimular a neuroplasticidade cerebral, \u00e9 poss\u00edvel desenvolver uma reserva cognitiva robusta. Essa reserva ajuda o c\u00e9rebro a resistir melhor aos danos causados pelo envelhecimento ou por doen\u00e7as. Al\u00e9m disso, ter parentes de primeiro grau com a doen\u00e7a n\u00e3o \u00e9 necessariamente uma senten\u00e7a, pois \u00e9 poss\u00edvel fazer muito para fortalecer o c\u00e9rebro, criando essa reserva cognitiva e antecipando-se a qualquer sintoma futuro.<\/p>\n<p>Conhe\u00e7a 12 fatores de risco para dem\u00eancia segundo a Alzheimer&#8217;s Disease International:<\/p>\n<p>1. Falta de atividade f\u00edsica;<\/p>\n<p>2. Tabagismo;<\/p>\n<p>3. Excesso de consumo de \u00e1lcool<\/p>\n<p>4. Polui\u00e7\u00e3o<\/p>\n<p>5. Traumatismo cef\u00e1lico;<\/p>\n<p>6. Isolamento social;<\/p>\n<p>7. Baixa escolaridade;<\/p>\n<p>8. Obesidade;<\/p>\n<p>9. Hipertens\u00e3o arterial;<\/p>\n<p>10. Diabetes;<\/p>\n<p>11. Depress\u00e3o;<\/p>\n<p>12. Perda auditiva;<\/p>\n<p>LEIA MAIS<\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2023\/09\/09\/mama-volumosa-pode-desencadear-problemas-de-saude\">Mama volumosa pode desencadear problemas de sa\u00fade<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imagine um mundo onde os adultos s\u00e3o minoria. Jovens e crian\u00e7as seguem a mesma tend\u00eancia, o que acontece sobretudo pela menor taxa de nascimentos e maior longevidade. Esta realidade j\u00e1 est\u00e1 se desenhando segundo especialistas que estudam o envelhecimento. Em um levantamento conclu\u00eddo neste ano, a psiquiatra Cleusa Ferri da Universidade Federal de S\u00e3o Paulo &hellip;<\/p>\n","protected":false},"author":30,"featured_media":111037,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[129],"tags":[26048,2182,165],"class_list":["post-111036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude","tag-demencia","tag-idoso","tag-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aumentam casos de dem\u00eancia no Brasil - Ribeir\u00e3o Preto e Regi\u00e3o<\/title>\n<meta name=\"description\" content=\"Aumentam casos de dem\u00eancia no Brasil\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/09\/24\/aumentam-casos-de-demencia-no-brasil\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aumentam casos de dem\u00eancia no Brasil - Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Aumentam casos de dem\u00eancia no Brasil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/09\/24\/aumentam-casos-de-demencia-no-brasil\" \/>\n<meta property=\"og:site_name\" content=\"Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/redenoticiaz.barretos\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-24T19:00:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/09\/Captura-de-tela-2023-09-22-175445.jpg?v=1695416119\" \/>\n\t<meta property=\"og:image:width\" content=\"497\" \/>\n\t<meta property=\"og:image:height\" content=\"335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carina Reifonas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:site\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carina Reifonas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/09\\\/24\\\/aumentam-casos-de-demencia-no-brasil#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/09\\\/24\\\/aumentam-casos-de-demencia-no-brasil\"},\"author\":{\"name\":\"Carina Reifonas\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/person\\\/1f84d6e94e6a62d2d81199d7503e9e90\"},\"headline\":\"Aumentam casos de dem\u00eancia no Brasil\",\"datePublished\":\"2023-09-24T19:00:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/09\\\/24\\\/aumentam-casos-de-demencia-no-brasil\"},\"wordCount\":694,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/09\\\/24\\\/aumentam-casos-de-demencia-no-brasil#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/09\\\/Captura-de-tela-2023-09-22-175445.jpg?v=1695416119\",\"keywords\":[\"DEM\u00caNCIA\",\"IDOSO\",\"saude\"],\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/09\\\/24\\\/aumentam-casos-de-demencia-no-brasil#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/09\\\/24\\\/aumentam-casos-de-demencia-no-brasil\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/09\\\/24\\\/aumentam-casos-de-demencia-no-brasil\",\"name\":\"Aumentam casos de dem\u00eancia no Brasil - Ribeir\u00e3o Preto e Regi\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/09\\\/24\\\/aumentam-casos-de-demencia-no-brasil#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/09\\\/24\\\/aumentam-casos-de-demencia-no-brasil#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/09\\\/Captura-de-tela-2023-09-22-175445.jpg?v=1695416119\",\"datePublished\":\"2023-09-24T19:00:29+00:00\",\"description\":\"Aumentam casos de dem\u00eancia no Brasil\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/09\\\/24\\\/aumentam-casos-de-demencia-no-brasil\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/09\\\/24\\\/aumentam-casos-de-demencia-no-brasil#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/09\\\/Captura-de-tela-2023-09-22-175445.jpg?v=1695416119\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/09\\\/Captura-de-tela-2023-09-22-175445.jpg?v=1695416119\",\"width\":497,\"height\":335},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"description\":\"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Ribeir\u00e3o Preto e Regi\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/redenoticiaz.barretos\",\"https:\\\/\\\/x.com\\\/RN_barretos\",\"https:\\\/\\\/www.instagram.com\\\/redenoticiaz.barretos\\\/?igshid=YmMyMTA2M2Y\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rede-noticiaz-barretos-e-regio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/person\\\/1f84d6e94e6a62d2d81199d7503e9e90\",\"name\":\"Carina Reifonas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"caption\":\"Carina Reifonas\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/author\\\/carinareifonas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aumentam casos de dem\u00eancia no Brasil - Ribeir\u00e3o Preto e Regi\u00e3o","description":"Aumentam casos de dem\u00eancia no Brasil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/09\/24\/aumentam-casos-de-demencia-no-brasil","og_locale":"pt_BR","og_type":"article","og_title":"Aumentam casos de dem\u00eancia no Brasil - Ribeir\u00e3o Preto e Regi\u00e3o","og_description":"Aumentam casos de dem\u00eancia no Brasil","og_url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/09\/24\/aumentam-casos-de-demencia-no-brasil","og_site_name":"Ribeir\u00e3o Preto e Regi\u00e3o","article_publisher":"https:\/\/m.facebook.com\/redenoticiaz.barretos","article_published_time":"2023-09-24T19:00:29+00:00","og_image":[{"width":497,"height":335,"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/09\/Captura-de-tela-2023-09-22-175445.jpg?v=1695416119","type":"image\/jpeg"}],"author":"Carina Reifonas","twitter_card":"summary_large_image","twitter_creator":"@RN_barretos","twitter_site":"@RN_barretos","twitter_misc":{"Escrito por":"Carina Reifonas","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/09\/24\/aumentam-casos-de-demencia-no-brasil#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/09\/24\/aumentam-casos-de-demencia-no-brasil"},"author":{"name":"Carina Reifonas","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/person\/1f84d6e94e6a62d2d81199d7503e9e90"},"headline":"Aumentam casos de dem\u00eancia no Brasil","datePublished":"2023-09-24T19:00:29+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/09\/24\/aumentam-casos-de-demencia-no-brasil"},"wordCount":694,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/09\/24\/aumentam-casos-de-demencia-no-brasil#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/09\/Captura-de-tela-2023-09-22-175445.jpg?v=1695416119","keywords":["DEM\u00caNCIA","IDOSO","saude"],"articleSection":["Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/09\/24\/aumentam-casos-de-demencia-no-brasil#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/09\/24\/aumentam-casos-de-demencia-no-brasil","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/09\/24\/aumentam-casos-de-demencia-no-brasil","name":"Aumentam casos de dem\u00eancia no Brasil - Ribeir\u00e3o Preto e Regi\u00e3o","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/09\/24\/aumentam-casos-de-demencia-no-brasil#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/09\/24\/aumentam-casos-de-demencia-no-brasil#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/09\/Captura-de-tela-2023-09-22-175445.jpg?v=1695416119","datePublished":"2023-09-24T19:00:29+00:00","description":"Aumentam casos de dem\u00eancia no Brasil","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/09\/24\/aumentam-casos-de-demencia-no-brasil"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/09\/24\/aumentam-casos-de-demencia-no-brasil#primaryimage","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/09\/Captura-de-tela-2023-09-22-175445.jpg?v=1695416119","contentUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/09\/Captura-de-tela-2023-09-22-175445.jpg?v=1695416119","width":497,"height":335},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","name":"Ribeir\u00e3o Preto e Regi\u00e3o","description":"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization","name":"Ribeir\u00e3o Preto e Regi\u00e3o","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","width":400,"height":250,"caption":"Ribeir\u00e3o Preto e Regi\u00e3o"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/redenoticiaz.barretos","https:\/\/x.com\/RN_barretos","https:\/\/www.instagram.com\/redenoticiaz.barretos\/?igshid=YmMyMTA2M2Y","https:\/\/www.linkedin.com\/company\/rede-noticiaz-barretos-e-regio\/"]},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/person\/1f84d6e94e6a62d2d81199d7503e9e90","name":"Carina Reifonas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","caption":"Carina Reifonas"},"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/author\/carinareifonas"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/111036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/comments?post=111036"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/111036\/revisions"}],"predecessor-version":[{"id":111038,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/111036\/revisions\/111038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media\/111037"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media?parent=111036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/categories?post=111036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/tags?post=111036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}