{"id":115529,"date":"2024-02-22T15:37:05","date_gmt":"2024-02-22T18:37:05","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/?p=115529"},"modified":"2024-02-22T15:37:05","modified_gmt":"2024-02-22T18:37:05","slug":"sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/02\/22\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao","title":{"rendered":"Sorteio da Mega-Sena premia cinco apostadores da regi\u00e3o"},"content":{"rendered":"<p>O sorteio 2.690 da Mega-Sena, realizado na \u00faltima segunda-feira (20), trouxe sorte para a regi\u00e3o de Barretos. Apostas feitas na \u00e1rea garantiram R$ 4.622,35 na quadra, com cinco apostadores levando, cada um, a partir de R$ 924,47 ao acertarem quatro dezenas sorteadas.<\/p>\n<p>Em Barretos, tr\u00eas felizardos compartilhar\u00e3o o pr\u00eamio, somando R$ 2.773,41. Al\u00e9m disso, houve um ganhador em Bebedouro (R$ 924,47) e outro em Tai\u00fava (R$ 924,47).<\/p>\n<p>O pr\u00eamio acumulado para o pr\u00f3ximo sorteio, marcado para hoje (22), atinge a cifra de R$ 97 milh\u00f5es. As dezenas sorteadas no \u00faltimo concurso foram: 09 \u2013 28 \u2013 33 \u2013 43 \u2013 45 \u2013 55.<\/p>\n<p>Nenhuma aposta acertou as seis dezenas, aumentando a expectativa para o pr\u00f3ximo sorteio. As apostas podem ser realizadas at\u00e9 as 19h, tanto em lot\u00e9ricas f\u00edsicas quanto pelo site da Caixa. A probabilidade de ganhar o pr\u00eamio milion\u00e1rio com uma aposta simples de seis dezenas \u00e9 de 1 em 50.063.860, de acordo com informa\u00e7\u00f5es fornecidas pela Caixa Econ\u00f4mica Federal.<\/p>\n<p>LEIA MAIS<\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/barretos-regiao\/sp\/2024\/02\/22\/show-de-michel-telo-em-comemoracao-aos-121-anos-de-olimpia\">Show de Michel Tel\u00f3 em comemora\u00e7\u00e3o aos 121 anos de Ol\u00edmpia<\/a><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/barretos-regiao\/sp\/2024\/02\/22\/estagio-para-estudantes-de-pedagogia-e-psicologia-na-rede-municipal-de-educacao\">Est\u00e1gio para Estudantes de Pedagogia e Psicologia na rede municipal de educa\u00e7\u00e3o<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O sorteio 2.690 da Mega-Sena, realizado na \u00faltima segunda-feira (20), trouxe sorte para a regi\u00e3o de Barretos. Apostas feitas na \u00e1rea garantiram R$ 4.622,35 na quadra, com cinco apostadores levando, cada um, a partir de R$ 924,47 ao acertarem quatro dezenas sorteadas. Em Barretos, tr\u00eas felizardos compartilhar\u00e3o o pr\u00eamio, somando R$ 2.773,41. Al\u00e9m disso, houve &hellip;<\/p>\n","protected":false},"author":30,"featured_media":115530,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101],"tags":[29974,64,3055],"class_list":["post-115529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-apostadores","tag-barretos","tag-mega-sena"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sorteio da Mega-Sena premia cinco apostadores da regi\u00e3o - Ribeir\u00e3o Preto e Regi\u00e3o<\/title>\n<meta name=\"description\" content=\"Apostas feitas na \u00e1rea garantiram R$ 4.622,35 na quadra, com cinco apostadores levando, cada um, a partir de R$ 924,47 ao acertarem quatro dezenas sorteadas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/02\/22\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sorteio da Mega-Sena premia cinco apostadores da regi\u00e3o - Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Apostas feitas na \u00e1rea garantiram R$ 4.622,35 na quadra, com cinco apostadores levando, cada um, a partir de R$ 924,47 ao acertarem quatro dezenas sorteadas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/02\/22\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao\" \/>\n<meta property=\"og:site_name\" content=\"Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/redenoticiaz.barretos\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-22T18:37:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/02\/mega.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carina Reifonas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:site\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carina Reifonas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/02\\\/22\\\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/02\\\/22\\\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao\"},\"author\":{\"name\":\"Carina Reifonas\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/person\\\/1f84d6e94e6a62d2d81199d7503e9e90\"},\"headline\":\"Sorteio da Mega-Sena premia cinco apostadores da regi\u00e3o\",\"datePublished\":\"2024-02-22T18:37:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/02\\\/22\\\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao\"},\"wordCount\":191,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/02\\\/22\\\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/02\\\/mega.jpg\",\"keywords\":[\"apostadores\",\"BARRETOS\",\"mega-sena\"],\"articleSection\":[\"Economia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/02\\\/22\\\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/02\\\/22\\\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/02\\\/22\\\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao\",\"name\":\"Sorteio da Mega-Sena premia cinco apostadores da regi\u00e3o - Ribeir\u00e3o Preto e Regi\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/02\\\/22\\\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/02\\\/22\\\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/02\\\/mega.jpg\",\"datePublished\":\"2024-02-22T18:37:05+00:00\",\"description\":\"Apostas feitas na \u00e1rea garantiram R$ 4.622,35 na quadra, com cinco apostadores levando, cada um, a partir de R$ 924,47 ao acertarem quatro dezenas sorteadas.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/02\\\/22\\\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/02\\\/22\\\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/02\\\/mega.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/02\\\/mega.jpg\",\"width\":650,\"height\":450,\"caption\":\"Sorteio da Mega-Sena premia cinco apostadores da regi\u00e3o\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"description\":\"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Ribeir\u00e3o Preto e Regi\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/redenoticiaz.barretos\",\"https:\\\/\\\/x.com\\\/RN_barretos\",\"https:\\\/\\\/www.instagram.com\\\/redenoticiaz.barretos\\\/?igshid=YmMyMTA2M2Y\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rede-noticiaz-barretos-e-regio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/person\\\/1f84d6e94e6a62d2d81199d7503e9e90\",\"name\":\"Carina Reifonas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"caption\":\"Carina Reifonas\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/author\\\/carinareifonas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sorteio da Mega-Sena premia cinco apostadores da regi\u00e3o - Ribeir\u00e3o Preto e Regi\u00e3o","description":"Apostas feitas na \u00e1rea garantiram R$ 4.622,35 na quadra, com cinco apostadores levando, cada um, a partir de R$ 924,47 ao acertarem quatro dezenas sorteadas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/02\/22\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao","og_locale":"pt_BR","og_type":"article","og_title":"Sorteio da Mega-Sena premia cinco apostadores da regi\u00e3o - Ribeir\u00e3o Preto e Regi\u00e3o","og_description":"Apostas feitas na \u00e1rea garantiram R$ 4.622,35 na quadra, com cinco apostadores levando, cada um, a partir de R$ 924,47 ao acertarem quatro dezenas sorteadas.","og_url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/02\/22\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao","og_site_name":"Ribeir\u00e3o Preto e Regi\u00e3o","article_publisher":"https:\/\/m.facebook.com\/redenoticiaz.barretos","article_published_time":"2024-02-22T18:37:05+00:00","og_image":[{"width":650,"height":450,"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/02\/mega.jpg","type":"image\/jpeg"}],"author":"Carina Reifonas","twitter_card":"summary_large_image","twitter_creator":"@RN_barretos","twitter_site":"@RN_barretos","twitter_misc":{"Escrito por":"Carina Reifonas","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/02\/22\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/02\/22\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao"},"author":{"name":"Carina Reifonas","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/person\/1f84d6e94e6a62d2d81199d7503e9e90"},"headline":"Sorteio da Mega-Sena premia cinco apostadores da regi\u00e3o","datePublished":"2024-02-22T18:37:05+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/02\/22\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao"},"wordCount":191,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/02\/22\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/02\/mega.jpg","keywords":["apostadores","BARRETOS","mega-sena"],"articleSection":["Economia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/02\/22\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/02\/22\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/02\/22\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao","name":"Sorteio da Mega-Sena premia cinco apostadores da regi\u00e3o - Ribeir\u00e3o Preto e Regi\u00e3o","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/02\/22\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/02\/22\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/02\/mega.jpg","datePublished":"2024-02-22T18:37:05+00:00","description":"Apostas feitas na \u00e1rea garantiram R$ 4.622,35 na quadra, com cinco apostadores levando, cada um, a partir de R$ 924,47 ao acertarem quatro dezenas sorteadas.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/02\/22\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/02\/22\/sorteio-da-mega-sena-premia-cinco-apostadores-da-regiao#primaryimage","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/02\/mega.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/02\/mega.jpg","width":650,"height":450,"caption":"Sorteio da Mega-Sena premia cinco apostadores da regi\u00e3o"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","name":"Ribeir\u00e3o Preto e Regi\u00e3o","description":"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization","name":"Ribeir\u00e3o Preto e Regi\u00e3o","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","width":400,"height":250,"caption":"Ribeir\u00e3o Preto e Regi\u00e3o"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/redenoticiaz.barretos","https:\/\/x.com\/RN_barretos","https:\/\/www.instagram.com\/redenoticiaz.barretos\/?igshid=YmMyMTA2M2Y","https:\/\/www.linkedin.com\/company\/rede-noticiaz-barretos-e-regio\/"]},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/person\/1f84d6e94e6a62d2d81199d7503e9e90","name":"Carina Reifonas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","caption":"Carina Reifonas"},"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/author\/carinareifonas"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/115529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/comments?post=115529"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/115529\/revisions"}],"predecessor-version":[{"id":115531,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/115529\/revisions\/115531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media\/115530"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media?parent=115529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/categories?post=115529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/tags?post=115529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}