{"id":117502,"date":"2024-06-25T13:14:59","date_gmt":"2024-06-25T16:14:59","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/sp\/2024\/06\/25\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee"},"modified":"2024-06-25T13:14:59","modified_gmt":"2024-06-25T16:14:59","slug":"confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/06\/25\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee","title":{"rendered":"Confira empresas com inscri\u00e7\u00f5es abertas para est\u00e1gio e trainee"},"content":{"rendered":"<p>As companhias Goodyear, PPG, UPL est\u00e3o com inscri\u00e7\u00f5es abertas para programas de est\u00e1gio. S\u00e3o eleg\u00edveis para as vagas <strong>estudantes de ensino superior e cursos t\u00e9cnicos de diversas \u00e1reas<\/strong>. J\u00e1 a Nitro, multinacional brasileira fabricante de especialidades qu\u00edmicas e insumos para o agro, est\u00e1 em busca de rec\u00e9m-formados para seu programa de trainees.<\/p>\n<p>H\u00e1 vagas dispon\u00edveis em todo territ\u00f3rio nacional, mas entre os munic\u00edpios com oportunidades destacam-se <strong>Sumar\u00e9\/SP, Campinas\/SP, Ituverava\/SP, Salto de Pirapora\/SP, S\u00e3o Paulo\/ SP, Americana\/ SP, Gravata\u00ed\/RS e Pinhais\/PR.<\/strong><\/p>\n<p>Al\u00e9m disso, a Companhia de Est\u00e1gios est\u00e1 conduzindo mais de 442 vagas pontuais de est\u00e1gio em empresas como ADM do Brasil, Boehringer Ingelheim, Carrefour, Clariant, Galderma, Henkel, Klabin, Lenovo, Novo Nordisk, Printi, Prometeon, Schneider Electric, Softys, Tenda, Volvo, Whirlpool e Zurich.<\/p>\n<p>Os processos seletivos s\u00e3o conduzidos pela Companhia de Est\u00e1gios, l\u00edder em recrutamento e sele\u00e7\u00e3o de estagi\u00e1rios, trainees e jovens aprendizes. Confira abaixo os requisitos para conquistar uma vaga de est\u00e1gio e trainee para promover o seu desenvolvimento profissional.<\/p>\n<p>&nbsp;<\/p>\n<h3>GENERAL MILLS<\/h3>\n<p>A General Mills, dona das marcas Yoki, Kitano e H\u00e4agen-Dazs, que tem atua\u00e7\u00e3o em mais de 100 pa\u00edses e em todos os continentes, est\u00e1 com inscri\u00e7\u00f5es abertas para o seu Programa de Est\u00e1gio. Ao todo, s\u00e3o 24 vagas em modelos h\u00edbridos para posi\u00e7\u00f5es corporativas (com idas ao escrit\u00f3rio de S\u00e3o Bernardo do Campo\/SP entre uma a tr\u00eas vezes ao m\u00eas), e de forma presencial para \u00e1reas que t\u00eam atua\u00e7\u00e3o direta em atividades fabris ou log\u00edsticas, nas unidades de Pouso Alegre\/MG e Cajamar\/SP.<\/p>\n<p>Os interessados devem estar cursando o ensino superior, com forma\u00e7\u00e3o prevista entre dezembro de 2025 e dezembro de 2026. As oportunidades s\u00e3o destinadas para estudantes dos cursos de acordo com a localidade:<\/p>\n<p>S\u00e3o Bernardo do Campo: Publicidade e Propaganda, Comunica\u00e7\u00e3o Social, Marketing Bacharel. Administra\u00e7\u00e3o, Economia, Marketing (Bacharel), Ci\u00eancia da Computa\u00e7\u00e3o, Ci\u00eancias Cont\u00e1beis, Marketing Bacharel, Engenharia de Alimentos, Engenharia de Produ\u00e7\u00e3o, Engenharia de Gest\u00e3o. Engenharia de Alimentos, Farm\u00e1cia, Engenharia Qu\u00edmica, Qu\u00edmica, \u00e1reas correlatas. Engenharia de Materiais, Engenharia Mec\u00e2nica. Engenharia de Produ\u00e7\u00e3o, Engenharia de Gest\u00e3o.<\/p>\n<p>Pouso Alegre: Engenharias, Administra\u00e7\u00e3o, Psicologia, Comunica\u00e7\u00e3o Social. Engenharia da Computa\u00e7\u00e3o, Engenharia de Software, Ci\u00eancias da Computa\u00e7\u00e3o, An\u00e1lise e Desenvolvimento de Sistemas, An\u00e1lise de Dados, Tecn\u00f3logos na \u00e1rea de Tecnologia. Engenharia de Alimentos, Engenharia Qu\u00edmica, Qu\u00edmica, Engenharia de Produ\u00e7\u00e3o e correlatas. Economia, Log\u00edstica, Com\u00e9rcio Exterior. Tecn\u00f3logo Superior em Controle e Processos Industriais, Gest\u00e3o da Produ\u00e7\u00e3o, Gest\u00e3o da Qualidade ou Processos Gerenciais. Marketing, \u00e1reas de exatas ou correlatas.<\/p>\n<p>Cajamar: Administra\u00e7\u00e3o, Economia, Log\u00edstica, Com\u00e9rcio Exterior.<\/p>\n<p>Todas as etapas do processo seletivo ser\u00e3o online. S\u00e3o oferecidos os benef\u00edcios: bolsa-aux\u00edlio compat\u00edvel com o mercado, vale-transporte, vale-alimenta\u00e7\u00e3o e vale-refei\u00e7\u00e3o (ou refei\u00e7\u00e3o no local a depender da unidade), seguro de vida, conv\u00eanio m\u00e9dico e odontol\u00f3gico, Programa de Apoio ao Colaborador (orienta\u00e7\u00e3o financeira, jur\u00eddica, social e emocional) e Day Off Anivers\u00e1rio. Os selecionados iniciar\u00e3o suas jornadas na General Mills na segunda semana de outubro de 2024.<\/p>\n<p>Bolsa-aux\u00edlio: compat\u00edvel com o mercado<\/p>\n<p>Prazo de inscri\u00e7\u00e3o: 11\/07<\/p>\n<p>Link de inscri\u00e7\u00e3o: <a href=\"https:\/\/www.ciadeestagios.com.br\/vagas\/generalmills\/\">https:\/\/www.ciadeestagios.com.br\/vagas\/generalmills\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3>NITRO (trainee)<\/h3>\n<p>A Nitro, multinacional brasileira fabricante de especialidades qu\u00edmicas e insumos para o agroneg\u00f3cio, est\u00e1 com inscri\u00e7\u00f5es abertas para o Programa Trainee Agro 2024, buscando ampliar o time com novos talentos de diversas \u00e1reas. H\u00e1 oportunidades para profissionais com forma\u00e7\u00e3o acad\u00eamica conclu\u00edda em at\u00e9 2 anos para atuar nos setores comercial e t\u00e9cnico relacionados com o agroneg\u00f3cio. S\u00e3o eleg\u00edveis candidatos dos cursos de Agronomia, Engenharia Agron\u00f4mica e correlatos.<\/p>\n<p>As vagas s\u00e3o distribu\u00eddas em todo territ\u00f3rio nacional, com jornada de 8 horas di\u00e1rias de trabalho presencial. Entre os dias 10 a 25 de junho acontecem as entrevistas iniciais. A partir dos dias 01 e 02\/07, os selecionados participam de um painel de apresenta\u00e7\u00e3o com os gestores da Nitro. No dia 15\/07 come\u00e7a o programa de forma\u00e7\u00e3o, com dura\u00e7\u00e3o de 12 meses. Na fase final, os profissionais ser\u00e3o direcionados para as \u00e1reas de neg\u00f3cios agro da Nitro.<\/p>\n<p>Bolsa-aux\u00edlio: compat\u00edvel com o mercado<\/p>\n<p>Prazo de inscri\u00e7\u00e3o: 21\/06<\/p>\n<p>Link de inscri\u00e7\u00e3o: <a href=\"https:\/\/www.ciadeestagios.com.br\/programas\/nitro\">https:\/\/www.ciadeestagios.com.br\/programas\/nitro<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3>GOODYEAR<\/h3>\n<p>A Goodyear, uma das l\u00edderes mundiais na fabrica\u00e7\u00e3o de pneus e presente no Brasil h\u00e1 mais de 100 anos, anuncia a abertura das inscri\u00e7\u00f5es para o seu Programa de Est\u00e1gio para o terceiro trimestre de 2024. Com o apoio da Companhia de Est\u00e1gios na condu\u00e7\u00e3o das etapas de inscri\u00e7\u00e3o, o programa \u00e9 destinado a estudantes universit\u00e1rios do pen\u00faltimo ano das \u00e1reas de exatas e humanas que desejam se desenvolver pessoal e profissionalmente.<\/p>\n<p>As vagas oferecidas est\u00e3o localizadas em S\u00e3o Paulo\/SP e Americana\/SP nas \u00e1reas de Manufatura, Intelig\u00eancia de Vendas, Engenharia de Campo, Recursos Humanos, Supply Chain e Desenvolvimento de Neg\u00f3cios. O in\u00edcio do per\u00edodo de est\u00e1gio para os estudantes selecionados est\u00e1 previsto para agosto, com jornada de trabalho de 30 horas semanais.Para participar do processo seletivo, os candidatos devem ter disponibilidade para cumprir um contrato de dois anos de est\u00e1gio.<\/p>\n<p>O Programa de Est\u00e1gio Goodyear 2024 tem como objetivo proporcionar um ambiente din\u00e2mico para os estudantes, oferecendo a possibilidade de transformar teoria em pr\u00e1tica, al\u00e9m da participa\u00e7\u00e3o em projetos multidisciplinares relevantes, treinamentos e o envolvimento com atividades de aprendizagem cont\u00ednua.<\/p>\n<p>Entre os benef\u00edcios oferecidos est\u00e3o programa de assist\u00eancia aos associados, vale-transporte, estacionamento, fretado ou reembolso de km, conv\u00eanio para desconto em medicamentos, acesso a produtos com desconto, seguro de vida, plano m\u00e9dico e odontol\u00f3gico; acesso a restaurante ou vale-refei\u00e7\u00e3o e Gympass.<\/p>\n<p>Bolsa-aux\u00edlio: compat\u00edvel com o mercado<\/p>\n<p>Prazo de inscri\u00e7\u00e3o: 30\/06<\/p>\n<p>Link de inscri\u00e7\u00e3o: <a href=\"http:\/\/www.ciadeestagios.com.br\/Goodyear\">www.ciadeestagios.com.br\/Goodyear<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3>PPG<\/h3>\n<p>A PPG, companhia que atua h\u00e1 mais de 140 anos no ramo de tintas, revestimentos e materiais especiais, est\u00e1 com as inscri\u00e7\u00f5es abertas para o seu Programa de Est\u00e1gio Pintando Novos Talentos PPG 2024.2<\/p>\n<p>O programa conta com uma trilha completa de desenvolvimento, com treinamentos, cursos que podem ser acessados a qualquer momento, rodas de conversa e equipes de desenvolvimento, com oportunidades para os munic\u00edpios de Sumar\u00e9\/SP, Gravata\u00ed\/RS e Pinhais\/PR.<\/p>\n<p>As vagas s\u00e3o para estudantes com previs\u00e3o de conclus\u00e3o do curso a partir de junho de 2025. Os candidatos podem estar em cursos t\u00e9cnicos ou no ensino superior, com possibilidade para estagiar no m\u00ednimo por 18 meses e limitado a 24 meses. Est\u00e3o eleg\u00edveis para as vagas estudantes das \u00e1reas de Administra\u00e7\u00e3o, Ci\u00eancias Cont\u00e1beis, Automa\u00e7\u00e3o Industrial, Comunica\u00e7\u00e3o, Design, Com\u00e9rcio Exterior, Neg\u00f3cios Internacionais e afins.<\/p>\n<p>Os benef\u00edcios oferecidos incluem assist\u00eancia m\u00e9dica e odontol\u00f3gica, b\u00f4nus, \u00f4nibus fretado ou vale-transporte, refei\u00e7\u00e3o no local, programa de sa\u00fade e bem-estar e seguro de vida.<\/p>\n<p>Bolsa-aux\u00edlio: compat\u00edvel com o mercado<\/p>\n<p>Prazo de inscri\u00e7\u00e3o: 10\/07<\/p>\n<p>Link de inscri\u00e7\u00e3o: <a href=\"https:\/\/www.ciadeestagios.com.br\/programas\/ppg\">https:\/\/www.ciadeestagios.com.br\/programas\/ppg<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3>UPL<\/h3>\n<p>A UPL \u00e9 uma fornecedora global de produtos e solu\u00e7\u00f5es agr\u00edcolas sustent\u00e1veis para toda a cadeia de produ\u00e7\u00e3o de alimentos, desde o tratamento de sementes at\u00e9 a mesa do consumidor, consiste em produtos biol\u00f3gicos e solu\u00e7\u00f5es tradicionais de prote\u00e7\u00e3o de cultivos e est\u00e1 presente em 130 pa\u00edses.<\/p>\n<p>A companhia est\u00e1 com as inscri\u00e7\u00f5es abertas para o Programa de Est\u00e1gio, que conta com 16 vagas de est\u00e1gio nos munic\u00edpios de Campinas\/SP, Ituverava\/SP e Salto de Pirapora\/SP. Os pr\u00e9-requisitos para as vagas incluem forma\u00e7\u00e3o superior, conhecimento do Pacote Office e, em alguns casos, ingl\u00eas. A dura\u00e7\u00e3o do programa \u00e9 de no m\u00e1ximo 2 anos.<\/p>\n<p>Al\u00e9m da bolsa-aux\u00edlio, o programa oferece como benef\u00edcio seguro de vida, assist\u00eancia m\u00e9dica e odontol\u00f3gica, vale-transporte ou estacionamento, fretado, vale-refei\u00e7\u00e3o ou refeit\u00f3rio, trilha de desenvolvimento e Gympass.<\/p>\n<p>Bolsa-aux\u00edlio: compat\u00edvel com o mercado<\/p>\n<p>Prazo de inscri\u00e7\u00e3o: 05\/07\/2024<\/p>\n<p>Link de inscri\u00e7\u00e3o: <a href=\"https:\/\/www.ciadeestagios.com.br\/vagas\/upl\/\">https:\/\/www.ciadeestagios.com.br\/vagas\/upl\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>LEIA MAIS<\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2024\/06\/25\/inscricoes-abertas-para-novo-processo-seletivo-bradesco\">Inscri\u00e7\u00f5es abertas para NOVO processo seletivo Bradesco<\/a><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2024\/06\/24\/tce-considera-irregular-contrato-de-r-23-milhoes-para-obras-em-itatiba\">TCE considera irregular contrato de R$ 23 milh\u00f5es para obras em Itatiba<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As companhias Goodyear, PPG, UPL est\u00e3o com inscri\u00e7\u00f5es abertas para programas de est\u00e1gio. S\u00e3o eleg\u00edveis para as vagas estudantes de ensino superior e cursos t\u00e9cnicos de diversas \u00e1reas. J\u00e1 a Nitro, multinacional brasileira fabricante de especialidades qu\u00edmicas e insumos para o agro, est\u00e1 em busca de rec\u00e9m-formados para seu programa de trainees. H\u00e1 vagas dispon\u00edveis &hellip;<\/p>\n","protected":false},"author":30,"featured_media":117503,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29902],"tags":[17605,3850,30361,577],"class_list":["post-117502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emprego","tag-estagio","tag-estudante","tag-trainee","tag-vagas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Confira empresas com inscri\u00e7\u00f5es abertas para est\u00e1gio e trainee - Ribeir\u00e3o Preto e Regi\u00e3o<\/title>\n<meta name=\"description\" content=\"As companhias Goodyear, PPG, UPL est\u00e3o com inscri\u00e7\u00f5es abertas para programas de est\u00e1gio. S\u00e3o eleg\u00edveis para as vagas estudantes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/06\/25\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confira empresas com inscri\u00e7\u00f5es abertas para est\u00e1gio e trainee - Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"og:description\" content=\"As companhias Goodyear, PPG, UPL est\u00e3o com inscri\u00e7\u00f5es abertas para programas de est\u00e1gio. S\u00e3o eleg\u00edveis para as vagas estudantes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/06\/25\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee\" \/>\n<meta property=\"og:site_name\" content=\"Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/redenoticiaz.barretos\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-25T16:14:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/06\/carteira_de_trabalho.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"613\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carina Reifonas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:site\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carina Reifonas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/06\\\/25\\\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/06\\\/25\\\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee\"},\"author\":{\"name\":\"Carina Reifonas\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/person\\\/1f84d6e94e6a62d2d81199d7503e9e90\"},\"headline\":\"Confira empresas com inscri\u00e7\u00f5es abertas para est\u00e1gio e trainee\",\"datePublished\":\"2024-06-25T16:14:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/06\\\/25\\\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee\"},\"wordCount\":1446,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/06\\\/25\\\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/06\\\/carteira_de_trabalho.jpg\",\"keywords\":[\"EST\u00c1GIO\",\"ESTUDANTE\",\"trainee\",\"VAGAS\"],\"articleSection\":[\"Emprego\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/06\\\/25\\\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/06\\\/25\\\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/06\\\/25\\\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee\",\"name\":\"Confira empresas com inscri\u00e7\u00f5es abertas para est\u00e1gio e trainee - Ribeir\u00e3o Preto e Regi\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/06\\\/25\\\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/06\\\/25\\\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/06\\\/carteira_de_trabalho.jpg\",\"datePublished\":\"2024-06-25T16:14:59+00:00\",\"description\":\"As companhias Goodyear, PPG, UPL est\u00e3o com inscri\u00e7\u00f5es abertas para programas de est\u00e1gio. S\u00e3o eleg\u00edveis para as vagas estudantes.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/06\\\/25\\\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/06\\\/25\\\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/06\\\/carteira_de_trabalho.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/06\\\/carteira_de_trabalho.jpg\",\"width\":1024,\"height\":613},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"description\":\"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Ribeir\u00e3o Preto e Regi\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/redenoticiaz.barretos\",\"https:\\\/\\\/x.com\\\/RN_barretos\",\"https:\\\/\\\/www.instagram.com\\\/redenoticiaz.barretos\\\/?igshid=YmMyMTA2M2Y\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rede-noticiaz-barretos-e-regio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/person\\\/1f84d6e94e6a62d2d81199d7503e9e90\",\"name\":\"Carina Reifonas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"caption\":\"Carina Reifonas\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/author\\\/carinareifonas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confira empresas com inscri\u00e7\u00f5es abertas para est\u00e1gio e trainee - Ribeir\u00e3o Preto e Regi\u00e3o","description":"As companhias Goodyear, PPG, UPL est\u00e3o com inscri\u00e7\u00f5es abertas para programas de est\u00e1gio. S\u00e3o eleg\u00edveis para as vagas estudantes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/06\/25\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee","og_locale":"pt_BR","og_type":"article","og_title":"Confira empresas com inscri\u00e7\u00f5es abertas para est\u00e1gio e trainee - Ribeir\u00e3o Preto e Regi\u00e3o","og_description":"As companhias Goodyear, PPG, UPL est\u00e3o com inscri\u00e7\u00f5es abertas para programas de est\u00e1gio. S\u00e3o eleg\u00edveis para as vagas estudantes.","og_url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/06\/25\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee","og_site_name":"Ribeir\u00e3o Preto e Regi\u00e3o","article_publisher":"https:\/\/m.facebook.com\/redenoticiaz.barretos","article_published_time":"2024-06-25T16:14:59+00:00","og_image":[{"width":1024,"height":613,"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/06\/carteira_de_trabalho.jpg","type":"image\/jpeg"}],"author":"Carina Reifonas","twitter_card":"summary_large_image","twitter_creator":"@RN_barretos","twitter_site":"@RN_barretos","twitter_misc":{"Escrito por":"Carina Reifonas","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/06\/25\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/06\/25\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee"},"author":{"name":"Carina Reifonas","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/person\/1f84d6e94e6a62d2d81199d7503e9e90"},"headline":"Confira empresas com inscri\u00e7\u00f5es abertas para est\u00e1gio e trainee","datePublished":"2024-06-25T16:14:59+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/06\/25\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee"},"wordCount":1446,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/06\/25\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/06\/carteira_de_trabalho.jpg","keywords":["EST\u00c1GIO","ESTUDANTE","trainee","VAGAS"],"articleSection":["Emprego"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/06\/25\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/06\/25\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/06\/25\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee","name":"Confira empresas com inscri\u00e7\u00f5es abertas para est\u00e1gio e trainee - Ribeir\u00e3o Preto e Regi\u00e3o","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/06\/25\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/06\/25\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/06\/carteira_de_trabalho.jpg","datePublished":"2024-06-25T16:14:59+00:00","description":"As companhias Goodyear, PPG, UPL est\u00e3o com inscri\u00e7\u00f5es abertas para programas de est\u00e1gio. S\u00e3o eleg\u00edveis para as vagas estudantes.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/06\/25\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/06\/25\/confira-empresas-com-inscricoes-abertas-para-estagio-e-trainee#primaryimage","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/06\/carteira_de_trabalho.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/06\/carteira_de_trabalho.jpg","width":1024,"height":613},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","name":"Ribeir\u00e3o Preto e Regi\u00e3o","description":"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization","name":"Ribeir\u00e3o Preto e Regi\u00e3o","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","width":400,"height":250,"caption":"Ribeir\u00e3o Preto e Regi\u00e3o"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/redenoticiaz.barretos","https:\/\/x.com\/RN_barretos","https:\/\/www.instagram.com\/redenoticiaz.barretos\/?igshid=YmMyMTA2M2Y","https:\/\/www.linkedin.com\/company\/rede-noticiaz-barretos-e-regio\/"]},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/person\/1f84d6e94e6a62d2d81199d7503e9e90","name":"Carina Reifonas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","caption":"Carina Reifonas"},"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/author\/carinareifonas"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/117502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/comments?post=117502"}],"version-history":[{"count":0,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/117502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media\/117503"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media?parent=117502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/categories?post=117502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/tags?post=117502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}