{"id":118170,"date":"2024-08-24T09:00:21","date_gmt":"2024-08-24T12:00:21","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/?p=118170"},"modified":"2024-08-24T09:00:21","modified_gmt":"2024-08-24T12:00:21","slug":"aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/08\/24\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos","title":{"rendered":"Aumento do pre\u00e7o do almo\u00e7o fora de casa supera o do sal\u00e1rio m\u00ednimo nos \u00faltimos cinco anos"},"content":{"rendered":"<p>A pesquisa + Valor, feita pela Ticket, marca da Edenred Brasil de Benef\u00edcios e Engajamento, em mais de 4,5 mil restaurantes em todo o territ\u00f3rio nacional, revelou que o aumento do pre\u00e7o m\u00e9dio da refei\u00e7\u00e3o completa nos \u00faltimos cinco anos foi superior ao do sal\u00e1rio m\u00ednimo.<\/p>\n<p>De acordo com o levantamento, o valor m\u00e9dio de uma refei\u00e7\u00e3o com prato principal, bebida, sobremesa e cafezinho em 2019 era de R$ 34,62, enquanto este ano est\u00e1 custando, em m\u00e9dia, R$ 51,61, o que representa um aumento de 49%. J\u00e1 o sal\u00e1rio m\u00ednimo, segundo dados do Instituto de Pesquisa Econ\u00f4mica Aplicada (Ipea), que era de R$ 998 cinco anos atr\u00e1s, hoje est\u00e1 em R$ 1.412, ou seja, um crescimento de 41%.<\/p>\n<p>Isso significa que quem recebe cinco sal\u00e1rios m\u00ednimos tem cerca de 15% de sua renda comprometida com as refei\u00e7\u00f5es de almo\u00e7o e quem recebe tr\u00eas sal\u00e1rios m\u00ednimos tem em m\u00e9dia 24% de comprometimento. J\u00e1 para quem tem uma remunera\u00e7\u00e3o de um sal\u00e1rio m\u00ednimo, 73% da renda fica comprometida.<\/p>\n<p>\u201cO pre\u00e7o da alimenta\u00e7\u00e3o fora de casa n\u00e3o acompanha o sal\u00e1rio, evidenciando o esfor\u00e7o que os trabalhadores precisam fazer para garantir as refei\u00e7\u00f5es nos dias trabalhados. Esse cen\u00e1rio tamb\u00e9m refor\u00e7a a import\u00e2ncia do benef\u00edcio de refei\u00e7\u00e3o oferecido pelas empresas como garantia de acesso a uma refei\u00e7\u00e3o completa e de qualidade, que \u00e9 fundamental para a produtividade e o bem-estar das pessoas\u201d, comenta Nat\u00e1lia Ghiotto, Diretora de Produtos da Ticket.<\/p>\n<p>Ainda de acordo com a pesquisa, uma pessoa que n\u00e3o recebe vale-refei\u00e7\u00e3o precisaria desembolsar R$ 1.032,23 por m\u00eas para garantir o almo\u00e7o de segunda a sexta \u2013 considerando que o m\u00eas possui, em m\u00e9dia, quatro semanas. \u201cIsso corresponde a 73% do sal\u00e1rio m\u00ednimo. Se somarmos o pre\u00e7o m\u00e9dio da cesta b\u00e1sica, que segundo o DIEESE \u00e9 de R$ 709,28, essa conta sobe para R$ 1.741,51, ou seja, 123% do valor do sal\u00e1rio\u201d, revela Nat\u00e1lia. \u201cCom a pesquisa + Valor, nosso objetivo \u00e9 apresentar \u00e0s empresas um panorama do setor de alimenta\u00e7\u00e3o, auxiliando em suas estrat\u00e9gias quanto ao valor do benef\u00edcio concedido \u00e0s pessoas colaboradoras\u201d, completa Nat\u00e1lia.<\/p>\n<p>Na an\u00e1lise regional, o Sudeste \u00e9 o local em que cinco refei\u00e7\u00f5es no hor\u00e1rio do almo\u00e7o por semana mais pesam no bolso do trabalhador, onerando 77% do sal\u00e1rio m\u00ednimo, enquanto o Norte e o Centro-oeste dividiram a \u00faltima posi\u00e7\u00e3o, com 64% do valor total do sal\u00e1rio.<\/p>\n<h3><strong>Compara\u00e7\u00e3o por regi\u00e3o<\/strong><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-118171 size-full\" src=\"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2024\/08\/Captura-de-tela-2024-08-20-135403.png\" alt=\"\" width=\"747\" height=\"242\" srcset=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/08\/Captura-de-tela-2024-08-20-135403.png?v=1724172877 747w, https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/08\/Captura-de-tela-2024-08-20-135403-300x97.png?v=1724172877 300w\" sizes=\"auto, (max-width: 747px) 100vw, 747px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>LEIA MAIS<\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2024\/08\/20\/goias-o-celeiro-do-brasil-para-o-mundo\">Goi\u00e1s, o celeiro do Brasil para o mundo<\/a><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2024\/08\/20\/korber-supply-chain-software-abre-processo-seletivo-para-novas-vagas-de-emprego\">K\u00f6rber Supply Chain Software abre processo seletivo para novas vagas de emprego<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pesquisa + Valor, feita pela Ticket, marca da Edenred Brasil de Benef\u00edcios e Engajamento, em mais de 4,5 mil restaurantes em todo o territ\u00f3rio nacional, revelou que o aumento do pre\u00e7o m\u00e9dio da refei\u00e7\u00e3o completa nos \u00faltimos cinco anos foi superior ao do sal\u00e1rio m\u00ednimo. De acordo com o levantamento, o valor m\u00e9dio de &hellip;<\/p>\n","protected":false},"author":30,"featured_media":118172,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101],"tags":[30511,19205],"class_list":["post-118170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-almoco-fora-de-casa","tag-salario-minimo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aumento do pre\u00e7o do almo\u00e7o fora de casa supera o do sal\u00e1rio m\u00ednimo nos \u00faltimos cinco anos - Ribeir\u00e3o Preto e Regi\u00e3o<\/title>\n<meta name=\"description\" content=\"Pesquisa em mais de 4,5 mil restaurantes em todo o territ\u00f3rio nacional, revelou que o aumento do pre\u00e7o m\u00e9dio da refei\u00e7\u00e3o completa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/08\/24\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aumento do pre\u00e7o do almo\u00e7o fora de casa supera o do sal\u00e1rio m\u00ednimo nos \u00faltimos cinco anos - Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Pesquisa em mais de 4,5 mil restaurantes em todo o territ\u00f3rio nacional, revelou que o aumento do pre\u00e7o m\u00e9dio da refei\u00e7\u00e3o completa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/08\/24\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos\" \/>\n<meta property=\"og:site_name\" content=\"Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/redenoticiaz.barretos\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-24T12:00:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/08\/restaurante.jpg?v=1599516946\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carina Reifonas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:site\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carina Reifonas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/08\\\/24\\\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/08\\\/24\\\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos\"},\"author\":{\"name\":\"Carina Reifonas\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/person\\\/1f84d6e94e6a62d2d81199d7503e9e90\"},\"headline\":\"Aumento do pre\u00e7o do almo\u00e7o fora de casa supera o do sal\u00e1rio m\u00ednimo nos \u00faltimos cinco anos\",\"datePublished\":\"2024-08-24T12:00:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/08\\\/24\\\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos\"},\"wordCount\":478,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/08\\\/24\\\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/08\\\/restaurante.jpg?v=1599516946\",\"keywords\":[\"almo\u00e7o fora de casa\",\"SAL\u00c1RIO M\u00cdNIMO\"],\"articleSection\":[\"Economia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/08\\\/24\\\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/08\\\/24\\\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/08\\\/24\\\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos\",\"name\":\"Aumento do pre\u00e7o do almo\u00e7o fora de casa supera o do sal\u00e1rio m\u00ednimo nos \u00faltimos cinco anos - Ribeir\u00e3o Preto e Regi\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/08\\\/24\\\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/08\\\/24\\\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/08\\\/restaurante.jpg?v=1599516946\",\"datePublished\":\"2024-08-24T12:00:21+00:00\",\"description\":\"Pesquisa em mais de 4,5 mil restaurantes em todo o territ\u00f3rio nacional, revelou que o aumento do pre\u00e7o m\u00e9dio da refei\u00e7\u00e3o completa.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/08\\\/24\\\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2024\\\/08\\\/24\\\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/08\\\/restaurante.jpg?v=1599516946\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/08\\\/restaurante.jpg?v=1599516946\",\"width\":1024,\"height\":683},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"description\":\"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Ribeir\u00e3o Preto e Regi\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/redenoticiaz.barretos\",\"https:\\\/\\\/x.com\\\/RN_barretos\",\"https:\\\/\\\/www.instagram.com\\\/redenoticiaz.barretos\\\/?igshid=YmMyMTA2M2Y\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rede-noticiaz-barretos-e-regio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/person\\\/1f84d6e94e6a62d2d81199d7503e9e90\",\"name\":\"Carina Reifonas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"caption\":\"Carina Reifonas\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/author\\\/carinareifonas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aumento do pre\u00e7o do almo\u00e7o fora de casa supera o do sal\u00e1rio m\u00ednimo nos \u00faltimos cinco anos - Ribeir\u00e3o Preto e Regi\u00e3o","description":"Pesquisa em mais de 4,5 mil restaurantes em todo o territ\u00f3rio nacional, revelou que o aumento do pre\u00e7o m\u00e9dio da refei\u00e7\u00e3o completa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/08\/24\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos","og_locale":"pt_BR","og_type":"article","og_title":"Aumento do pre\u00e7o do almo\u00e7o fora de casa supera o do sal\u00e1rio m\u00ednimo nos \u00faltimos cinco anos - Ribeir\u00e3o Preto e Regi\u00e3o","og_description":"Pesquisa em mais de 4,5 mil restaurantes em todo o territ\u00f3rio nacional, revelou que o aumento do pre\u00e7o m\u00e9dio da refei\u00e7\u00e3o completa.","og_url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/08\/24\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos","og_site_name":"Ribeir\u00e3o Preto e Regi\u00e3o","article_publisher":"https:\/\/m.facebook.com\/redenoticiaz.barretos","article_published_time":"2024-08-24T12:00:21+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/08\/restaurante.jpg?v=1599516946","type":"image\/jpeg"}],"author":"Carina Reifonas","twitter_card":"summary_large_image","twitter_creator":"@RN_barretos","twitter_site":"@RN_barretos","twitter_misc":{"Escrito por":"Carina Reifonas","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/08\/24\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/08\/24\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos"},"author":{"name":"Carina Reifonas","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/person\/1f84d6e94e6a62d2d81199d7503e9e90"},"headline":"Aumento do pre\u00e7o do almo\u00e7o fora de casa supera o do sal\u00e1rio m\u00ednimo nos \u00faltimos cinco anos","datePublished":"2024-08-24T12:00:21+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/08\/24\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos"},"wordCount":478,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/08\/24\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/08\/restaurante.jpg?v=1599516946","keywords":["almo\u00e7o fora de casa","SAL\u00c1RIO M\u00cdNIMO"],"articleSection":["Economia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/08\/24\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/08\/24\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/08\/24\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos","name":"Aumento do pre\u00e7o do almo\u00e7o fora de casa supera o do sal\u00e1rio m\u00ednimo nos \u00faltimos cinco anos - Ribeir\u00e3o Preto e Regi\u00e3o","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/08\/24\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/08\/24\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/08\/restaurante.jpg?v=1599516946","datePublished":"2024-08-24T12:00:21+00:00","description":"Pesquisa em mais de 4,5 mil restaurantes em todo o territ\u00f3rio nacional, revelou que o aumento do pre\u00e7o m\u00e9dio da refei\u00e7\u00e3o completa.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/08\/24\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2024\/08\/24\/aumento-do-preco-do-almoco-fora-de-casa-supera-o-do-salario-minimo-nos-ultimos-cinco-anos#primaryimage","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/08\/restaurante.jpg?v=1599516946","contentUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2024\/08\/restaurante.jpg?v=1599516946","width":1024,"height":683},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","name":"Ribeir\u00e3o Preto e Regi\u00e3o","description":"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization","name":"Ribeir\u00e3o Preto e Regi\u00e3o","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","width":400,"height":250,"caption":"Ribeir\u00e3o Preto e Regi\u00e3o"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/redenoticiaz.barretos","https:\/\/x.com\/RN_barretos","https:\/\/www.instagram.com\/redenoticiaz.barretos\/?igshid=YmMyMTA2M2Y","https:\/\/www.linkedin.com\/company\/rede-noticiaz-barretos-e-regio\/"]},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/person\/1f84d6e94e6a62d2d81199d7503e9e90","name":"Carina Reifonas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","caption":"Carina Reifonas"},"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/author\/carinareifonas"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/118170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/comments?post=118170"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/118170\/revisions"}],"predecessor-version":[{"id":118173,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/118170\/revisions\/118173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media\/118172"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media?parent=118170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/categories?post=118170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/tags?post=118170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}