{"id":120728,"date":"2025-11-13T13:10:29","date_gmt":"2025-11-13T16:10:29","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/sp\/2025\/11\/13\/netflix-confirma-2a-temporada-de-os-donos-do-jogo"},"modified":"2025-11-13T13:14:34","modified_gmt":"2025-11-13T16:14:34","slug":"netflix-confirma-2a-temporada-de-os-donos-do-jogo","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2025\/11\/13\/netflix-confirma-2a-temporada-de-os-donos-do-jogo","title":{"rendered":"Netflix confirma 2\u00aa temporada de Os Donos do Jogo"},"content":{"rendered":"<p>A Netflix anunciou oficialmente a segunda temporada de Os Donos do Jogo, s\u00e9rie brasileira que se tornou um fen\u00f4meno dentro e fora do pa\u00eds ao mergulhar no universo da m\u00e1fia do jogo do bicho. O an\u00fancio foi feito pelo ator Andr\u00e9 Lamoglia, int\u00e9rprete do Profeta, em um v\u00eddeo divulgado nos canais oficiais da plataforma.<\/p>\n<p>Desde sua estreia, em 29 de outubro, a produ\u00e7\u00e3o ocupa o 1\u00ba lugar no Top 10 da Netflix Brasil e alcan\u00e7ou o topo do ranking global das s\u00e9ries de l\u00edngua n\u00e3o inglesa mais assistidas, somando 5,9 milh\u00f5es de visualiza\u00e7\u00f5es.<\/p>\n<p><iframe loading=\"lazy\" title=\"\u00c9 real: OS DONOS DO JOGO EST\u00c1 RENOVADA! \ud83e\udd85\" width=\"422\" height=\"750\" src=\"https:\/\/www.youtube.com\/embed\/Sv__t8V8XVs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><em>\u201cA gente se dedicou de verdade nesse projeto, ent\u00e3o \u00e9 incr\u00edvel ver esse retorno t\u00e3o positivo. Agora \u00e9 segurar a ansiedade para come\u00e7ar logo a gravar os pr\u00f3ximos epis\u00f3dios!\u201d<\/em>, comemorou Lamoglia.<\/p>\n<p>Produzida pela Parano\u00efd e criada por Heitor Dhalia, Bernardo Barcellos e Bruno Passeri, Os Donos do Jogo consolidou-se como o primeiro grande drama brasileiro da Netflix a explorar o submundo do crime organizado com um toque de realismo e sotaque carioca.<\/p>\n<p>A nova temporada ainda n\u00e3o tem data de estreia, mas os f\u00e3s j\u00e1 podem esperar mais segredos, disputas de poder e reviravoltas no imp\u00e9rio do jogo do bicho.<\/p>\n<p>LEIA MAIS<\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2025\/11\/13\/coca-cola-abre-vagas-em-jundiai-inscricoes-vao-so-ate-23-de-novembro\">Coca-Cola abre vagas em Jundia\u00ed \u2014 inscri\u00e7\u00f5es v\u00e3o s\u00f3 at\u00e9 23 de novembro!<\/a><\/p>\n<p><a href=\"https:\/\/redenoticiaz.com.br\/blog\/2025\/11\/13\/festival-de-musica-de-itupeva-promete-agitar-o-domingo-16-com-shows-gratuitos\">Festival de M\u00fasica de Itupeva promete agitar o domingo (16) com shows gratuitos<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Netflix anunciou oficialmente a segunda temporada de Os Donos do Jogo, s\u00e9rie brasileira que se tornou um fen\u00f4meno dentro e fora do pa\u00eds ao mergulhar no universo da m\u00e1fia do jogo do bicho. O an\u00fancio foi feito pelo ator Andr\u00e9 Lamoglia, int\u00e9rprete do Profeta, em um v\u00eddeo divulgado nos canais oficiais da plataforma. Desde &hellip;<\/p>\n","protected":false},"author":30,"featured_media":120729,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23210],"tags":[5887,31381,20517,12580],"class_list":["post-120728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cameraz","tag-netflix","tag-os-donos-do-jogo","tag-segunda-temporada","tag-serie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Netflix confirma 2\u00aa temporada de Os Donos do Jogo - Ribeir\u00e3o Preto e Regi\u00e3o<\/title>\n<meta name=\"description\" content=\"Os Donos do Jogo, s\u00e9rie brasileira que se tornou um fen\u00f4meno dentro e fora do pa\u00eds ao mergulhar no universo da m\u00e1fia do jogo do bicho.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2025\/11\/13\/netflix-confirma-2a-temporada-de-os-donos-do-jogo\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Netflix confirma 2\u00aa temporada de Os Donos do Jogo - Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Os Donos do Jogo, s\u00e9rie brasileira que se tornou um fen\u00f4meno dentro e fora do pa\u00eds ao mergulhar no universo da m\u00e1fia do jogo do bicho.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2025\/11\/13\/netflix-confirma-2a-temporada-de-os-donos-do-jogo\" \/>\n<meta property=\"og:site_name\" content=\"Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/redenoticiaz.barretos\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-13T16:10:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T16:14:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2025\/11\/a6e60e99-7020-5b52-24d5-10af9fe09595.jpeg?v=1763045727\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carina Reifonas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:site\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carina Reifonas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2025\\\/11\\\/13\\\/netflix-confirma-2a-temporada-de-os-donos-do-jogo#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2025\\\/11\\\/13\\\/netflix-confirma-2a-temporada-de-os-donos-do-jogo\"},\"author\":{\"name\":\"Carina Reifonas\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/person\\\/1f84d6e94e6a62d2d81199d7503e9e90\"},\"headline\":\"Netflix confirma 2\u00aa temporada de Os Donos do Jogo\",\"datePublished\":\"2025-11-13T16:10:29+00:00\",\"dateModified\":\"2025-11-13T16:14:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2025\\\/11\\\/13\\\/netflix-confirma-2a-temporada-de-os-donos-do-jogo\"},\"wordCount\":263,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2025\\\/11\\\/13\\\/netflix-confirma-2a-temporada-de-os-donos-do-jogo#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/11\\\/a6e60e99-7020-5b52-24d5-10af9fe09595.jpeg?v=1763045727\",\"keywords\":[\"NETFLIX\",\"Os Donos do jogo\",\"segunda temporada\",\"S\u00c9RIE\"],\"articleSection\":[\"C\u00e2mera Z\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2025\\\/11\\\/13\\\/netflix-confirma-2a-temporada-de-os-donos-do-jogo#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2025\\\/11\\\/13\\\/netflix-confirma-2a-temporada-de-os-donos-do-jogo\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2025\\\/11\\\/13\\\/netflix-confirma-2a-temporada-de-os-donos-do-jogo\",\"name\":\"Netflix confirma 2\u00aa temporada de Os Donos do Jogo - Ribeir\u00e3o Preto e Regi\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2025\\\/11\\\/13\\\/netflix-confirma-2a-temporada-de-os-donos-do-jogo#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2025\\\/11\\\/13\\\/netflix-confirma-2a-temporada-de-os-donos-do-jogo#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/11\\\/a6e60e99-7020-5b52-24d5-10af9fe09595.jpeg?v=1763045727\",\"datePublished\":\"2025-11-13T16:10:29+00:00\",\"dateModified\":\"2025-11-13T16:14:34+00:00\",\"description\":\"Os Donos do Jogo, s\u00e9rie brasileira que se tornou um fen\u00f4meno dentro e fora do pa\u00eds ao mergulhar no universo da m\u00e1fia do jogo do bicho.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2025\\\/11\\\/13\\\/netflix-confirma-2a-temporada-de-os-donos-do-jogo\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2025\\\/11\\\/13\\\/netflix-confirma-2a-temporada-de-os-donos-do-jogo#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/11\\\/a6e60e99-7020-5b52-24d5-10af9fe09595.jpeg?v=1763045727\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/11\\\/a6e60e99-7020-5b52-24d5-10af9fe09595.jpeg?v=1763045727\",\"width\":1600,\"height\":1066,\"caption\":\"Netflix confirma 2\u00aa temporada de Os Donos do Jogo \u2014 (Cr\u00e9ditos: Albert Andrade\\\/Netflix)\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"description\":\"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Ribeir\u00e3o Preto e Regi\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/redenoticiaz.barretos\",\"https:\\\/\\\/x.com\\\/RN_barretos\",\"https:\\\/\\\/www.instagram.com\\\/redenoticiaz.barretos\\\/?igshid=YmMyMTA2M2Y\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rede-noticiaz-barretos-e-regio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/person\\\/1f84d6e94e6a62d2d81199d7503e9e90\",\"name\":\"Carina Reifonas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g\",\"caption\":\"Carina Reifonas\"},\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/author\\\/carinareifonas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Netflix confirma 2\u00aa temporada de Os Donos do Jogo - Ribeir\u00e3o Preto e Regi\u00e3o","description":"Os Donos do Jogo, s\u00e9rie brasileira que se tornou um fen\u00f4meno dentro e fora do pa\u00eds ao mergulhar no universo da m\u00e1fia do jogo do bicho.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2025\/11\/13\/netflix-confirma-2a-temporada-de-os-donos-do-jogo","og_locale":"pt_BR","og_type":"article","og_title":"Netflix confirma 2\u00aa temporada de Os Donos do Jogo - Ribeir\u00e3o Preto e Regi\u00e3o","og_description":"Os Donos do Jogo, s\u00e9rie brasileira que se tornou um fen\u00f4meno dentro e fora do pa\u00eds ao mergulhar no universo da m\u00e1fia do jogo do bicho.","og_url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2025\/11\/13\/netflix-confirma-2a-temporada-de-os-donos-do-jogo","og_site_name":"Ribeir\u00e3o Preto e Regi\u00e3o","article_publisher":"https:\/\/m.facebook.com\/redenoticiaz.barretos","article_published_time":"2025-11-13T16:10:29+00:00","article_modified_time":"2025-11-13T16:14:34+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2025\/11\/a6e60e99-7020-5b52-24d5-10af9fe09595.jpeg?v=1763045727","type":"image\/jpeg"}],"author":"Carina Reifonas","twitter_card":"summary_large_image","twitter_creator":"@RN_barretos","twitter_site":"@RN_barretos","twitter_misc":{"Escrito por":"Carina Reifonas","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2025\/11\/13\/netflix-confirma-2a-temporada-de-os-donos-do-jogo#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2025\/11\/13\/netflix-confirma-2a-temporada-de-os-donos-do-jogo"},"author":{"name":"Carina Reifonas","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/person\/1f84d6e94e6a62d2d81199d7503e9e90"},"headline":"Netflix confirma 2\u00aa temporada de Os Donos do Jogo","datePublished":"2025-11-13T16:10:29+00:00","dateModified":"2025-11-13T16:14:34+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2025\/11\/13\/netflix-confirma-2a-temporada-de-os-donos-do-jogo"},"wordCount":263,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2025\/11\/13\/netflix-confirma-2a-temporada-de-os-donos-do-jogo#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2025\/11\/a6e60e99-7020-5b52-24d5-10af9fe09595.jpeg?v=1763045727","keywords":["NETFLIX","Os Donos do jogo","segunda temporada","S\u00c9RIE"],"articleSection":["C\u00e2mera Z"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2025\/11\/13\/netflix-confirma-2a-temporada-de-os-donos-do-jogo#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2025\/11\/13\/netflix-confirma-2a-temporada-de-os-donos-do-jogo","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2025\/11\/13\/netflix-confirma-2a-temporada-de-os-donos-do-jogo","name":"Netflix confirma 2\u00aa temporada de Os Donos do Jogo - Ribeir\u00e3o Preto e Regi\u00e3o","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2025\/11\/13\/netflix-confirma-2a-temporada-de-os-donos-do-jogo#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2025\/11\/13\/netflix-confirma-2a-temporada-de-os-donos-do-jogo#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2025\/11\/a6e60e99-7020-5b52-24d5-10af9fe09595.jpeg?v=1763045727","datePublished":"2025-11-13T16:10:29+00:00","dateModified":"2025-11-13T16:14:34+00:00","description":"Os Donos do Jogo, s\u00e9rie brasileira que se tornou um fen\u00f4meno dentro e fora do pa\u00eds ao mergulhar no universo da m\u00e1fia do jogo do bicho.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2025\/11\/13\/netflix-confirma-2a-temporada-de-os-donos-do-jogo"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2025\/11\/13\/netflix-confirma-2a-temporada-de-os-donos-do-jogo#primaryimage","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2025\/11\/a6e60e99-7020-5b52-24d5-10af9fe09595.jpeg?v=1763045727","contentUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2025\/11\/a6e60e99-7020-5b52-24d5-10af9fe09595.jpeg?v=1763045727","width":1600,"height":1066,"caption":"Netflix confirma 2\u00aa temporada de Os Donos do Jogo \u2014 (Cr\u00e9ditos: Albert Andrade\/Netflix)"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","name":"Ribeir\u00e3o Preto e Regi\u00e3o","description":"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization","name":"Ribeir\u00e3o Preto e Regi\u00e3o","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","width":400,"height":250,"caption":"Ribeir\u00e3o Preto e Regi\u00e3o"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/redenoticiaz.barretos","https:\/\/x.com\/RN_barretos","https:\/\/www.instagram.com\/redenoticiaz.barretos\/?igshid=YmMyMTA2M2Y","https:\/\/www.linkedin.com\/company\/rede-noticiaz-barretos-e-regio\/"]},{"@type":"Person","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/person\/1f84d6e94e6a62d2d81199d7503e9e90","name":"Carina Reifonas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04c59859b23696cf867715880f81d5c037e60109730bdb4e6670ec2a2245bc97?s=96&d=mm&r=g","caption":"Carina Reifonas"},"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/author\/carinareifonas"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/120728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/comments?post=120728"}],"version-history":[{"count":3,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/120728\/revisions"}],"predecessor-version":[{"id":120732,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/120728\/revisions\/120732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media\/120729"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media?parent=120728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/categories?post=120728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/tags?post=120728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}