{"id":90905,"date":"2022-09-04T12:30:58","date_gmt":"2022-09-04T15:30:58","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/?p=90905"},"modified":"2022-08-31T17:19:18","modified_gmt":"2022-08-31T20:19:18","slug":"olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/09\/04\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas","title":{"rendered":"Ol\u00edmpia fecha m\u00eas com saldo de mais de 100 vagas de emprego geradas"},"content":{"rendered":"<p class=\"v1MsoNormal\"><span style=\"font-family: arial, sans-serif\">O m\u00eas de julho fechou com saldo positivo na gera\u00e7\u00e3o de emprego na Est\u00e2ncia Tur\u00edstica de Ol\u00edmpia. O relat\u00f3rio mensal do Caged \u2013 Cadastro Geral de Empregados e Desempregados, divulgado na manh\u00e3 desta segunda-feira (29), pelo Minist\u00e9rio da Economia mostra que o balan\u00e7o do m\u00eas foi de 101 vagas formais.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span style=\"font-family: arial, sans-serif\">Ao todo, foram 721 admiss\u00f5es contra 620 desligamentos no \u00faltimo m\u00eas. Em 2022, o acumulado aponta 5.447 contrata\u00e7\u00f5es contra 4.985 demiss\u00f5es.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span style=\"font-family: arial, sans-serif\">Em julho, os setores mais positivos foram o da Agropecu\u00e1ria e de Servi\u00e7os, principalmente, devido ao in\u00edcio da safra da cana-de-a\u00e7\u00facar e tamb\u00e9m \u00e0 alta temporada no turismo, que elevaram a contrata\u00e7\u00e3o.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span style=\"font-family: arial, sans-serif\">Na regi\u00e3o, o desempenho de Ol\u00edmpia superou o de cidades como Votuporanga (-55 vagas), Mirassol (-8), Fernand\u00f3polis (-7), Jos\u00e9 Bonif\u00e1cio (+12), Jales (+32) e Novo Horizonte (+34).<\/span><\/p>\n<p><strong>VEJA TAMB\u00c9M:\u00a0<a href=\"https:\/\/redenoticiaz.com.br\/barretos-regiao\/sp\/2022\/08\/21\/empresa-farmaceutica-abre-vagas-de-estagio-em-6-estados-do-brasil\">Empresa farmac\u00eautica abre vagas de est\u00e1gio em 6 estados do Brasil<\/a><\/strong><\/p>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O m\u00eas de julho fechou com saldo positivo na gera\u00e7\u00e3o de emprego na Est\u00e2ncia Tur\u00edstica de Ol\u00edmpia. O relat\u00f3rio mensal do Caged \u2013 Cadastro Geral de Empregados e Desempregados, divulgado na manh\u00e3 desta segunda-feira (29), pelo Minist\u00e9rio da Economia mostra que o balan\u00e7o do m\u00eas foi de 101 vagas formais. Ao todo, foram 721 admiss\u00f5es &hellip;<\/p>\n","protected":false},"author":15,"featured_media":90906,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[172,814,20000,577],"class_list":["post-90905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades","tag-emprego","tag-olimpia","tag-positivo","tag-vagas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ol\u00edmpia fecha m\u00eas com saldo de mais de 100 vagas de emprego geradas - Ribeir\u00e3o Preto e Regi\u00e3o<\/title>\n<meta name=\"description\" content=\"O m\u00ea fechou com saldo positivo na gera\u00e7\u00e3o de emprego na Est\u00e2ncia Tur\u00edstica de Ol\u00edmpia. O relat\u00f3rio mensal do Caged.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/09\/04\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ol\u00edmpia fecha m\u00eas com saldo de mais de 100 vagas de emprego geradas - Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"og:description\" content=\"O m\u00ea fechou com saldo positivo na gera\u00e7\u00e3o de emprego na Est\u00e2ncia Tur\u00edstica de Ol\u00edmpia. O relat\u00f3rio mensal do Caged.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/09\/04\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas\" \/>\n<meta property=\"og:site_name\" content=\"Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/redenoticiaz.barretos\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-04T15:30:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2022\/08\/Aerea-Olimpia-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:site\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/09\\\/04\\\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/09\\\/04\\\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Ol\u00edmpia fecha m\u00eas com saldo de mais de 100 vagas de emprego geradas\",\"datePublished\":\"2022-09-04T15:30:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/09\\\/04\\\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas\"},\"wordCount\":170,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/09\\\/04\\\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/08\\\/Aerea-Olimpia-1-scaled.jpg\",\"keywords\":[\"EMPREGO\",\"OLIMP\u00cdA\",\"POSITIVO\",\"VAGAS\"],\"articleSection\":[\"Cidades\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/09\\\/04\\\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/09\\\/04\\\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/09\\\/04\\\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas\",\"name\":\"Ol\u00edmpia fecha m\u00eas com saldo de mais de 100 vagas de emprego geradas - Ribeir\u00e3o Preto e Regi\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/09\\\/04\\\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/09\\\/04\\\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/08\\\/Aerea-Olimpia-1-scaled.jpg\",\"datePublished\":\"2022-09-04T15:30:58+00:00\",\"description\":\"O m\u00ea fechou com saldo positivo na gera\u00e7\u00e3o de emprego na Est\u00e2ncia Tur\u00edstica de Ol\u00edmpia. O relat\u00f3rio mensal do Caged.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/09\\\/04\\\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/09\\\/04\\\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/08\\\/Aerea-Olimpia-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/08\\\/Aerea-Olimpia-1-scaled.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Cr\u00e9dito: Divulga\u00e7\u00e3o\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"description\":\"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Ribeir\u00e3o Preto e Regi\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/redenoticiaz.barretos\",\"https:\\\/\\\/x.com\\\/RN_barretos\",\"https:\\\/\\\/www.instagram.com\\\/redenoticiaz.barretos\\\/?igshid=YmMyMTA2M2Y\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rede-noticiaz-barretos-e-regio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ol\u00edmpia fecha m\u00eas com saldo de mais de 100 vagas de emprego geradas - Ribeir\u00e3o Preto e Regi\u00e3o","description":"O m\u00ea fechou com saldo positivo na gera\u00e7\u00e3o de emprego na Est\u00e2ncia Tur\u00edstica de Ol\u00edmpia. O relat\u00f3rio mensal do Caged.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/09\/04\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas","og_locale":"pt_BR","og_type":"article","og_title":"Ol\u00edmpia fecha m\u00eas com saldo de mais de 100 vagas de emprego geradas - Ribeir\u00e3o Preto e Regi\u00e3o","og_description":"O m\u00ea fechou com saldo positivo na gera\u00e7\u00e3o de emprego na Est\u00e2ncia Tur\u00edstica de Ol\u00edmpia. O relat\u00f3rio mensal do Caged.","og_url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/09\/04\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas","og_site_name":"Ribeir\u00e3o Preto e Regi\u00e3o","article_publisher":"https:\/\/m.facebook.com\/redenoticiaz.barretos","article_published_time":"2022-09-04T15:30:58+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2022\/08\/Aerea-Olimpia-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@RN_barretos","twitter_site":"@RN_barretos","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/09\/04\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/09\/04\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas"},"author":{"name":"","@id":""},"headline":"Ol\u00edmpia fecha m\u00eas com saldo de mais de 100 vagas de emprego geradas","datePublished":"2022-09-04T15:30:58+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/09\/04\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas"},"wordCount":170,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/09\/04\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2022\/08\/Aerea-Olimpia-1-scaled.jpg","keywords":["EMPREGO","OLIMP\u00cdA","POSITIVO","VAGAS"],"articleSection":["Cidades"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/09\/04\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/09\/04\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/09\/04\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas","name":"Ol\u00edmpia fecha m\u00eas com saldo de mais de 100 vagas de emprego geradas - Ribeir\u00e3o Preto e Regi\u00e3o","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/09\/04\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/09\/04\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2022\/08\/Aerea-Olimpia-1-scaled.jpg","datePublished":"2022-09-04T15:30:58+00:00","description":"O m\u00ea fechou com saldo positivo na gera\u00e7\u00e3o de emprego na Est\u00e2ncia Tur\u00edstica de Ol\u00edmpia. O relat\u00f3rio mensal do Caged.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/09\/04\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/09\/04\/olimpia-fecha-mes-com-saldo-de-mais-de-100-vagas-de-emprego-geradas#primaryimage","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2022\/08\/Aerea-Olimpia-1-scaled.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2022\/08\/Aerea-Olimpia-1-scaled.jpg","width":1920,"height":1080,"caption":"Cr\u00e9dito: Divulga\u00e7\u00e3o"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","name":"Ribeir\u00e3o Preto e Regi\u00e3o","description":"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization","name":"Ribeir\u00e3o Preto e Regi\u00e3o","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","width":400,"height":250,"caption":"Ribeir\u00e3o Preto e Regi\u00e3o"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/redenoticiaz.barretos","https:\/\/x.com\/RN_barretos","https:\/\/www.instagram.com\/redenoticiaz.barretos\/?igshid=YmMyMTA2M2Y","https:\/\/www.linkedin.com\/company\/rede-noticiaz-barretos-e-regio\/"]},{"@type":"Person","@id":"","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/author"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/90905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/comments?post=90905"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/90905\/revisions"}],"predecessor-version":[{"id":90907,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/90905\/revisions\/90907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media\/90906"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media?parent=90905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/categories?post=90905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/tags?post=90905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}