{"id":93673,"date":"2022-10-20T13:31:15","date_gmt":"2022-10-20T16:31:15","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/?p=93673"},"modified":"2022-10-20T13:31:15","modified_gmt":"2022-10-20T16:31:15","slug":"veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/10\/20\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act","title":{"rendered":"Veja as orienta\u00e7\u00f5es e locais de prova do processo seletivo de professores ACT"},"content":{"rendered":"<p class=\"v1MsoNormal\"><span style=\"font-family: arial, sans-serif\">Os candidatos inscritos no Processo Seletivo Simplificado 01\/2022 para a forma\u00e7\u00e3o de cadastro reserva de professores admitidos em car\u00e1ter tempor\u00e1rio (ACT), para o ano letivo de 2023 da rede municipal de ensino da Est\u00e2ncia Tur\u00edstica de Ol\u00edmpia, devem ficar atentos aos locais e orienta\u00e7\u00f5es da prova.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span style=\"font-family: arial, sans-serif\">A convoca\u00e7\u00e3o dos candidatos inscritos para a realiza\u00e7\u00e3o do exame foi publicada na edi\u00e7\u00e3o do Di\u00e1rio Oficial Eletr\u00f4nico desta quarta-feira (19). Segundo o documento, a prova ser\u00e1 aplicada neste domingo, dia 23 de outubro, nos per\u00edodos da manh\u00e3 e da tarde. Ao todo, mais de 800 candidatos participam do certame.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span style=\"font-family: arial, sans-serif\">Professores de Educa\u00e7\u00e3o B\u00e1sica I (PEB I) far\u00e3o as provas na EMEB Santo Seno e na EMEB Professor Maur\u00edcio C\u00e9sar Alves Pereira, com fechamento dos port\u00f5es \u00e0s 9 horas.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span style=\"font-family: arial, sans-serif\">J\u00e1 os candidatos para as diversas modalidades de Professor de Educa\u00e7\u00e3o B\u00e1sica II (PEB II) realizar\u00e3o o exame exclusivamente na EMEB Professor Maur\u00edcio C\u00e9sar Alves Pereira, com fechamento dos port\u00f5es \u00e0s 14 horas.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span style=\"font-family: arial, sans-serif\">Vale ressaltar que os proponentes que forem apresentar t\u00edtulos dever\u00e3o entreg\u00e1-los no mesmo dia e local da realiza\u00e7\u00e3o da prova objetiva, lembrando que s\u00f3 ter\u00e3o os t\u00edtulos avaliados os candidatos que foram considerados habilitados na prova.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span style=\"font-family: arial, sans-serif\">Ainda segundo a publica\u00e7\u00e3o, os candidatos dever\u00e3o comparecer ao local da prova com pelo menos 30 (trinta) minutos de anteced\u00eancia do fechamento dos port\u00f5es, n\u00e3o sendo permitidos atrasos. \u00c9 necess\u00e1rio observar tamb\u00e9m as demais informa\u00e7\u00f5es do edital e recomenda\u00e7\u00f5es para a realiza\u00e7\u00e3o das provas, como cuidados de higiene, levar garrafas de \u00e1gua, uso de m\u00e1scara para ingresso ao local, entre outras.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span style=\"font-family: arial, sans-serif\">Todo o\u00a0processo\u00a0seletivo \u00e9 de responsabilidade da empresa Apta Assessoria e Consultoria Ltda. Mais informa\u00e7\u00f5es pelo site\u00a0<a href=\"https:\/\/www.aptaconcursos.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.aptaconcursos.com.br\/<\/a>.<\/span><\/p>\n<p>VEJA TAMB\u00c9M:\u00a0<a href=\"https:\/\/redenoticiaz.com.br\/barretos-regiao\/sp\/2022\/10\/20\/emais-urbanismo-assume-compromisso-de-construcao-da-ponte-do-mais-parque\">Emais Urbanismo assume compromisso de constru\u00e7\u00e3o da ponte do Mais Parque<\/a><\/p>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Os candidatos inscritos no Processo Seletivo Simplificado 01\/2022 para a forma\u00e7\u00e3o de cadastro reserva de professores admitidos em car\u00e1ter tempor\u00e1rio (ACT), para o ano letivo de 2023 da rede municipal de ensino da Est\u00e2ncia Tur\u00edstica de Ol\u00edmpia, devem ficar atentos aos locais e orienta\u00e7\u00f5es da prova. A convoca\u00e7\u00e3o dos candidatos inscritos para a realiza\u00e7\u00e3o do &hellip;<\/p>\n","protected":false},"author":15,"featured_media":93674,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[820],"tags":[8298,814,21310,17520],"class_list":["post-93673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","tag-escola","tag-olimpia","tag-professores-temporarios","tag-prova"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veja as orienta\u00e7\u00f5es e locais de prova do processo seletivo de professores ACT - Ribeir\u00e3o Preto e Regi\u00e3o<\/title>\n<meta name=\"description\" content=\"Processo Seletivo Simplificado 01\/2022 para a forma\u00e7\u00e3o de cadastro reserva de professores admitidos em car\u00e1ter tempor\u00e1rio (ACT)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/10\/20\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veja as orienta\u00e7\u00f5es e locais de prova do processo seletivo de professores ACT - Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Processo Seletivo Simplificado 01\/2022 para a forma\u00e7\u00e3o de cadastro reserva de professores admitidos em car\u00e1ter tempor\u00e1rio (ACT)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/10\/20\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act\" \/>\n<meta property=\"og:site_name\" content=\"Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/redenoticiaz.barretos\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-20T16:31:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2022\/10\/Sem-nome-1000-\u00d7-900-px-Post-para-Facebook.png\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:site\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/10\\\/20\\\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/10\\\/20\\\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Veja as orienta\u00e7\u00f5es e locais de prova do processo seletivo de professores ACT\",\"datePublished\":\"2022-10-20T16:31:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/10\\\/20\\\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act\"},\"wordCount\":340,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/10\\\/20\\\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/10\\\/Sem-nome-1000-\u00d7-900-px-Post-para-Facebook.png\",\"keywords\":[\"ESCOLA\",\"OLIMP\u00cdA\",\"PROFESSORES TEMPOR\u00c1RIOS\",\"PROVA\"],\"articleSection\":[\"Educa\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/10\\\/20\\\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/10\\\/20\\\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/10\\\/20\\\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act\",\"name\":\"Veja as orienta\u00e7\u00f5es e locais de prova do processo seletivo de professores ACT - Ribeir\u00e3o Preto e Regi\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/10\\\/20\\\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/10\\\/20\\\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/10\\\/Sem-nome-1000-\u00d7-900-px-Post-para-Facebook.png\",\"datePublished\":\"2022-10-20T16:31:15+00:00\",\"description\":\"Processo Seletivo Simplificado 01\\\/2022 para a forma\u00e7\u00e3o de cadastro reserva de professores admitidos em car\u00e1ter tempor\u00e1rio (ACT)\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/10\\\/20\\\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2022\\\/10\\\/20\\\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/10\\\/Sem-nome-1000-\u00d7-900-px-Post-para-Facebook.png\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/10\\\/Sem-nome-1000-\u00d7-900-px-Post-para-Facebook.png\",\"width\":940,\"height\":788,\"caption\":\"Orienta\u00e7\u00f5es da prova para processo seletivo. Cr\u00e9dito: Reprodu\u00e7\u00e3o\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"description\":\"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Ribeir\u00e3o Preto e Regi\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/redenoticiaz.barretos\",\"https:\\\/\\\/x.com\\\/RN_barretos\",\"https:\\\/\\\/www.instagram.com\\\/redenoticiaz.barretos\\\/?igshid=YmMyMTA2M2Y\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rede-noticiaz-barretos-e-regio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veja as orienta\u00e7\u00f5es e locais de prova do processo seletivo de professores ACT - Ribeir\u00e3o Preto e Regi\u00e3o","description":"Processo Seletivo Simplificado 01\/2022 para a forma\u00e7\u00e3o de cadastro reserva de professores admitidos em car\u00e1ter tempor\u00e1rio (ACT)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/10\/20\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act","og_locale":"pt_BR","og_type":"article","og_title":"Veja as orienta\u00e7\u00f5es e locais de prova do processo seletivo de professores ACT - Ribeir\u00e3o Preto e Regi\u00e3o","og_description":"Processo Seletivo Simplificado 01\/2022 para a forma\u00e7\u00e3o de cadastro reserva de professores admitidos em car\u00e1ter tempor\u00e1rio (ACT)","og_url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/10\/20\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act","og_site_name":"Ribeir\u00e3o Preto e Regi\u00e3o","article_publisher":"https:\/\/m.facebook.com\/redenoticiaz.barretos","article_published_time":"2022-10-20T16:31:15+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2022\/10\/Sem-nome-1000-\u00d7-900-px-Post-para-Facebook.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@RN_barretos","twitter_site":"@RN_barretos","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/10\/20\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/10\/20\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act"},"author":{"name":"","@id":""},"headline":"Veja as orienta\u00e7\u00f5es e locais de prova do processo seletivo de professores ACT","datePublished":"2022-10-20T16:31:15+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/10\/20\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act"},"wordCount":340,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/10\/20\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2022\/10\/Sem-nome-1000-\u00d7-900-px-Post-para-Facebook.png","keywords":["ESCOLA","OLIMP\u00cdA","PROFESSORES TEMPOR\u00c1RIOS","PROVA"],"articleSection":["Educa\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/10\/20\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/10\/20\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/10\/20\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act","name":"Veja as orienta\u00e7\u00f5es e locais de prova do processo seletivo de professores ACT - Ribeir\u00e3o Preto e Regi\u00e3o","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/10\/20\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/10\/20\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2022\/10\/Sem-nome-1000-\u00d7-900-px-Post-para-Facebook.png","datePublished":"2022-10-20T16:31:15+00:00","description":"Processo Seletivo Simplificado 01\/2022 para a forma\u00e7\u00e3o de cadastro reserva de professores admitidos em car\u00e1ter tempor\u00e1rio (ACT)","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/10\/20\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2022\/10\/20\/veja-as-orientacoes-e-locais-de-prova-do-processo-seletivo-de-professores-act#primaryimage","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2022\/10\/Sem-nome-1000-\u00d7-900-px-Post-para-Facebook.png","contentUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2022\/10\/Sem-nome-1000-\u00d7-900-px-Post-para-Facebook.png","width":940,"height":788,"caption":"Orienta\u00e7\u00f5es da prova para processo seletivo. Cr\u00e9dito: Reprodu\u00e7\u00e3o"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","name":"Ribeir\u00e3o Preto e Regi\u00e3o","description":"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization","name":"Ribeir\u00e3o Preto e Regi\u00e3o","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","width":400,"height":250,"caption":"Ribeir\u00e3o Preto e Regi\u00e3o"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/redenoticiaz.barretos","https:\/\/x.com\/RN_barretos","https:\/\/www.instagram.com\/redenoticiaz.barretos\/?igshid=YmMyMTA2M2Y","https:\/\/www.linkedin.com\/company\/rede-noticiaz-barretos-e-regio\/"]},{"@type":"Person","@id":"","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/author"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/93673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/comments?post=93673"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/93673\/revisions"}],"predecessor-version":[{"id":93675,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/93673\/revisions\/93675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media\/93674"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media?parent=93673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/categories?post=93673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/tags?post=93673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}