{"id":98837,"date":"2023-01-19T08:54:14","date_gmt":"2023-01-19T11:54:14","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/?p=98837"},"modified":"2023-01-19T08:54:14","modified_gmt":"2023-01-19T11:54:14","slug":"posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/01\/19\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego","title":{"rendered":"Posto de Atendimento ao Trabalhador oferece vagas de emprego"},"content":{"rendered":"<p>O Posto de Atendimento ao trabalhador disponibiliza nove vagas de emprego em diversas \u00e1reas. Os interessados dever\u00e3o procurar o PAT no hor\u00e1rio das 8h30 \u00e0s 16h30 para cadastrar ou atualizar o cadastro com documentos pessoais.<\/p>\n<p>O PAT est\u00e1 localizado na rua 8 N\u00ba 221 esquina da Avenida 5, pr\u00e9dio do Ganha Tempo Municipal de Gua\u00edra.<\/p>\n<h3>Confira as vagas:<\/h3>\n<p><strong><u>AUXILIAR DE CAMPO\u2013 02 VAGAS<\/u><\/strong><\/p>\n<p>Desej\u00e1vel ensino m\u00e9dio completo<\/p>\n<p>N\u00e3o \u00e9 necess\u00e1rio possuir experi\u00eancia<\/p>\n<p>Manuten\u00e7\u00e3o da unidade de Pesquisa; Opera\u00e7\u00f5es de Plantio mecanizada e manual, Capina quimica, Pulveriza\u00e7\u00e3o edosagem defensivos, Colheita e Debulha manual ; Contagem de stand e Roguing de Plantas no Campo; Poliniza\u00e7\u00e3o e Despendoamento; Limpeza, Classifica\u00e7\u00e3o e Tratamento de sementes e Disponibilidade de viagens<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>COZINHEIRA (O)\u2013 01 VAGA<\/u><\/strong><\/p>\n<p>Que possua experi\u00eancia em preparo de grandes quantidades<\/p>\n<p>Disponibilidade para trabalhar em domingos e feriados<\/p>\n<p>Habilidades necess\u00e1rias: trabalho em equipe, Agilidade, gest\u00e3o de tempo,organiza\u00e7\u00e3o, e planejamento.<\/p>\n<p>Acima de 30 anos<\/p>\n<p>Desej\u00e1vel ensino fundamental completo<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>AUXILIAR DE PESQUISA\u2013 01 VAGA<\/u><\/strong><\/p>\n<p>Necess\u00e1rio possuir habilita\u00e7\u00e3o<\/p>\n<p>Desej\u00e1vel\u00a0 ensino m\u00e9dio-<\/p>\n<p>Possuir experi\u00eancia na \u00e1rea<\/p>\n<p>Fun\u00e7\u00f5es: Servi\u00e7os de limpeza e manuten\u00e7\u00e3o da unidade; Plantio,capina, pulveriza\u00e7\u00e3o, colheita e debulha manual ; Contagem de stand e Roguing; Poliniza\u00e7\u00e3o e Despendoamento; Limpeza, Classifica\u00e7\u00e3o e Tratamento de sementes; Identifica\u00e7\u00e3o de parcelas de ensaio e nursery; Coleta de dados (manuseio coletor)<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>OPERADOR DE M\u00c1QUINAS AGR\u00cdCOLAS\u2013 01 VAGA<\/u><\/strong><\/p>\n<p>Necess\u00e1rio possuir habilita\u00e7\u00e3o,<\/p>\n<p>Possuir experi\u00eancia na \u00e1rea<\/p>\n<p>Desej\u00e1vel ensino m\u00e9dio<\/p>\n<p>Fun\u00e7\u00f5es:Manuten\u00e7\u00e3o de M\u00e1quinas e Equipamentos Agricolas (Trator, Plantadeira, Colhedeira, Pulverizador e Irriga\u00e7\u00e3o);Opera\u00e7\u00e3o com Plantadeira, Pulverizador, Subsolador e Irriga\u00e7\u00e3o; Plantio de ensaios e Nursery mecanizado; Plantio, Pulveriza\u00e7\u00e3o e Colheita mecanizada<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>ANALISTA DE DADOS (TI)\u2013 01 VAGA<\/u><\/strong><\/p>\n<p>Ambos os g\u00eaneros- com experi\u00eancia na \u00e1rea<\/p>\n<p>Ensino m\u00e9dio ou cursando t\u00e9cnico ou superior em TI<\/p>\n<p>Fun\u00e7\u00f5es: Digita\u00e7\u00e3o de dados, Analise de dados, Montagem de Planilhas , Cadernos de Campo, Programa\u00e7\u00e3o de Coletores de Dados, Armazenamento de informa\u00e7\u00e3o.<\/p>\n<p><strong><u>ASSISTENTE DE PESQUISA- 01 VAGA<\/u><\/strong><\/p>\n<p>Necess\u00e1rio possuir habilita\u00e7\u00e3o<\/p>\n<p>Possuir experi\u00eancia na \u00e1rea<\/p>\n<p>Desej\u00e1vel ensino m\u00e9dio<\/p>\n<p>Fun\u00e7\u00f5es: Coordena\u00e7\u00e3o de Equipes; Inform\u00e1tica b\u00e1sica ; Identifica\u00e7\u00e3o e Manuseio de germoplasma; Escolha de areas para ensaios; Montagem de ensaios, Campos de Linhagens e Cruzamentos; Recomenda\u00e7\u00f5es t\u00e9cnicas (dosagens inseticidas, herbicidas,etc); Regulagens de equipamentos (adubadeira, pulverizador, plantadeira de ensaios, colheitadeira de ensaios)<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>PRESENTANTE DE NEG\u00d3CIOS\u2013 01 VAGA<\/u><\/strong><\/p>\n<p>Com CNH \u201cAB\u201d e Moto pr\u00f3pria<\/p>\n<p>Ensino m\u00e9dio completo; conhecimentos b\u00e1sicos em inform\u00e1tica<\/p>\n<p>Ramo de bebidas em geral<\/p>\n<p>Atuar somente em Gua\u00edra<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>CASEIRO (RETIREIRO)\u2013 01 VAGA<\/u><\/strong><\/p>\n<p>Casado , pode ter filhos em idade escolar, (h\u00e1 transporte escolar na porta)<\/p>\n<p>Que o casal goste e tenha disponibilidade de morar na fazenda<\/p>\n<p>Com experi\u00eancia e refer\u00eancias\u00a0 anteriores.<\/p>\n<p>Necess\u00e1rio habilidade em ordenha (1 vez por dia)<\/p>\n<p>Fazenda a 18 km de Gua\u00edra<\/p>\n<p>Atribui\u00e7\u00f5es: Limpeza da sede, jardim, manuten\u00e7\u00e3o em geral do local, que goste e cuide de animais dom\u00e9sticos(gatos, cachorros, etc)<\/p>\n<p>&nbsp;<\/p>\n<p><b>VEJA TAMB\u00c9M:\u00a0<a href=\"https:\/\/redenoticiaz.com.br\/barretos-regiao\/sp\/2023\/01\/19\/bbb-23-tem-show-de-anitta-e-festival-de-beijos\">BBB 23 tem show de Anitta e festival de beijos<\/a><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Posto de Atendimento ao trabalhador disponibiliza nove vagas de emprego em diversas \u00e1reas. Os interessados dever\u00e3o procurar o PAT no hor\u00e1rio das 8h30 \u00e0s 16h30 para cadastrar ou atualizar o cadastro com documentos pessoais. O PAT est\u00e1 localizado na rua 8 N\u00ba 221 esquina da Avenida 5, pr\u00e9dio do Ganha Tempo Municipal de Gua\u00edra. &hellip;<\/p>\n","protected":false},"author":15,"featured_media":98841,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2075],"tags":[23979,23980,23981,3174,23982,23978],"class_list":["post-98837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trabalho","tag-auxiliar-de-campo","tag-auxiliar-de-pesquisa","tag-cozinheira","tag-guaira","tag-operador-de-maquinas-agriculas","tag-vagas-trabalho"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Posto de Atendimento ao Trabalhador oferece vagas de emprego - Ribeir\u00e3o Preto e Regi\u00e3o<\/title>\n<meta name=\"description\" content=\"O Posto de Atendimento ao trabalhador disponibiliza nove vagas de emprego em diversas \u00e1reas. Os interessados dever\u00e3o procurar o PAT\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/01\/19\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posto de Atendimento ao Trabalhador oferece vagas de emprego - Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"og:description\" content=\"O Posto de Atendimento ao trabalhador disponibiliza nove vagas de emprego em diversas \u00e1reas. Os interessados dever\u00e3o procurar o PAT\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/01\/19\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego\" \/>\n<meta property=\"og:site_name\" content=\"Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/redenoticiaz.barretos\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-19T11:54:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/01\/Posto-de-Atendimento-ao-Trabalhador-oferece-vagas-de-emprego.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:site\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/01\\\/19\\\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/01\\\/19\\\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Posto de Atendimento ao Trabalhador oferece vagas de emprego\",\"datePublished\":\"2023-01-19T11:54:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/01\\\/19\\\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego\"},\"wordCount\":544,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/01\\\/19\\\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/01\\\/Posto-de-Atendimento-ao-Trabalhador-oferece-vagas-de-emprego.png\",\"keywords\":[\"auxiliar de campo\",\"auxiliar de pesquisa\",\"cozinheira\",\"GUA\u00cdRA\",\"operador de m\u00e1quinas agr\u00edculas\",\"VAGAS TRABALHO\"],\"articleSection\":[\"Trabalho\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/01\\\/19\\\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/01\\\/19\\\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/01\\\/19\\\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego\",\"name\":\"Posto de Atendimento ao Trabalhador oferece vagas de emprego - Ribeir\u00e3o Preto e Regi\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/01\\\/19\\\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/01\\\/19\\\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/01\\\/Posto-de-Atendimento-ao-Trabalhador-oferece-vagas-de-emprego.png\",\"datePublished\":\"2023-01-19T11:54:14+00:00\",\"description\":\"O Posto de Atendimento ao trabalhador disponibiliza nove vagas de emprego em diversas \u00e1reas. Os interessados dever\u00e3o procurar o PAT\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/01\\\/19\\\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/01\\\/19\\\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/01\\\/Posto-de-Atendimento-ao-Trabalhador-oferece-vagas-de-emprego.png\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/01\\\/Posto-de-Atendimento-ao-Trabalhador-oferece-vagas-de-emprego.png\",\"width\":1200,\"height\":628,\"caption\":\"Cr\u00e9dito: Divulga\u00e7\u00e3o\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"description\":\"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Ribeir\u00e3o Preto e Regi\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/redenoticiaz.barretos\",\"https:\\\/\\\/x.com\\\/RN_barretos\",\"https:\\\/\\\/www.instagram.com\\\/redenoticiaz.barretos\\\/?igshid=YmMyMTA2M2Y\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rede-noticiaz-barretos-e-regio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Posto de Atendimento ao Trabalhador oferece vagas de emprego - Ribeir\u00e3o Preto e Regi\u00e3o","description":"O Posto de Atendimento ao trabalhador disponibiliza nove vagas de emprego em diversas \u00e1reas. Os interessados dever\u00e3o procurar o PAT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/01\/19\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego","og_locale":"pt_BR","og_type":"article","og_title":"Posto de Atendimento ao Trabalhador oferece vagas de emprego - Ribeir\u00e3o Preto e Regi\u00e3o","og_description":"O Posto de Atendimento ao trabalhador disponibiliza nove vagas de emprego em diversas \u00e1reas. Os interessados dever\u00e3o procurar o PAT","og_url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/01\/19\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego","og_site_name":"Ribeir\u00e3o Preto e Regi\u00e3o","article_publisher":"https:\/\/m.facebook.com\/redenoticiaz.barretos","article_published_time":"2023-01-19T11:54:14+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/01\/Posto-de-Atendimento-ao-Trabalhador-oferece-vagas-de-emprego.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@RN_barretos","twitter_site":"@RN_barretos","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/01\/19\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/01\/19\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego"},"author":{"name":"","@id":""},"headline":"Posto de Atendimento ao Trabalhador oferece vagas de emprego","datePublished":"2023-01-19T11:54:14+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/01\/19\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego"},"wordCount":544,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/01\/19\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/01\/Posto-de-Atendimento-ao-Trabalhador-oferece-vagas-de-emprego.png","keywords":["auxiliar de campo","auxiliar de pesquisa","cozinheira","GUA\u00cdRA","operador de m\u00e1quinas agr\u00edculas","VAGAS TRABALHO"],"articleSection":["Trabalho"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/01\/19\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/01\/19\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/01\/19\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego","name":"Posto de Atendimento ao Trabalhador oferece vagas de emprego - Ribeir\u00e3o Preto e Regi\u00e3o","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/01\/19\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/01\/19\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/01\/Posto-de-Atendimento-ao-Trabalhador-oferece-vagas-de-emprego.png","datePublished":"2023-01-19T11:54:14+00:00","description":"O Posto de Atendimento ao trabalhador disponibiliza nove vagas de emprego em diversas \u00e1reas. Os interessados dever\u00e3o procurar o PAT","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/01\/19\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/01\/19\/posto-de-atendimento-ao-trabalhador-oferece-vagas-de-emprego#primaryimage","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/01\/Posto-de-Atendimento-ao-Trabalhador-oferece-vagas-de-emprego.png","contentUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/01\/Posto-de-Atendimento-ao-Trabalhador-oferece-vagas-de-emprego.png","width":1200,"height":628,"caption":"Cr\u00e9dito: Divulga\u00e7\u00e3o"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","name":"Ribeir\u00e3o Preto e Regi\u00e3o","description":"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization","name":"Ribeir\u00e3o Preto e Regi\u00e3o","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","width":400,"height":250,"caption":"Ribeir\u00e3o Preto e Regi\u00e3o"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/redenoticiaz.barretos","https:\/\/x.com\/RN_barretos","https:\/\/www.instagram.com\/redenoticiaz.barretos\/?igshid=YmMyMTA2M2Y","https:\/\/www.linkedin.com\/company\/rede-noticiaz-barretos-e-regio\/"]},{"@type":"Person","@id":"","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/author"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/98837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/comments?post=98837"}],"version-history":[{"count":1,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/98837\/revisions"}],"predecessor-version":[{"id":98842,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/98837\/revisions\/98842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media\/98841"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media?parent=98837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/categories?post=98837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/tags?post=98837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}