{"id":99728,"date":"2023-02-02T15:54:46","date_gmt":"2023-02-02T18:54:46","guid":{"rendered":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/?p=99728"},"modified":"2023-02-02T15:57:27","modified_gmt":"2023-02-02T18:57:27","slug":"motorista-morre-apos-acidente-na-regiao-central-da-cidade","status":"publish","type":"post","link":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/02\/02\/motorista-morre-apos-acidente-na-regiao-central-da-cidade","title":{"rendered":"Motorista morre ap\u00f3s acidente na regi\u00e3o central da cidade"},"content":{"rendered":"<p>Um acidente ocorrido na tarde de quarta-feira (01), na rua 16, entre avenidas 7 e 9, em Barretos, terminou com a morte do condutor do ve\u00edculo, com placas de S\u00e3o Roque.<\/p>\n<p>Segundo a Pol\u00edcia Militar, possivelmente, a v\u00edtima de 59 anos, sofreu um mal s\u00fabito, perdendo o controle do ve\u00edculo.<\/p>\n<p>O motorista da caminhonete tamb\u00e9m atingiu um ve\u00edculo que estava estacionando, jogando-o sobre a cal\u00e7ada, na sequ\u00eancia colidiu com uma \u00e1rvore.<\/p>\n<p>Socorristas do Samu e do Corpo de Bombeiros tentaram por um grande per\u00edodo reanimar a v\u00edtima, que n\u00e3o suportou os traumas e acabou falecendo no local.<\/p>\n<p>VEJA TAMB\u00c9M:\u00a0<a href=\"https:\/\/redenoticiaz.com.br\/barretos-regiao\/sp\/2023\/02\/02\/transporte-coletivo-emissao-do-cartao-gratuidade-para-idosos-continua-no-terminal-de-integracao\">Transporte Coletivo: Emiss\u00e3o do cart\u00e3o gratuidade para idosos continua no Terminal de Integra\u00e7\u00e3o<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um acidente ocorrido na tarde de quarta-feira (01), na rua 16, entre avenidas 7 e 9, em Barretos, terminou com a morte do condutor do ve\u00edculo, com placas de S\u00e3o Roque. Segundo a Pol\u00edcia Militar, possivelmente, a v\u00edtima de 59 anos, sofreu um mal s\u00fabito, perdendo o controle do ve\u00edculo. O motorista da caminhonete tamb\u00e9m &hellip;<\/p>\n","protected":false},"author":15,"featured_media":99739,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[145,64,24504,18203,2741],"class_list":["post-99728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-acidente","tag-barretos","tag-central-da-cidade","tag-morre","tag-motorista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Motorista morre ap\u00f3s acidente na regi\u00e3o central da cidade - Ribeir\u00e3o Preto e Regi\u00e3o<\/title>\n<meta name=\"description\" content=\"Um acidente ocorrido na tarde de quarta-feira (01), na rua 16, entre avenidas 7 e 9,\u00a0terminou com a morte do condutor de uma caminhonete.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/02\/02\/motorista-morre-apos-acidente-na-regiao-central-da-cidade\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Motorista morre ap\u00f3s acidente na regi\u00e3o central da cidade - Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Um acidente ocorrido na tarde de quarta-feira (01), na rua 16, entre avenidas 7 e 9,\u00a0terminou com a morte do condutor de uma caminhonete.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/02\/02\/motorista-morre-apos-acidente-na-regiao-central-da-cidade\" \/>\n<meta property=\"og:site_name\" content=\"Ribeir\u00e3o Preto e Regi\u00e3o\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/redenoticiaz.barretos\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-02T18:54:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-02T18:57:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/02\/Acidente-tira.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"734\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:site\" content=\"@RN_barretos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/02\\\/02\\\/motorista-morre-apos-acidente-na-regiao-central-da-cidade#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/02\\\/02\\\/motorista-morre-apos-acidente-na-regiao-central-da-cidade\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Motorista morre ap\u00f3s acidente na regi\u00e3o central da cidade\",\"datePublished\":\"2023-02-02T18:54:46+00:00\",\"dateModified\":\"2023-02-02T18:57:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/02\\\/02\\\/motorista-morre-apos-acidente-na-regiao-central-da-cidade\"},\"wordCount\":135,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/02\\\/02\\\/motorista-morre-apos-acidente-na-regiao-central-da-cidade#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/02\\\/Acidente-tira.jpg\",\"keywords\":[\"acidente\",\"BARRETOS\",\"central da cidade\",\"MORRE\",\"MOTORISTA\"],\"articleSection\":[\"Pol\u00edcia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/02\\\/02\\\/motorista-morre-apos-acidente-na-regiao-central-da-cidade#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/02\\\/02\\\/motorista-morre-apos-acidente-na-regiao-central-da-cidade\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/02\\\/02\\\/motorista-morre-apos-acidente-na-regiao-central-da-cidade\",\"name\":\"Motorista morre ap\u00f3s acidente na regi\u00e3o central da cidade - Ribeir\u00e3o Preto e Regi\u00e3o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/02\\\/02\\\/motorista-morre-apos-acidente-na-regiao-central-da-cidade#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/02\\\/02\\\/motorista-morre-apos-acidente-na-regiao-central-da-cidade#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/02\\\/Acidente-tira.jpg\",\"datePublished\":\"2023-02-02T18:54:46+00:00\",\"dateModified\":\"2023-02-02T18:57:27+00:00\",\"description\":\"Um acidente ocorrido na tarde de quarta-feira (01), na rua 16, entre avenidas 7 e 9,\u00a0terminou com a morte do condutor de uma caminhonete.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/02\\\/02\\\/motorista-morre-apos-acidente-na-regiao-central-da-cidade\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/2023\\\/02\\\/02\\\/motorista-morre-apos-acidente-na-regiao-central-da-cidade#primaryimage\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/02\\\/Acidente-tira.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/02\\\/Acidente-tira.jpg\",\"width\":734,\"height\":330,\"caption\":\"Cr\u00e9dito: Reprodu\u00e7\u00e3o\\\/Foto: JB\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#website\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"description\":\"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#organization\",\"name\":\"Ribeir\u00e3o Preto e Regi\u00e3o\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/redenoticiaz.com.br\\\/barretos-regiao\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/02\\\/logo.jpg\",\"width\":400,\"height\":250,\"caption\":\"Ribeir\u00e3o Preto e Regi\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/redenoticiaz.barretos\",\"https:\\\/\\\/x.com\\\/RN_barretos\",\"https:\\\/\\\/www.instagram.com\\\/redenoticiaz.barretos\\\/?igshid=YmMyMTA2M2Y\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rede-noticiaz-barretos-e-regio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/redenoticiaz.com.br\\\/ribeiraopreto-regiao\\\/sp\\\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Motorista morre ap\u00f3s acidente na regi\u00e3o central da cidade - Ribeir\u00e3o Preto e Regi\u00e3o","description":"Um acidente ocorrido na tarde de quarta-feira (01), na rua 16, entre avenidas 7 e 9,\u00a0terminou com a morte do condutor de uma caminhonete.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/02\/02\/motorista-morre-apos-acidente-na-regiao-central-da-cidade","og_locale":"pt_BR","og_type":"article","og_title":"Motorista morre ap\u00f3s acidente na regi\u00e3o central da cidade - Ribeir\u00e3o Preto e Regi\u00e3o","og_description":"Um acidente ocorrido na tarde de quarta-feira (01), na rua 16, entre avenidas 7 e 9,\u00a0terminou com a morte do condutor de uma caminhonete.","og_url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/02\/02\/motorista-morre-apos-acidente-na-regiao-central-da-cidade","og_site_name":"Ribeir\u00e3o Preto e Regi\u00e3o","article_publisher":"https:\/\/m.facebook.com\/redenoticiaz.barretos","article_published_time":"2023-02-02T18:54:46+00:00","article_modified_time":"2023-02-02T18:57:27+00:00","og_image":[{"width":734,"height":330,"url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/02\/Acidente-tira.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@RN_barretos","twitter_site":"@RN_barretos","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/02\/02\/motorista-morre-apos-acidente-na-regiao-central-da-cidade#article","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/02\/02\/motorista-morre-apos-acidente-na-regiao-central-da-cidade"},"author":{"name":"","@id":""},"headline":"Motorista morre ap\u00f3s acidente na regi\u00e3o central da cidade","datePublished":"2023-02-02T18:54:46+00:00","dateModified":"2023-02-02T18:57:27+00:00","mainEntityOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/02\/02\/motorista-morre-apos-acidente-na-regiao-central-da-cidade"},"wordCount":135,"commentCount":0,"publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/02\/02\/motorista-morre-apos-acidente-na-regiao-central-da-cidade#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/02\/Acidente-tira.jpg","keywords":["acidente","BARRETOS","central da cidade","MORRE","MOTORISTA"],"articleSection":["Pol\u00edcia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/02\/02\/motorista-morre-apos-acidente-na-regiao-central-da-cidade#respond"]}]},{"@type":"WebPage","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/02\/02\/motorista-morre-apos-acidente-na-regiao-central-da-cidade","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/02\/02\/motorista-morre-apos-acidente-na-regiao-central-da-cidade","name":"Motorista morre ap\u00f3s acidente na regi\u00e3o central da cidade - Ribeir\u00e3o Preto e Regi\u00e3o","isPartOf":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/02\/02\/motorista-morre-apos-acidente-na-regiao-central-da-cidade#primaryimage"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/02\/02\/motorista-morre-apos-acidente-na-regiao-central-da-cidade#primaryimage"},"thumbnailUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/02\/Acidente-tira.jpg","datePublished":"2023-02-02T18:54:46+00:00","dateModified":"2023-02-02T18:57:27+00:00","description":"Um acidente ocorrido na tarde de quarta-feira (01), na rua 16, entre avenidas 7 e 9,\u00a0terminou com a morte do condutor de uma caminhonete.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/02\/02\/motorista-morre-apos-acidente-na-regiao-central-da-cidade"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/2023\/02\/02\/motorista-morre-apos-acidente-na-regiao-central-da-cidade#primaryimage","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/02\/Acidente-tira.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-content\/uploads\/sites\/4\/2023\/02\/Acidente-tira.jpg","width":734,"height":330,"caption":"Cr\u00e9dito: Reprodu\u00e7\u00e3o\/Foto: JB"},{"@type":"WebSite","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#website","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","name":"Ribeir\u00e3o Preto e Regi\u00e3o","description":"Rede NoticiaZ - Ribeir\u00e3o Preto e regi\u00e3o","publisher":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#organization","name":"Ribeir\u00e3o Preto e Regi\u00e3o","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/","url":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","contentUrl":"https:\/\/redenoticiaz.com.br\/barretos-regiao\/wp-content\/uploads\/sites\/4\/2022\/02\/logo.jpg","width":400,"height":250,"caption":"Ribeir\u00e3o Preto e Regi\u00e3o"},"image":{"@id":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/redenoticiaz.barretos","https:\/\/x.com\/RN_barretos","https:\/\/www.instagram.com\/redenoticiaz.barretos\/?igshid=YmMyMTA2M2Y","https:\/\/www.linkedin.com\/company\/rede-noticiaz-barretos-e-regio\/"]},{"@type":"Person","@id":"","url":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/sp\/author"}]}},"_links":{"self":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/99728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/comments?post=99728"}],"version-history":[{"count":2,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/99728\/revisions"}],"predecessor-version":[{"id":99741,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/posts\/99728\/revisions\/99741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media\/99739"}],"wp:attachment":[{"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/media?parent=99728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/categories?post=99728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redenoticiaz.com.br\/ribeiraopreto-regiao\/wp-json\/wp\/v2\/tags?post=99728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}